{"id":77075,"date":"2021-10-20T23:33:39","date_gmt":"2021-10-21T02:33:39","guid":{"rendered":"http:\/\/www.padreydecano.com\/cms\/?p=77075"},"modified":"2021-10-22T02:52:52","modified_gmt":"2021-10-22T05:52:52","slug":"victoria-y-recuperacion-de-nivel","status":"publish","type":"post","link":"https:\/\/www.padreydecano.com\/cms\/noticias\/victoria-y-recuperacion-de-nivel\/","title":{"rendered":"Victoria y recuperaci\u00f3n de nivel"},"content":{"rendered":"<p><a href=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-20-at-22.18.28.jpeg\" rel=\"shadowbox[sbpost-77075];player=img;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-77076\" src=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-20-at-22.18.28-1024x682.jpeg\" alt=\"\" width=\"620\" height=\"413\" srcset=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-20-at-22.18.28-1024x682.jpeg 1024w, https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-20-at-22.18.28-600x400.jpeg 600w, https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-20-at-22.18.28-768x512.jpeg 768w, https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-20-at-22.18.28.jpeg 2048w\" sizes=\"(max-width: 620px) 100vw, 620px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><strong>Pe\u00f1arol derrot\u00f3 a Montevideo City Torque 3 tantos contra 1. Los goles carboneros fueron convertidos por Facundo Torres en dos oportunidades y por Agust\u00edn \u00c1lvarez Mart\u00ednez. El equipo de Larriera gan\u00f3 y recuper\u00f3 su nivel colectivo.<\/strong><\/p>\n<p style=\"text-align: justify;\">Mauricio Larriera volvi\u00f3 a colocar a Jes\u00fas Trindade en la mitad de la cancha en lugar de Dami\u00e1n Musto, y Edgard Elizalde reemplaz\u00f3 al lesionado Carlos Rodr\u00edguez. As\u00ed, el once form\u00f3 con Kevin Dawson; Giovanni Gonz\u00e1lez, Gary Kagelmacher, Edgard Elizalde y Juan Ramos; Jes\u00fas Trindade, Walter Gargano; Agust\u00edn Canobbio, Pablo Ceppelini, Facundo Torres; Agust\u00edn \u00c1lvarez Mart\u00ednez.<\/p>\n<p style=\"text-align: justify;\">Pe\u00f1arol cedi\u00f3 la iniciativa los primeros 15 minutos del partido, pero luego de eso se adue\u00f1\u00f3 del encuentro. Con un Mota Gargano en muy buen nivel, el equipo creci\u00f3 en juego y volvi\u00f3 a mostrar lo que se hab\u00eda perdido en los \u00faltimos partidos.<\/p>\n<p style=\"text-align: justify;\">El primer gol lleg\u00f3 tras una gran jugada combinada entre Agust\u00edn \u00c1lvarez Mart\u00ednez (habilita de taco) y Facundo Torres (termina eludiendo al golero rival y mandando la pelota a la red).<\/p>\n<p style=\"text-align: justify;\">En el segundo tiempo y tras un buen centro de Jes\u00fas Trindade, Facundo Torres anticipi\u00f3 de buena manera a su marcado y puso el 2 &#8211; 0.<\/p>\n<p style=\"text-align: justify;\">El tercer gol lleg\u00f3 tras una gran recuperaci\u00f3n de Walter Gargano en 3\/4 de cancha, quien traslad\u00f3, esper\u00f3 y habilit\u00f3 al &#8216;Canario&#8217; para que el m\u00e1ximo goleador en la historia del Campe\u00f3n del Siglo anotara.<\/p>\n<p style=\"text-align: justify;\">Sobre el final del partido lleg\u00f3 el descuento de Torque, pero que no lleg\u00f3 a inquietar al mirasol.<\/p>\n<p style=\"text-align: justify;\">Pe\u00f1arol jug\u00f3 bien, Facundo Torres volvi\u00f3 a su nivel, \u00c1lvarez Mart\u00ednez volvi\u00f3 a convertir, Gargano fue la figura.<\/p>\n<p style=\"text-align: justify;\">El s\u00e1bado jugaremos ante Villa Espa\u00f1ola, en el Parque Viera a las 19:00 horas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pe\u00f1arol derrot\u00f3 a Montevideo City Torque 3 tantos contra 1. Los goles carboneros fueron convertidos por Facundo Torres en dos oportunidades y por Agust\u00edn \u00c1lvarez Mart\u00ednez. El equipo de Larriera gan\u00f3 y recuper\u00f3 su nivel colectivo. Mauricio Larriera volvi\u00f3 a colocar a Jes\u00fas Trindade en la mitad de la cancha en lugar de Dami\u00e1n Musto, [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":77076,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,13],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Victoria y recuperaci\u00f3n de nivel - Padre y Decano - El Sitio del Pueblo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.padreydecano.com\/cms\/noticias\/victoria-y-recuperacion-de-nivel\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Victoria y recuperaci\u00f3n de nivel - Padre y Decano - El Sitio del Pueblo\" \/>\n<meta property=\"og:description\" content=\"Pe\u00f1arol derrot\u00f3 a Montevideo City Torque 3 tantos contra 1. Los goles carboneros fueron convertidos por Facundo Torres en dos oportunidades y por Agust\u00edn \u00c1lvarez Mart\u00ednez. El equipo de Larriera gan\u00f3 y recuper\u00f3 su nivel colectivo. Mauricio Larriera volvi\u00f3 a colocar a Jes\u00fas Trindade en la mitad de la cancha en lugar de Dami\u00e1n Musto, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.padreydecano.com\/cms\/noticias\/victoria-y-recuperacion-de-nivel\/\" \/>\n<meta property=\"og:site_name\" content=\"Padre y Decano - El Sitio del Pueblo\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-21T02:33:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-22T05:52:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-20-at-22.18.28.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1364\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Emirona07\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Emirona07\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/victoria-y-recuperacion-de-nivel\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/victoria-y-recuperacion-de-nivel\/\"},\"author\":{\"name\":\"Emirona07\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/51e0214db654d9624824b37c2838bb65\"},\"headline\":\"Victoria y recuperaci\u00f3n de nivel\",\"datePublished\":\"2021-10-21T02:33:39+00:00\",\"dateModified\":\"2021-10-22T05:52:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/victoria-y-recuperacion-de-nivel\/\"},\"wordCount\":301,\"commentCount\":35,\"publisher\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/victoria-y-recuperacion-de-nivel\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-20-at-22.18.28.jpeg\",\"articleSection\":[\"Noticias\",\"Partidos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.padreydecano.com\/cms\/noticias\/victoria-y-recuperacion-de-nivel\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/victoria-y-recuperacion-de-nivel\/\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/victoria-y-recuperacion-de-nivel\/\",\"name\":\"Victoria y recuperaci\u00f3n de nivel - Padre y Decano - El Sitio del Pueblo\",\"isPartOf\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/victoria-y-recuperacion-de-nivel\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/victoria-y-recuperacion-de-nivel\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-20-at-22.18.28.jpeg\",\"datePublished\":\"2021-10-21T02:33:39+00:00\",\"dateModified\":\"2021-10-22T05:52:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/victoria-y-recuperacion-de-nivel\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.padreydecano.com\/cms\/noticias\/victoria-y-recuperacion-de-nivel\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/victoria-y-recuperacion-de-nivel\/#primaryimage\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-20-at-22.18.28.jpeg\",\"contentUrl\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-20-at-22.18.28.jpeg\",\"width\":2048,\"height\":1364},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/victoria-y-recuperacion-de-nivel\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.padreydecano.com\/cms\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Victoria y recuperaci\u00f3n de nivel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#website\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/\",\"name\":\"Padre y Decano - El Sitio del Pueblo\",\"description\":\"Club Atl\u00e9tico Pe\u00f1arol\",\"publisher\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.padreydecano.com\/cms\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#organization\",\"name\":\"Padre y Decano\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2022\/01\/avatar-square.png\",\"contentUrl\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2022\/01\/avatar-square.png\",\"width\":1500,\"height\":1500,\"caption\":\"Padre y Decano\"},\"image\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/51e0214db654d9624824b37c2838bb65\",\"name\":\"Emirona07\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/93c9118dbd5373a8a065bb5cdddde6bf?s=96&d=https%3A%2F%2Fpadreydecano.com%2Fcms%2Fwp-content%2Fthemes%2Fpyd-theme%2Fimg%2Fdefault-avatar.png&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/93c9118dbd5373a8a065bb5cdddde6bf?s=96&d=https%3A%2F%2Fpadreydecano.com%2Fcms%2Fwp-content%2Fthemes%2Fpyd-theme%2Fimg%2Fdefault-avatar.png&r=g\",\"caption\":\"Emirona07\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Victoria y recuperaci\u00f3n de nivel - Padre y Decano - El Sitio del Pueblo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.padreydecano.com\/cms\/noticias\/victoria-y-recuperacion-de-nivel\/","og_locale":"es_ES","og_type":"article","og_title":"Victoria y recuperaci\u00f3n de nivel - Padre y Decano - El Sitio del Pueblo","og_description":"Pe\u00f1arol derrot\u00f3 a Montevideo City Torque 3 tantos contra 1. Los goles carboneros fueron convertidos por Facundo Torres en dos oportunidades y por Agust\u00edn \u00c1lvarez Mart\u00ednez. El equipo de Larriera gan\u00f3 y recuper\u00f3 su nivel colectivo. Mauricio Larriera volvi\u00f3 a colocar a Jes\u00fas Trindade en la mitad de la cancha en lugar de Dami\u00e1n Musto, [&hellip;]","og_url":"https:\/\/www.padreydecano.com\/cms\/noticias\/victoria-y-recuperacion-de-nivel\/","og_site_name":"Padre y Decano - El Sitio del Pueblo","article_published_time":"2021-10-21T02:33:39+00:00","article_modified_time":"2021-10-22T05:52:52+00:00","og_image":[{"width":2048,"height":1364,"url":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-20-at-22.18.28.jpeg","type":"image\/jpeg"}],"author":"Emirona07","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Emirona07","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/victoria-y-recuperacion-de-nivel\/#article","isPartOf":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/victoria-y-recuperacion-de-nivel\/"},"author":{"name":"Emirona07","@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/51e0214db654d9624824b37c2838bb65"},"headline":"Victoria y recuperaci\u00f3n de nivel","datePublished":"2021-10-21T02:33:39+00:00","dateModified":"2021-10-22T05:52:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/victoria-y-recuperacion-de-nivel\/"},"wordCount":301,"commentCount":35,"publisher":{"@id":"https:\/\/www.padreydecano.com\/cms\/#organization"},"image":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/victoria-y-recuperacion-de-nivel\/#primaryimage"},"thumbnailUrl":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-20-at-22.18.28.jpeg","articleSection":["Noticias","Partidos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.padreydecano.com\/cms\/noticias\/victoria-y-recuperacion-de-nivel\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/victoria-y-recuperacion-de-nivel\/","url":"https:\/\/www.padreydecano.com\/cms\/noticias\/victoria-y-recuperacion-de-nivel\/","name":"Victoria y recuperaci\u00f3n de nivel - Padre y Decano - El Sitio del Pueblo","isPartOf":{"@id":"https:\/\/www.padreydecano.com\/cms\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/victoria-y-recuperacion-de-nivel\/#primaryimage"},"image":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/victoria-y-recuperacion-de-nivel\/#primaryimage"},"thumbnailUrl":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-20-at-22.18.28.jpeg","datePublished":"2021-10-21T02:33:39+00:00","dateModified":"2021-10-22T05:52:52+00:00","breadcrumb":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/victoria-y-recuperacion-de-nivel\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.padreydecano.com\/cms\/noticias\/victoria-y-recuperacion-de-nivel\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/victoria-y-recuperacion-de-nivel\/#primaryimage","url":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-20-at-22.18.28.jpeg","contentUrl":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-20-at-22.18.28.jpeg","width":2048,"height":1364},{"@type":"BreadcrumbList","@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/victoria-y-recuperacion-de-nivel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.padreydecano.com\/cms\/"},{"@type":"ListItem","position":2,"name":"Victoria y recuperaci\u00f3n de nivel"}]},{"@type":"WebSite","@id":"https:\/\/www.padreydecano.com\/cms\/#website","url":"https:\/\/www.padreydecano.com\/cms\/","name":"Padre y Decano - El Sitio del Pueblo","description":"Club Atl\u00e9tico Pe\u00f1arol","publisher":{"@id":"https:\/\/www.padreydecano.com\/cms\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.padreydecano.com\/cms\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.padreydecano.com\/cms\/#organization","name":"Padre y Decano","url":"https:\/\/www.padreydecano.com\/cms\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/logo\/image\/","url":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2022\/01\/avatar-square.png","contentUrl":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2022\/01\/avatar-square.png","width":1500,"height":1500,"caption":"Padre y Decano"},"image":{"@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/51e0214db654d9624824b37c2838bb65","name":"Emirona07","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/93c9118dbd5373a8a065bb5cdddde6bf?s=96&d=https%3A%2F%2Fpadreydecano.com%2Fcms%2Fwp-content%2Fthemes%2Fpyd-theme%2Fimg%2Fdefault-avatar.png&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/93c9118dbd5373a8a065bb5cdddde6bf?s=96&d=https%3A%2F%2Fpadreydecano.com%2Fcms%2Fwp-content%2Fthemes%2Fpyd-theme%2Fimg%2Fdefault-avatar.png&r=g","caption":"Emirona07"}}]}},"_links":{"self":[{"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/posts\/77075"}],"collection":[{"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/comments?post=77075"}],"version-history":[{"count":0,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/posts\/77075\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/media\/77076"}],"wp:attachment":[{"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/media?parent=77075"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/categories?post=77075"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/tags?post=77075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}