{"id":77059,"date":"2021-10-17T19:47:58","date_gmt":"2021-10-17T22:47:58","guid":{"rendered":"http:\/\/www.padreydecano.com\/cms\/?p=77059"},"modified":"2021-10-19T18:57:35","modified_gmt":"2021-10-19T21:57:35","slug":"costosa-derrota","status":"publish","type":"post","link":"https:\/\/www.padreydecano.com\/cms\/noticias\/costosa-derrota\/","title":{"rendered":"Costosa derrota"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-17-at-16.35.45-1.jpeg\" rel=\"shadowbox[sbpost-77059];player=img;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-77061\" src=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-17-at-16.35.45-1-1024x683.jpeg\" alt=\"\" width=\"620\" height=\"414\" srcset=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-17-at-16.35.45-1-1024x683.jpeg 1024w, https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-17-at-16.35.45-1-600x400.jpeg 600w, https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-17-at-16.35.45-1-768x512.jpeg 768w, https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-17-at-16.35.45-1.jpeg 2048w\" sizes=\"(max-width: 620px) 100vw, 620px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><strong>Pe\u00f1arol cay\u00f3 derrotado ante Deportivo Maldonado en el Estadio Domingo Burgue\u00f1o Miguel y complic\u00f3 su posici\u00f3n en ambas tablas.<\/strong><\/p>\n<p style=\"text-align: justify;\">Con la vuelta de los futbolistas cedidos a la selecci\u00f3n uruguaya, Larriera decidi\u00f3 contar con los 3 como titulares. Adem\u00e1s de ratificar a Dawson en el puesto de arquero y de volver a ubicar a Musto junto a Gargano en la mitad de la cancha.<\/p>\n<p style=\"text-align: justify;\">El Decano form\u00f3 con: Kevin Dawson; Giovanni Gonz\u00e1lez, Gary Kagelmacher, Carlos Rodr\u00edguez (15&#8242; Edgar Elizalde), Juan Manuel Ramos (65&#8242; Valent\u00edn Rodr\u00edguez); Agust\u00edn Canobbio (65&#8242; Ignacio Laquintana), Walter Gargano (80&#8242; R\u00faben Bentancur), Dami\u00e1n Musto, Facundo Torres; Pablo Ceppelini (46&#8242; Nicol\u00e1s Gait\u00e1n) y Agust\u00edn \u00c1lvarez Mart\u00ednez.<\/p>\n<p style=\"text-align: justify;\">Banco: Neto Volpi, Agust\u00edn Da Silveira, Maximiliano Pereira, Jes\u00fas Trindade y M\u00e1ximo Alonso.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffcc00;\"><strong>Primer tiempo<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">El carbonero depend\u00eda de si mismo para seguir arriba de las 2 tablas. Por lo que se preve\u00eda que se fuera en busca de la victoria desde el primer momento.<\/p>\n<p style=\"text-align: justify;\">El local incomod\u00f3 desde el inicio del partido a una vulnerable defensa en la tarde de hoy. Ya a los 7 minutos de juego, un pase largo desde la propia cancha del verdirojo, culmina con Carlos Rodr\u00edguez no pudiendo interceptar el bal\u00f3n y al delantero rival definiendo ante Dawson, pasando por arriba del travesa\u00f1o. Posteriormente, el rival volvi\u00f3 a llegar al arco aurinegro, generando una buena atajada de Dawson y no pudiendo concretar en el rebote.<\/p>\n<p style=\"text-align: justify;\">Pocos minutos despu\u00e9s, el zaguero debi\u00f3 abandonar la cancha por lesi\u00f3n. En su lugar ingres\u00f3 Edgar Elizalde.<\/p>\n<p style=\"text-align: justify;\">El equipo de Larriera no supo dominar la mitad de la cancha, siendo la mayor complicaci\u00f3n en el partido. Gargano no logr\u00f3 las conexiones como suele suceder y adem\u00e1s el equipo jug\u00f3 muy impreciso con el bal\u00f3n.<\/p>\n<p style=\"text-align: justify;\">En una mala salida en defensa, Deportivo Maldonado se hizo due\u00f1o del bal\u00f3n con Ramos, que avanz\u00f3 unos metros y dispar\u00f3 de larga distancia, venciendo a Dawson y abriendo el marcador a los 26&#8242;.<\/p>\n<p style=\"text-align: justify;\">El juego se reanud\u00f3 con Pe\u00f1arol buscando el empate intensamente, intentando meter la pelota en el \u00e1rea o con intentos desde afuera, sin embargo de a poco se fue apagando y el primer tiempo termin\u00f3 sin cambios en el marcador.<\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"color: #ffcc00;\">Segundo tiempo<\/span><\/strong><\/p>\n<p style=\"text-align: justify;\">Para el complemento, el entrenador aurinegro mand\u00f3 a la cancha al argentino Nicol\u00e1s Gait\u00e1n, en lugar de Pablo Ceppelini.<\/p>\n<p style=\"text-align: justify;\">El segundo tiempo comenz\u00f3 de mejor manera que el primero. Pe\u00f1arol se acerc\u00f3 m\u00e1s al \u00e1rea y presionaba a los rivales en sus salidas. Pero los ataques fueron sin profundidad y adem\u00e1s el rival durmi\u00f3 el partido el mayor tiempo posible, en la reanudaci\u00f3n de cada pelota y en cada choque. Los jugadores aurinegros no supieron c\u00f3mo manejar la situaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Pasado los 70&#8242;, el carbonero volvi\u00f3 a tener chances de igualar el marcador, que no se lograron concretar. Primero un cabezazo de Gait\u00e1n y posteriormente, una buena jugada del Canario dentro del \u00e1rea que se fue desviada al c\u00f3rner.<\/p>\n<p style=\"text-align: justify;\">En los minutos finales, Pe\u00f1arol no supo que hacer con la pelota y el local sigui\u00f3 dejando que el reloj pase.<\/p>\n<p style=\"text-align: justify;\">Pe\u00f1arol perdi\u00f3 y qued\u00f3 tercero en la tabla anual por detr\u00e1s de Plaza Colonia y Nacional, y primero en el Clausura igualado con el tradicional adversario.<\/p>\n<p style=\"text-align: justify;\">El pr\u00f3ximo mi\u00e9rcoles, el Decano recibir\u00e1 a Montevideo City Torque en el Estadio Campe\u00f3n del Siglo.<\/p>\n<p style=\"text-align: justify;\"><div class=\"user-wrapper\"><a class=\"userlink\"href=\"https:\/\/twitter.com\/ftrucce18\" target=\"_blank\"><figure><img decoding=\"async\" src=\"http:\/\/www.padreydecano.com\/cms\/wp-users-files\/postfirmas\/ftrucce.jpg\" \/><\/figure><p class=\"user\"><strong>Franco Trucce<\/strong><br \/>@FTrucce18<\/p><\/a><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Pe\u00f1arol cay\u00f3 derrotado ante Deportivo Maldonado en el Estadio Domingo Burgue\u00f1o Miguel y complic\u00f3 su posici\u00f3n en ambas tablas. Con la vuelta de los futbolistas cedidos a la selecci\u00f3n uruguaya, Larriera decidi\u00f3 contar con los 3 como titulares. Adem\u00e1s de ratificar a Dawson en el puesto de arquero y de volver a ubicar a [&hellip;]<\/p>\n","protected":false},"author":27,"featured_media":77061,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Costosa derrota - Padre y Decano - El Sitio del Pueblo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.padreydecano.com\/cms\/noticias\/costosa-derrota\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Costosa derrota - Padre y Decano - El Sitio del Pueblo\" \/>\n<meta property=\"og:description\" content=\"&nbsp; Pe\u00f1arol cay\u00f3 derrotado ante Deportivo Maldonado en el Estadio Domingo Burgue\u00f1o Miguel y complic\u00f3 su posici\u00f3n en ambas tablas. Con la vuelta de los futbolistas cedidos a la selecci\u00f3n uruguaya, Larriera decidi\u00f3 contar con los 3 como titulares. Adem\u00e1s de ratificar a Dawson en el puesto de arquero y de volver a ubicar a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.padreydecano.com\/cms\/noticias\/costosa-derrota\/\" \/>\n<meta property=\"og:site_name\" content=\"Padre y Decano - El Sitio del Pueblo\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-17T22:47:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-19T21:57:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-17-at-16.35.45-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1366\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redactores Padre y Decano\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redactores Padre y Decano\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/costosa-derrota\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/costosa-derrota\/\"},\"author\":{\"name\":\"Redactores Padre y Decano\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/37aae8f93aa78e4c5385497f056e3246\"},\"headline\":\"Costosa derrota\",\"datePublished\":\"2021-10-17T22:47:58+00:00\",\"dateModified\":\"2021-10-19T21:57:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/costosa-derrota\/\"},\"wordCount\":582,\"commentCount\":83,\"publisher\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/costosa-derrota\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-17-at-16.35.45-1.jpeg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.padreydecano.com\/cms\/noticias\/costosa-derrota\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/costosa-derrota\/\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/costosa-derrota\/\",\"name\":\"Costosa derrota - Padre y Decano - El Sitio del Pueblo\",\"isPartOf\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/costosa-derrota\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/costosa-derrota\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-17-at-16.35.45-1.jpeg\",\"datePublished\":\"2021-10-17T22:47:58+00:00\",\"dateModified\":\"2021-10-19T21:57:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/costosa-derrota\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.padreydecano.com\/cms\/noticias\/costosa-derrota\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/costosa-derrota\/#primaryimage\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-17-at-16.35.45-1.jpeg\",\"contentUrl\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-17-at-16.35.45-1.jpeg\",\"width\":2048,\"height\":1366},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/costosa-derrota\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.padreydecano.com\/cms\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Costosa derrota\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#website\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/\",\"name\":\"Padre y Decano - El Sitio del Pueblo\",\"description\":\"Club Atl\u00e9tico Pe\u00f1arol\",\"publisher\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.padreydecano.com\/cms\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#organization\",\"name\":\"Padre y Decano\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2022\/01\/avatar-square.png\",\"contentUrl\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2022\/01\/avatar-square.png\",\"width\":1500,\"height\":1500,\"caption\":\"Padre y Decano\"},\"image\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/37aae8f93aa78e4c5385497f056e3246\",\"name\":\"Redactores Padre y Decano\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8810c4b9081192b118b104af54549af8?s=96&d=https%3A%2F%2Fpadreydecano.com%2Fcms%2Fwp-content%2Fthemes%2Fpyd-theme%2Fimg%2Fdefault-avatar.png&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8810c4b9081192b118b104af54549af8?s=96&d=https%3A%2F%2Fpadreydecano.com%2Fcms%2Fwp-content%2Fthemes%2Fpyd-theme%2Fimg%2Fdefault-avatar.png&r=g\",\"caption\":\"Redactores Padre y Decano\"},\"sameAs\":[\"http:\/\/www.padreydecano.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Costosa derrota - Padre y Decano - El Sitio del Pueblo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.padreydecano.com\/cms\/noticias\/costosa-derrota\/","og_locale":"es_ES","og_type":"article","og_title":"Costosa derrota - Padre y Decano - El Sitio del Pueblo","og_description":"&nbsp; Pe\u00f1arol cay\u00f3 derrotado ante Deportivo Maldonado en el Estadio Domingo Burgue\u00f1o Miguel y complic\u00f3 su posici\u00f3n en ambas tablas. Con la vuelta de los futbolistas cedidos a la selecci\u00f3n uruguaya, Larriera decidi\u00f3 contar con los 3 como titulares. Adem\u00e1s de ratificar a Dawson en el puesto de arquero y de volver a ubicar a [&hellip;]","og_url":"https:\/\/www.padreydecano.com\/cms\/noticias\/costosa-derrota\/","og_site_name":"Padre y Decano - El Sitio del Pueblo","article_published_time":"2021-10-17T22:47:58+00:00","article_modified_time":"2021-10-19T21:57:35+00:00","og_image":[{"width":2048,"height":1366,"url":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-17-at-16.35.45-1.jpeg","type":"image\/jpeg"}],"author":"Redactores Padre y Decano","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Redactores Padre y Decano","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/costosa-derrota\/#article","isPartOf":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/costosa-derrota\/"},"author":{"name":"Redactores Padre y Decano","@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/37aae8f93aa78e4c5385497f056e3246"},"headline":"Costosa derrota","datePublished":"2021-10-17T22:47:58+00:00","dateModified":"2021-10-19T21:57:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/costosa-derrota\/"},"wordCount":582,"commentCount":83,"publisher":{"@id":"https:\/\/www.padreydecano.com\/cms\/#organization"},"image":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/costosa-derrota\/#primaryimage"},"thumbnailUrl":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-17-at-16.35.45-1.jpeg","articleSection":["Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.padreydecano.com\/cms\/noticias\/costosa-derrota\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/costosa-derrota\/","url":"https:\/\/www.padreydecano.com\/cms\/noticias\/costosa-derrota\/","name":"Costosa derrota - Padre y Decano - El Sitio del Pueblo","isPartOf":{"@id":"https:\/\/www.padreydecano.com\/cms\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/costosa-derrota\/#primaryimage"},"image":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/costosa-derrota\/#primaryimage"},"thumbnailUrl":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-17-at-16.35.45-1.jpeg","datePublished":"2021-10-17T22:47:58+00:00","dateModified":"2021-10-19T21:57:35+00:00","breadcrumb":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/costosa-derrota\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.padreydecano.com\/cms\/noticias\/costosa-derrota\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/costosa-derrota\/#primaryimage","url":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-17-at-16.35.45-1.jpeg","contentUrl":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-17-at-16.35.45-1.jpeg","width":2048,"height":1366},{"@type":"BreadcrumbList","@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/costosa-derrota\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.padreydecano.com\/cms\/"},{"@type":"ListItem","position":2,"name":"Costosa derrota"}]},{"@type":"WebSite","@id":"https:\/\/www.padreydecano.com\/cms\/#website","url":"https:\/\/www.padreydecano.com\/cms\/","name":"Padre y Decano - El Sitio del Pueblo","description":"Club Atl\u00e9tico Pe\u00f1arol","publisher":{"@id":"https:\/\/www.padreydecano.com\/cms\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.padreydecano.com\/cms\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.padreydecano.com\/cms\/#organization","name":"Padre y Decano","url":"https:\/\/www.padreydecano.com\/cms\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/logo\/image\/","url":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2022\/01\/avatar-square.png","contentUrl":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2022\/01\/avatar-square.png","width":1500,"height":1500,"caption":"Padre y Decano"},"image":{"@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/37aae8f93aa78e4c5385497f056e3246","name":"Redactores Padre y Decano","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8810c4b9081192b118b104af54549af8?s=96&d=https%3A%2F%2Fpadreydecano.com%2Fcms%2Fwp-content%2Fthemes%2Fpyd-theme%2Fimg%2Fdefault-avatar.png&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8810c4b9081192b118b104af54549af8?s=96&d=https%3A%2F%2Fpadreydecano.com%2Fcms%2Fwp-content%2Fthemes%2Fpyd-theme%2Fimg%2Fdefault-avatar.png&r=g","caption":"Redactores Padre y Decano"},"sameAs":["http:\/\/www.padreydecano.com"]}]}},"_links":{"self":[{"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/posts\/77059"}],"collection":[{"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/comments?post=77059"}],"version-history":[{"count":0,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/posts\/77059\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/media\/77061"}],"wp:attachment":[{"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/media?parent=77059"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/categories?post=77059"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/tags?post=77059"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}