{"id":76924,"date":"2021-09-24T11:19:46","date_gmt":"2021-09-24T14:19:46","guid":{"rendered":"http:\/\/www.padreydecano.com\/cms\/?p=76924"},"modified":"2021-09-26T11:52:47","modified_gmt":"2021-09-26T14:52:47","slug":"puntajes-vs-athletico-paranaense-sudamericana-2021","status":"publish","type":"post","link":"https:\/\/www.padreydecano.com\/cms\/noticias\/puntajes-vs-athletico-paranaense-sudamericana-2021\/","title":{"rendered":"Puntajes vs Athletico Paranaense (Sudamericana 2021)"},"content":{"rendered":"<p><a href=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2021\/09\/4FC37254-A7F8-41EE-AA60-F9001D052A4E.jpeg\" rel=\"shadowbox[sbpost-76924];player=img;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-76925\" src=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2021\/09\/4FC37254-A7F8-41EE-AA60-F9001D052A4E.jpeg\" alt=\"\" width=\"1600\" height=\"1066\" srcset=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2021\/09\/4FC37254-A7F8-41EE-AA60-F9001D052A4E.jpeg 1600w, https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2021\/09\/4FC37254-A7F8-41EE-AA60-F9001D052A4E-600x400.jpeg 600w, https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2021\/09\/4FC37254-A7F8-41EE-AA60-F9001D052A4E-768x512.jpeg 768w, https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2021\/09\/4FC37254-A7F8-41EE-AA60-F9001D052A4E-1024x682.jpeg 1024w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/a><\/p>\n<p class=\"p3\" style=\"text-align: justify;\"><span class=\"s2\"><strong>Kevin Dawson: <span style=\"color: #ffcc00;\">(5)<\/span><\/strong> A pesar de no tener una responsabilidad directa en los goles, queda la sensaci\u00f3n de que al menos en el segundo, pudo haber hecho algo m\u00e1s. <\/span><\/p>\n<p class=\"p3\" style=\"text-align: justify;\"><span class=\"s2\"><strong>Giovanni Gonz\u00e1lez: <span style=\"color: #ffcc00;\">(7)<\/span><\/strong> M\u00e1s que correcto partido, muy preciso en los cierres, aportando energ\u00eda por la banda y desdobl\u00e1ndose al ataque. Le falt\u00f3 mayor precisi\u00f3n a la hora de centrar.<\/span><\/p>\n<p class=\"p3\" style=\"text-align: justify;\"><span class=\"s2\"><strong>Carlos Rodr\u00edguez:<span style=\"color: #ffcc00;\"> (6)<\/span><\/strong> Firme en la zaga, jugando con un equipo muy adelantado, control\u00f3 la mayor\u00eda de los intentos de ataques rivales.<\/span><\/p>\n<p class=\"p3\" style=\"text-align: justify;\"><span class=\"s2\"><strong>Gary Kagelmacher: <span style=\"color: #ffcc00;\">(6)<\/span><\/strong> Igual que su compa\u00f1ero de zaga, en los goles no hay gran responsabilidad de ellos dos y durante el juego fueron una pareja s\u00f3lida, en defensa<\/span><\/p>\n<p class=\"p3\" style=\"text-align: justify;\"><span class=\"s2\"><strong>Juan Ramos:<span style=\"color: #ffcc00;\"> (3)<\/span><\/strong> Un error que cost\u00f3 car\u00edsimo. En estas instancias esas falencias quedan muy expuestas y el rival no lo perdon\u00f3, la serie arranc\u00f3 cuesta arriba. Se lo vio impreciso y con algunas dudas en la toma de decisiones. Bien sustituido.<\/span><\/p>\n<p class=\"p3\" style=\"text-align: justify;\"><span class=\"s2\"><strong>Agust\u00edn Canobbio: <span style=\"color: #ffcc00;\">(7)<\/span><\/strong> Sin lograr el pase final, pero intentando por todos los medios. Fue muy importante en la buena presi\u00f3n alta del equipo, y m\u00e1s que nada en el primer tiempo, fue de los mejores de Pe\u00f1arol. Con el pasar de los minutos su nivel fue bajando, en parte por cansancio y nerviosismo general.<\/span><\/p>\n<p class=\"p3\" style=\"text-align: justify;\"><span class=\"s2\"><strong>Walter Gargano: <span style=\"color: #ffcc00;\">(6)<\/span><\/strong> El planteo rival no le dej\u00f3 dominar el mediocampo de manera libre como s\u00ed lo hizo en otras series. De todas maneras cuando el equipo manej\u00f3 la pelota con m\u00e1s fluidez, fue cuando pas\u00f3 por sus pies, como en la jugada del gol. El cambio se explica por el tema sanitario comentado por el DT.<\/span><\/p>\n<p class=\"p3\" style=\"text-align: justify;\"><span class=\"s2\"><strong>Jes\u00fas Trindade:<span style=\"color: #ffcc00;\"> (5)<\/span><\/strong> El comienzo del gran error del primer gol rival es todo de \u00e9l, dividiendo una pelota innecesariamente ante la m\u00ednima presi\u00f3n. Luego se fue acomodando en el partido, hasta llegar a tomar m\u00e1s protagonismo en el mediocampo, pero la amarilla le cost\u00f3 el cambio.<\/span><\/p>\n<p class=\"p3\" style=\"text-align: justify;\"><span class=\"s2\"><strong>Pablo Ceppelini: <span style=\"color: #ffcc00;\">(6)<\/span><\/strong> La falta de espacios que propon\u00eda el rival, con un bloque defensivo bien cerrado, le impidi\u00f3 jugar de manera vertical, por momentos cay\u00f3 en la intrascendencia con el bal\u00f3n. Otro que fue clave en la presi\u00f3n al rival<\/span><\/p>\n<p class=\"p3\" style=\"text-align: justify;\"><span class=\"s2\"><strong>Facundo Torres:<span style=\"color: #ffcc00;\"> (7)<\/span><\/strong> Volviendo a ser el 10 del equipo. Fue desequilibrante por ambas bandas, volvi\u00f3 loco a los defensas rivales que solo pudieron pararlo con falta y amarillas. En la \u00fanica que se pudo agarrar mal parada a la defensa rival y no tan metida atr\u00e1s, gener\u00f3 la jugada del gol. Buen partido<\/span><\/p>\n<p class=\"p3\" style=\"text-align: justify;\"><span class=\"s2\"><strong>Agust\u00edn \u00c1lvarez Mart\u00ednez:<span style=\"color: #ffcc00;\"> (6)<\/span><\/strong> Muy poco habilitado, incluso en la jugada del gol, la cual requiere una genialidad de su parte para parar la pelota en el \u00e1rea y el olfato de siempre estar ah\u00ed. Pe\u00f1arol debe involucrarlo mucho m\u00e1s en el juego, aunque es cierto que es la principal referencia que toma el rival en cada ataque. El goleador de la Copa.<\/span><\/p>\n<p class=\"p3\" style=\"text-align: justify;\"><strong><span class=\"s2\">Ingresaron:<\/span><\/strong><\/p>\n<p class=\"p3\" style=\"text-align: justify;\"><span class=\"s2\"><strong>Valent\u00edn Rodr\u00edguez: <span style=\"color: #ffcc00;\">(5)<\/span><\/strong> Correcto partido, al que le pudo haber sumado m\u00e1s si se soltaba al ataque. Demuestra condiciones para quedarse con el puesto.<\/span><\/p>\n<p class=\"p3\" style=\"text-align: justify;\"><span class=\"s2\"><strong>Dami\u00e1n Musto:<span style=\"color: #ffcc00;\"> (5)<\/span><\/strong> Otro de correcto ingreso, aunque por momentos se excede en la marca y comete faltas innecesarias, es preciso con el bal\u00f3n y las coberturas, generalmente es un buen sustituto.<\/span><\/p>\n<p class=\"p3\" style=\"text-align: justify;\"><span class=\"s2\"><strong>Nicol\u00e1s Gaitan:<span style=\"color: #ffcc00;\"> (5)<\/span><\/strong> Siempre siendo opci\u00f3n de pase e intentando involucrarse en el juego. No fue el partido ideal para el debut, mucho menos cuando llega el segundo gol rival. Sorprendi\u00f3 la mala ejecuci\u00f3n de pelota quieta, la cual esperemos sea solo ocasional.<\/span><\/p>\n<p class=\"p3\" style=\"text-align: justify;\"><span class=\"s2\"><strong>Ariel Nahuelpan:<span style=\"color: #ffcc00;\"> (-)<\/span><\/strong> Pocos minutos.<\/span><\/p>\n<p class=\"p3\" style=\"text-align: justify;\"><span class=\"s2\"><strong>Ignacio Laquintana: <span style=\"color: #ffcc00;\">(-)<\/span><\/strong> Pocos minutos.<\/span><\/p>\n<p class=\"p3\" style=\"text-align: justify;\"><span class=\"s2\"><div class=\"user-wrapper\"><a class=\"userlink\" href=\"https:\/\/twitter.com\/agustin_oronoz\" target=\"_blank\"><figure><img decoding=\"async\" src=\"http:\/\/www.padreydecano.com\/cms\/wp-users-files\/postfirmas\/agustin_oronoz.jpg\" \/><\/figure><p class=\"user\"><strong>Agust&iacute;n Oronoz<\/strong><br \/>@agustin_oronoz<\/p><\/a><\/div><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kevin Dawson: (5) A pesar de no tener una responsabilidad directa en los goles, queda la sensaci\u00f3n de que al menos en el segundo, pudo haber hecho algo m\u00e1s. Giovanni Gonz\u00e1lez: (7) M\u00e1s que correcto partido, muy preciso en los cierres, aportando energ\u00eda por la banda y desdobl\u00e1ndose al ataque. Le falt\u00f3 mayor precisi\u00f3n a [&hellip;]<\/p>\n","protected":false},"author":30,"featured_media":76925,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Puntajes vs Athletico Paranaense (Sudamericana 2021) - Padre y Decano - El Sitio del Pueblo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.padreydecano.com\/cms\/noticias\/puntajes-vs-athletico-paranaense-sudamericana-2021\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Puntajes vs Athletico Paranaense (Sudamericana 2021) - Padre y Decano - El Sitio del Pueblo\" \/>\n<meta property=\"og:description\" content=\"Kevin Dawson: (5) A pesar de no tener una responsabilidad directa en los goles, queda la sensaci\u00f3n de que al menos en el segundo, pudo haber hecho algo m\u00e1s. Giovanni Gonz\u00e1lez: (7) M\u00e1s que correcto partido, muy preciso en los cierres, aportando energ\u00eda por la banda y desdobl\u00e1ndose al ataque. Le falt\u00f3 mayor precisi\u00f3n a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.padreydecano.com\/cms\/noticias\/puntajes-vs-athletico-paranaense-sudamericana-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"Padre y Decano - El Sitio del Pueblo\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-24T14:19:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-26T14:52:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2021\/09\/4FC37254-A7F8-41EE-AA60-F9001D052A4E.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1066\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Udelar\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Udelar\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/puntajes-vs-athletico-paranaense-sudamericana-2021\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/puntajes-vs-athletico-paranaense-sudamericana-2021\/\"},\"author\":{\"name\":\"Udelar\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/b22191326be6d1c7fa55c2ad137a9a32\"},\"headline\":\"Puntajes vs Athletico Paranaense (Sudamericana 2021)\",\"datePublished\":\"2021-09-24T14:19:46+00:00\",\"dateModified\":\"2021-09-26T14:52:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/puntajes-vs-athletico-paranaense-sudamericana-2021\/\"},\"wordCount\":608,\"commentCount\":61,\"publisher\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/puntajes-vs-athletico-paranaense-sudamericana-2021\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2021\/09\/4FC37254-A7F8-41EE-AA60-F9001D052A4E.jpeg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.padreydecano.com\/cms\/noticias\/puntajes-vs-athletico-paranaense-sudamericana-2021\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/puntajes-vs-athletico-paranaense-sudamericana-2021\/\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/puntajes-vs-athletico-paranaense-sudamericana-2021\/\",\"name\":\"Puntajes vs Athletico Paranaense (Sudamericana 2021) - Padre y Decano - El Sitio del Pueblo\",\"isPartOf\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/puntajes-vs-athletico-paranaense-sudamericana-2021\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/puntajes-vs-athletico-paranaense-sudamericana-2021\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2021\/09\/4FC37254-A7F8-41EE-AA60-F9001D052A4E.jpeg\",\"datePublished\":\"2021-09-24T14:19:46+00:00\",\"dateModified\":\"2021-09-26T14:52:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/puntajes-vs-athletico-paranaense-sudamericana-2021\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.padreydecano.com\/cms\/noticias\/puntajes-vs-athletico-paranaense-sudamericana-2021\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/puntajes-vs-athletico-paranaense-sudamericana-2021\/#primaryimage\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2021\/09\/4FC37254-A7F8-41EE-AA60-F9001D052A4E.jpeg\",\"contentUrl\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2021\/09\/4FC37254-A7F8-41EE-AA60-F9001D052A4E.jpeg\",\"width\":1600,\"height\":1066},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/puntajes-vs-athletico-paranaense-sudamericana-2021\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.padreydecano.com\/cms\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Puntajes vs Athletico Paranaense (Sudamericana 2021)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#website\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/\",\"name\":\"Padre y Decano - El Sitio del Pueblo\",\"description\":\"Club Atl\u00e9tico Pe\u00f1arol\",\"publisher\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.padreydecano.com\/cms\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#organization\",\"name\":\"Padre y Decano\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2022\/01\/avatar-square.png\",\"contentUrl\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2022\/01\/avatar-square.png\",\"width\":1500,\"height\":1500,\"caption\":\"Padre y Decano\"},\"image\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/b22191326be6d1c7fa55c2ad137a9a32\",\"name\":\"Udelar\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/611ece663b16897a2cd2f46982281225?s=96&d=https%3A%2F%2Fpadreydecano.com%2Fcms%2Fwp-content%2Fthemes%2Fpyd-theme%2Fimg%2Fdefault-avatar.png&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/611ece663b16897a2cd2f46982281225?s=96&d=https%3A%2F%2Fpadreydecano.com%2Fcms%2Fwp-content%2Fthemes%2Fpyd-theme%2Fimg%2Fdefault-avatar.png&r=g\",\"caption\":\"Udelar\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Puntajes vs Athletico Paranaense (Sudamericana 2021) - Padre y Decano - El Sitio del Pueblo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.padreydecano.com\/cms\/noticias\/puntajes-vs-athletico-paranaense-sudamericana-2021\/","og_locale":"es_ES","og_type":"article","og_title":"Puntajes vs Athletico Paranaense (Sudamericana 2021) - Padre y Decano - El Sitio del Pueblo","og_description":"Kevin Dawson: (5) A pesar de no tener una responsabilidad directa en los goles, queda la sensaci\u00f3n de que al menos en el segundo, pudo haber hecho algo m\u00e1s. Giovanni Gonz\u00e1lez: (7) M\u00e1s que correcto partido, muy preciso en los cierres, aportando energ\u00eda por la banda y desdobl\u00e1ndose al ataque. Le falt\u00f3 mayor precisi\u00f3n a [&hellip;]","og_url":"https:\/\/www.padreydecano.com\/cms\/noticias\/puntajes-vs-athletico-paranaense-sudamericana-2021\/","og_site_name":"Padre y Decano - El Sitio del Pueblo","article_published_time":"2021-09-24T14:19:46+00:00","article_modified_time":"2021-09-26T14:52:47+00:00","og_image":[{"width":1600,"height":1066,"url":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2021\/09\/4FC37254-A7F8-41EE-AA60-F9001D052A4E.jpeg","type":"image\/jpeg"}],"author":"Udelar","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Udelar","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/puntajes-vs-athletico-paranaense-sudamericana-2021\/#article","isPartOf":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/puntajes-vs-athletico-paranaense-sudamericana-2021\/"},"author":{"name":"Udelar","@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/b22191326be6d1c7fa55c2ad137a9a32"},"headline":"Puntajes vs Athletico Paranaense (Sudamericana 2021)","datePublished":"2021-09-24T14:19:46+00:00","dateModified":"2021-09-26T14:52:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/puntajes-vs-athletico-paranaense-sudamericana-2021\/"},"wordCount":608,"commentCount":61,"publisher":{"@id":"https:\/\/www.padreydecano.com\/cms\/#organization"},"image":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/puntajes-vs-athletico-paranaense-sudamericana-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2021\/09\/4FC37254-A7F8-41EE-AA60-F9001D052A4E.jpeg","articleSection":["Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.padreydecano.com\/cms\/noticias\/puntajes-vs-athletico-paranaense-sudamericana-2021\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/puntajes-vs-athletico-paranaense-sudamericana-2021\/","url":"https:\/\/www.padreydecano.com\/cms\/noticias\/puntajes-vs-athletico-paranaense-sudamericana-2021\/","name":"Puntajes vs Athletico Paranaense (Sudamericana 2021) - Padre y Decano - El Sitio del Pueblo","isPartOf":{"@id":"https:\/\/www.padreydecano.com\/cms\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/puntajes-vs-athletico-paranaense-sudamericana-2021\/#primaryimage"},"image":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/puntajes-vs-athletico-paranaense-sudamericana-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2021\/09\/4FC37254-A7F8-41EE-AA60-F9001D052A4E.jpeg","datePublished":"2021-09-24T14:19:46+00:00","dateModified":"2021-09-26T14:52:47+00:00","breadcrumb":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/puntajes-vs-athletico-paranaense-sudamericana-2021\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.padreydecano.com\/cms\/noticias\/puntajes-vs-athletico-paranaense-sudamericana-2021\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/puntajes-vs-athletico-paranaense-sudamericana-2021\/#primaryimage","url":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2021\/09\/4FC37254-A7F8-41EE-AA60-F9001D052A4E.jpeg","contentUrl":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2021\/09\/4FC37254-A7F8-41EE-AA60-F9001D052A4E.jpeg","width":1600,"height":1066},{"@type":"BreadcrumbList","@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/puntajes-vs-athletico-paranaense-sudamericana-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.padreydecano.com\/cms\/"},{"@type":"ListItem","position":2,"name":"Puntajes vs Athletico Paranaense (Sudamericana 2021)"}]},{"@type":"WebSite","@id":"https:\/\/www.padreydecano.com\/cms\/#website","url":"https:\/\/www.padreydecano.com\/cms\/","name":"Padre y Decano - El Sitio del Pueblo","description":"Club Atl\u00e9tico Pe\u00f1arol","publisher":{"@id":"https:\/\/www.padreydecano.com\/cms\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.padreydecano.com\/cms\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.padreydecano.com\/cms\/#organization","name":"Padre y Decano","url":"https:\/\/www.padreydecano.com\/cms\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/logo\/image\/","url":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2022\/01\/avatar-square.png","contentUrl":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2022\/01\/avatar-square.png","width":1500,"height":1500,"caption":"Padre y Decano"},"image":{"@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/b22191326be6d1c7fa55c2ad137a9a32","name":"Udelar","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/611ece663b16897a2cd2f46982281225?s=96&d=https%3A%2F%2Fpadreydecano.com%2Fcms%2Fwp-content%2Fthemes%2Fpyd-theme%2Fimg%2Fdefault-avatar.png&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/611ece663b16897a2cd2f46982281225?s=96&d=https%3A%2F%2Fpadreydecano.com%2Fcms%2Fwp-content%2Fthemes%2Fpyd-theme%2Fimg%2Fdefault-avatar.png&r=g","caption":"Udelar"}}]}},"_links":{"self":[{"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/posts\/76924"}],"collection":[{"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/comments?post=76924"}],"version-history":[{"count":0,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/posts\/76924\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/media\/76925"}],"wp:attachment":[{"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/media?parent=76924"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/categories?post=76924"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/tags?post=76924"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}