{"id":74870,"date":"2020-11-26T20:46:37","date_gmt":"2020-11-26T23:46:37","guid":{"rendered":"http:\/\/www.padreydecano.com\/cms\/?p=74870"},"modified":"2020-11-30T09:49:08","modified_gmt":"2020-11-30T12:49:08","slug":"todas-las-listas-de-las-elecciones","status":"publish","type":"post","link":"https:\/\/www.padreydecano.com\/cms\/noticias\/todas-las-listas-de-las-elecciones\/","title":{"rendered":"Todas las listas de las elecciones"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-64824\" src=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2017\/10\/elecciones-2014-2.jpg\" alt=\"\" width=\"900\" height=\"492\" srcset=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2017\/10\/elecciones-2014-2.jpg 900w, https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2017\/10\/elecciones-2014-2-600x328.jpg 600w, https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2017\/10\/elecciones-2014-2-768x420.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/p>\n<p style=\"text-align: justify;\"><strong>El pr\u00f3ximo 5 de diciembre, los socios de Pe\u00f1arol designaremos autoridades para el per\u00edodo 2021-2023. Los candidatos ser\u00e1n cinco: Evaristo Gonz\u00e1lez, Guillermo Varela, Juan Ignacio Ruglio, Juan Pedro Damiani y Mario Colla. Padre y Decano te presenta las listas que apoyar\u00e1n a cada f\u00f3rmula.<\/strong><\/p>\n<p><span style=\"color: #ffcc00;\"><strong>Evaristo Gonz\u00e1lez &#8211; Carlos Scherschener<\/strong><\/span><\/p>\n<p><strong>Lista 280921<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-74872\" src=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2020\/11\/lista-280921.jpg\" alt=\"\" width=\"648\" height=\"900\" srcset=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2020\/11\/lista-280921.jpg 648w, https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2020\/11\/lista-280921-432x600.jpg 432w\" sizes=\"(max-width: 648px) 100vw, 648px\" \/><\/p>\n<p><span style=\"color: #ffcc00;\"><strong>Guillermo Varela &#8211; Marcos Acle<\/strong><\/span><\/p>\n<p><strong>Lista 129<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-74871\" src=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2020\/11\/lista-129.jpg\" alt=\"\" width=\"600\" height=\"900\" srcset=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2020\/11\/lista-129.jpg 600w, https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2020\/11\/lista-129-400x600.jpg 400w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/p>\n<p><span style=\"color: #ffcc00;\"><strong>Juan Ignacio Ruglio &#8211; Eduardo Zaindesztat<\/strong><\/span><\/p>\n<p><strong>Lista 1891<\/strong><\/p>\n<p><a href=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2020\/11\/Lista-1891-2020.png\" rel=\"shadowbox[sbpost-74870];player=img;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-74880 size-large\" src=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2020\/11\/Lista-1891-2020-696x1024.png\" alt=\"\" width=\"620\" height=\"912\" srcset=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2020\/11\/Lista-1891-2020-696x1024.png 696w, https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2020\/11\/Lista-1891-2020-408x600.png 408w, https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2020\/11\/Lista-1891-2020-768x1130.png 768w, https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2020\/11\/Lista-1891-2020.png 1935w\" sizes=\"(max-width: 620px) 100vw, 620px\" \/><\/a><\/p>\n<p><span style=\"color: #ffcc00;\"><strong>Juan Pedro Damiani &#8211; Gast\u00f3n Tealdi<\/strong><\/span><\/p>\n<p><strong>Lista 3<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-74873\" src=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2020\/11\/lista3.jpg\" alt=\"\" width=\"613\" height=\"900\" srcset=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2020\/11\/lista3.jpg 613w, https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2020\/11\/lista3-409x600.jpg 409w\" sizes=\"(max-width: 613px) 100vw, 613px\" \/><\/p>\n<p><strong>Lista 5<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-74874\" src=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2020\/11\/lista5.jpg\" alt=\"\" width=\"637\" height=\"900\" srcset=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2020\/11\/lista5.jpg 637w, https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2020\/11\/lista5-425x600.jpg 425w\" sizes=\"(max-width: 637px) 100vw, 637px\" \/><\/p>\n<p><strong>Lista 10<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-74875\" src=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2020\/11\/lista10.jpg\" alt=\"\" width=\"616\" height=\"900\" srcset=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2020\/11\/lista10.jpg 616w, https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2020\/11\/lista10-411x600.jpg 411w\" sizes=\"(max-width: 616px) 100vw, 616px\" \/><\/p>\n<p><strong>Lista 1987<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-74877\" src=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2020\/11\/lista1987.jpg\" alt=\"\" width=\"641\" height=\"900\" srcset=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2020\/11\/lista1987.jpg 641w, https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2020\/11\/lista1987-427x600.jpg 427w\" sizes=\"(max-width: 641px) 100vw, 641px\" \/><\/p>\n<p><span style=\"color: #ffcc00;\"><strong>Mario Colla &#8211; Jos\u00e9 Da Silva<\/strong><\/span><\/p>\n<p><strong>Lista 555<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-74878\" src=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2020\/11\/WhatsApp-Image-2020-11-25-at-1.10.44-PM.jpeg\" alt=\"\" width=\"1005\" height=\"1418\" srcset=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2020\/11\/WhatsApp-Image-2020-11-25-at-1.10.44-PM.jpeg 1005w, https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2020\/11\/WhatsApp-Image-2020-11-25-at-1.10.44-PM-425x600.jpeg 425w, https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2020\/11\/WhatsApp-Image-2020-11-25-at-1.10.44-PM-768x1084.jpeg 768w, https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2020\/11\/WhatsApp-Image-2020-11-25-at-1.10.44-PM-726x1024.jpeg 726w\" sizes=\"(max-width: 1005px) 100vw, 1005px\" \/><\/p>\n<p style=\"text-align: justify;\"><strong>De estas listas saldr\u00e1n los 11 integrantes de la Comisi\u00f3n Directiva, los 3 de la Comisi\u00f3n Fiscal, los 3 de la Comisi\u00f3n Electoral y los 124 de la Asamblea Representativa.<\/strong><\/p>\n<div class=\"user-wrapper\"><a class=\"userlink\" href=\"https:\/\/twitter.com\/brunocurcc\" target=\"_blank\"><figure><img decoding=\"async\" src=\"http:\/\/www.padreydecano.com\/cms\/wp-users-files\/postfirmas\/brunocurcc.jpg\" \/><\/figure><p class=\"user\"><strong>Bruno Mazza<\/strong><br \/>@brunocurcc<\/p><\/a><\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pr\u00f3ximo 5 de diciembre, los socios de Pe\u00f1arol designaremos autoridades para el per\u00edodo 2021-2023. Los candidatos ser\u00e1n cinco: Evaristo Gonz\u00e1lez, Guillermo Varela, Juan Ignacio Ruglio, Juan Pedro Damiani y Mario Colla. Padre y Decano te presenta las listas que apoyar\u00e1n a cada f\u00f3rmula. Evaristo Gonz\u00e1lez &#8211; Carlos Scherschener Lista 280921 Guillermo Varela &#8211; Marcos [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":50377,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Todas las listas de las elecciones - Padre y Decano - El Sitio del Pueblo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.padreydecano.com\/cms\/noticias\/todas-las-listas-de-las-elecciones\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Todas las listas de las elecciones - Padre y Decano - El Sitio del Pueblo\" \/>\n<meta property=\"og:description\" content=\"El pr\u00f3ximo 5 de diciembre, los socios de Pe\u00f1arol designaremos autoridades para el per\u00edodo 2021-2023. Los candidatos ser\u00e1n cinco: Evaristo Gonz\u00e1lez, Guillermo Varela, Juan Ignacio Ruglio, Juan Pedro Damiani y Mario Colla. Padre y Decano te presenta las listas que apoyar\u00e1n a cada f\u00f3rmula. Evaristo Gonz\u00e1lez &#8211; Carlos Scherschener Lista 280921 Guillermo Varela &#8211; Marcos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.padreydecano.com\/cms\/noticias\/todas-las-listas-de-las-elecciones\/\" \/>\n<meta property=\"og:site_name\" content=\"Padre y Decano - El Sitio del Pueblo\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-26T23:46:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-30T12:49:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2014\/12\/elecciones-penarol-2014-14-mariano-alvez.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"492\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"1891\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"1891\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/todas-las-listas-de-las-elecciones\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/todas-las-listas-de-las-elecciones\/\"},\"author\":{\"name\":\"1891\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/5607c72c38a1537a151b24d1e67535e0\"},\"headline\":\"Todas las listas de las elecciones\",\"datePublished\":\"2020-11-26T23:46:37+00:00\",\"dateModified\":\"2020-11-30T12:49:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/todas-las-listas-de-las-elecciones\/\"},\"wordCount\":126,\"commentCount\":95,\"publisher\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/todas-las-listas-de-las-elecciones\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2014\/12\/elecciones-penarol-2014-14-mariano-alvez.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.padreydecano.com\/cms\/noticias\/todas-las-listas-de-las-elecciones\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/todas-las-listas-de-las-elecciones\/\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/todas-las-listas-de-las-elecciones\/\",\"name\":\"Todas las listas de las elecciones - Padre y Decano - El Sitio del Pueblo\",\"isPartOf\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/todas-las-listas-de-las-elecciones\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/todas-las-listas-de-las-elecciones\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2014\/12\/elecciones-penarol-2014-14-mariano-alvez.jpg\",\"datePublished\":\"2020-11-26T23:46:37+00:00\",\"dateModified\":\"2020-11-30T12:49:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/todas-las-listas-de-las-elecciones\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.padreydecano.com\/cms\/noticias\/todas-las-listas-de-las-elecciones\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/todas-las-listas-de-las-elecciones\/#primaryimage\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2014\/12\/elecciones-penarol-2014-14-mariano-alvez.jpg\",\"contentUrl\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2014\/12\/elecciones-penarol-2014-14-mariano-alvez.jpg\",\"width\":900,\"height\":492},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/todas-las-listas-de-las-elecciones\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.padreydecano.com\/cms\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Todas las listas de las elecciones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#website\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/\",\"name\":\"Padre y Decano - El Sitio del Pueblo\",\"description\":\"Club Atl\u00e9tico Pe\u00f1arol\",\"publisher\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.padreydecano.com\/cms\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#organization\",\"name\":\"Padre y Decano\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2022\/01\/avatar-square.png\",\"contentUrl\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2022\/01\/avatar-square.png\",\"width\":1500,\"height\":1500,\"caption\":\"Padre y Decano\"},\"image\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/5607c72c38a1537a151b24d1e67535e0\",\"name\":\"1891\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/29d4d1b0d523a21898e8cf9585d259d3?s=96&d=https%3A%2F%2Fpadreydecano.com%2Fcms%2Fwp-content%2Fthemes%2Fpyd-theme%2Fimg%2Fdefault-avatar.png&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/29d4d1b0d523a21898e8cf9585d259d3?s=96&d=https%3A%2F%2Fpadreydecano.com%2Fcms%2Fwp-content%2Fthemes%2Fpyd-theme%2Fimg%2Fdefault-avatar.png&r=g\",\"caption\":\"1891\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Todas las listas de las elecciones - Padre y Decano - El Sitio del Pueblo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.padreydecano.com\/cms\/noticias\/todas-las-listas-de-las-elecciones\/","og_locale":"es_ES","og_type":"article","og_title":"Todas las listas de las elecciones - Padre y Decano - El Sitio del Pueblo","og_description":"El pr\u00f3ximo 5 de diciembre, los socios de Pe\u00f1arol designaremos autoridades para el per\u00edodo 2021-2023. Los candidatos ser\u00e1n cinco: Evaristo Gonz\u00e1lez, Guillermo Varela, Juan Ignacio Ruglio, Juan Pedro Damiani y Mario Colla. Padre y Decano te presenta las listas que apoyar\u00e1n a cada f\u00f3rmula. Evaristo Gonz\u00e1lez &#8211; Carlos Scherschener Lista 280921 Guillermo Varela &#8211; Marcos [&hellip;]","og_url":"https:\/\/www.padreydecano.com\/cms\/noticias\/todas-las-listas-de-las-elecciones\/","og_site_name":"Padre y Decano - El Sitio del Pueblo","article_published_time":"2020-11-26T23:46:37+00:00","article_modified_time":"2020-11-30T12:49:08+00:00","og_image":[{"width":900,"height":492,"url":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2014\/12\/elecciones-penarol-2014-14-mariano-alvez.jpg","type":"image\/jpeg"}],"author":"1891","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"1891","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/todas-las-listas-de-las-elecciones\/#article","isPartOf":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/todas-las-listas-de-las-elecciones\/"},"author":{"name":"1891","@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/5607c72c38a1537a151b24d1e67535e0"},"headline":"Todas las listas de las elecciones","datePublished":"2020-11-26T23:46:37+00:00","dateModified":"2020-11-30T12:49:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/todas-las-listas-de-las-elecciones\/"},"wordCount":126,"commentCount":95,"publisher":{"@id":"https:\/\/www.padreydecano.com\/cms\/#organization"},"image":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/todas-las-listas-de-las-elecciones\/#primaryimage"},"thumbnailUrl":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2014\/12\/elecciones-penarol-2014-14-mariano-alvez.jpg","articleSection":["Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.padreydecano.com\/cms\/noticias\/todas-las-listas-de-las-elecciones\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/todas-las-listas-de-las-elecciones\/","url":"https:\/\/www.padreydecano.com\/cms\/noticias\/todas-las-listas-de-las-elecciones\/","name":"Todas las listas de las elecciones - Padre y Decano - El Sitio del Pueblo","isPartOf":{"@id":"https:\/\/www.padreydecano.com\/cms\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/todas-las-listas-de-las-elecciones\/#primaryimage"},"image":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/todas-las-listas-de-las-elecciones\/#primaryimage"},"thumbnailUrl":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2014\/12\/elecciones-penarol-2014-14-mariano-alvez.jpg","datePublished":"2020-11-26T23:46:37+00:00","dateModified":"2020-11-30T12:49:08+00:00","breadcrumb":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/todas-las-listas-de-las-elecciones\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.padreydecano.com\/cms\/noticias\/todas-las-listas-de-las-elecciones\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/todas-las-listas-de-las-elecciones\/#primaryimage","url":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2014\/12\/elecciones-penarol-2014-14-mariano-alvez.jpg","contentUrl":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2014\/12\/elecciones-penarol-2014-14-mariano-alvez.jpg","width":900,"height":492},{"@type":"BreadcrumbList","@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/todas-las-listas-de-las-elecciones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.padreydecano.com\/cms\/"},{"@type":"ListItem","position":2,"name":"Todas las listas de las elecciones"}]},{"@type":"WebSite","@id":"https:\/\/www.padreydecano.com\/cms\/#website","url":"https:\/\/www.padreydecano.com\/cms\/","name":"Padre y Decano - El Sitio del Pueblo","description":"Club Atl\u00e9tico Pe\u00f1arol","publisher":{"@id":"https:\/\/www.padreydecano.com\/cms\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.padreydecano.com\/cms\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.padreydecano.com\/cms\/#organization","name":"Padre y Decano","url":"https:\/\/www.padreydecano.com\/cms\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/logo\/image\/","url":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2022\/01\/avatar-square.png","contentUrl":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2022\/01\/avatar-square.png","width":1500,"height":1500,"caption":"Padre y Decano"},"image":{"@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/5607c72c38a1537a151b24d1e67535e0","name":"1891","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/29d4d1b0d523a21898e8cf9585d259d3?s=96&d=https%3A%2F%2Fpadreydecano.com%2Fcms%2Fwp-content%2Fthemes%2Fpyd-theme%2Fimg%2Fdefault-avatar.png&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/29d4d1b0d523a21898e8cf9585d259d3?s=96&d=https%3A%2F%2Fpadreydecano.com%2Fcms%2Fwp-content%2Fthemes%2Fpyd-theme%2Fimg%2Fdefault-avatar.png&r=g","caption":"1891"}}]}},"_links":{"self":[{"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/posts\/74870"}],"collection":[{"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/comments?post=74870"}],"version-history":[{"count":0,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/posts\/74870\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/media\/50377"}],"wp:attachment":[{"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/media?parent=74870"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/categories?post=74870"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/tags?post=74870"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}