{"id":71540,"date":"2019-08-15T19:24:35","date_gmt":"2019-08-15T22:24:35","guid":{"rendered":"http:\/\/www.padreydecano.com\/cms\/?p=71540"},"modified":"2019-08-15T19:27:28","modified_gmt":"2019-08-15T22:27:28","slug":"venta-de-entradas-vs-juventud-de-las-piedras-torneo-intermedio-2019","status":"publish","type":"post","link":"https:\/\/www.padreydecano.com\/cms\/noticias\/venta-de-entradas-vs-juventud-de-las-piedras-torneo-intermedio-2019\/","title":{"rendered":"Venta de entradas vs Juventud de Las Piedras (Torneo Intermedio 2019)"},"content":{"rendered":"<p><a href=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2019\/07\/ENTRADAS75.png\" rel=\"shadowbox[sbpost-71540];player=img;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-71211\" src=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2019\/07\/ENTRADAS75.png\" alt=\"\" width=\"800\" height=\"600\" srcset=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2019\/07\/ENTRADAS75.png 800w, https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2019\/07\/ENTRADAS75-600x450.png 600w, https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2019\/07\/ENTRADAS75-768x576.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><strong>Ya est\u00e1 habilitado el canje y venta de entradas para el encuentro entre Pe\u00f1arol y Juventud de las Piedras, a jugarse el pr\u00f3ximo domingo a partir de las 18 horas, en el Estadio Campe\u00f3n del Siglo, por la quinta fecha del Torneo Intermedio 2019. Adquir\u00ed la tuya en los locales de Redpagos o a trav\u00e9s de Tickantel.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"color: #ffcc00;\">Operativo de venta<\/span><\/strong><\/p>\n<p style=\"text-align: justify;\">Los <strong>socios con TCAP<\/strong>\u00a0canjean la suya a trav\u00e9s de la aplicaci\u00f3n \u2018Tarjeta CAP\u2019.<\/p>\n<p style=\"text-align: justify;\">Los\u00a0<strong>socios sin TCAP<\/strong>\u00a0deben dirigirse a un Redpagos hasta el d\u00eda previo al partido para realizar el canje.<\/p>\n<p style=\"text-align: justify;\">La venta de\u00a0<strong>entradas generales<\/strong>\u00a0es a trav\u00e9s de\u00a0la web de Tickantel (hasta la hora del partido) y en locales de Redpagos (hasta el d\u00eda previo al partido).<\/p>\n<p style=\"text-align: justify;\">Los\u00a0<strong>Palquistas y Butaquistas<\/strong>\u00a0que tengan su lugar asociado a su TCAP, ingresan de forma directa al Estadio Campe\u00f3n del Siglo. Si tienen tarjeta, gen\u00e9rica deber\u00e1n canjearla previamente, por la aplicaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Los\u00a0<strong>Socios Adherentes<\/strong>\u00a0tienen la oportunidad de ingresar gratis en un partido por Campeonato Uruguayo; sino podr\u00e1n acceder a las tribunas Cataldi o Damiani, con un 30 % de descuento.<\/p>\n<p style=\"text-align: justify;\">Los\u00a0<strong>Socios Cadetes<\/strong>\u00a0(de 6 a 11 a\u00f1os inclusive) que quieran acceder de forma gratuita a la Tribuna Henderson, deber\u00e1n canjear previamente su entrada en los locales Redpagos, independientemente de que tengan o no TCAP.<\/p>\n<p style=\"text-align: justify;\">La novedad: con motivo del d\u00eda del ni\u00f1o, <strong>todos los ni\u00f1os de hasta 12 a\u00f1os ingresar\u00e1n gratis en todas las tribunas,\u00a0<\/strong>acompa\u00f1ados de un adulto.<\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"color: #ffcc00;\">Tribuna Cataldi<\/span><\/strong><\/p>\n<ul style=\"text-align: justify;\">\n<li>Socios:\u00a0Gratis<\/li>\n<li>Socios adherentes:\u00a0$ 245<\/li>\n<li>Generales:\u00a0$ 350<\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><strong><span style=\"color: #ffcc00;\">Tribuna Damiani<\/span><\/strong><\/p>\n<ul style=\"text-align: justify;\">\n<li>Socios: Gratis<\/li>\n<li>Socios adherentes:\u00a0$455<\/li>\n<li>Generales:\u00a0$650<\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><strong><span style=\"color: #ffcc00;\">Tribuna Henderson<\/span><\/strong><\/p>\n<ul style=\"text-align: justify;\">\n<li>Socios:\u00a0$750<\/li>\n<li>Generales:\u00a0$1.600<\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><strong><span style=\"color: #ffcc00;\">Visita<\/span><\/strong><\/p>\n<p style=\"text-align: justify;\">Para los parciales de Juventud de las Piedras, las entradas se vender\u00e1n en los locales de Redpagos a $ 350. Ser\u00e1n ubicados en el port\u00f3n \u2018A\u2019 de la Tribuna Guelfi.<\/p>\n<p style=\"text-align: right;\"><a href=\"https:\/\/twitter.com\/mathiaastilve\" target=\"_blank\" rel=\"noopener\">Mathias Tilve<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ya est\u00e1 habilitado el canje y venta de entradas para el encuentro entre Pe\u00f1arol y Juventud de las Piedras, a jugarse el pr\u00f3ximo domingo a partir de las 18 horas, en el Estadio Campe\u00f3n del Siglo, por la quinta fecha del Torneo Intermedio 2019. Adquir\u00ed la tuya en los locales de Redpagos o a trav\u00e9s [&hellip;]<\/p>\n","protected":false},"author":30,"featured_media":71211,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[447,32],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Venta de entradas vs Juventud de Las Piedras (Torneo Intermedio 2019) - Padre y Decano - El Sitio del Pueblo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.padreydecano.com\/cms\/noticias\/venta-de-entradas-vs-juventud-de-las-piedras-torneo-intermedio-2019\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Venta de entradas vs Juventud de Las Piedras (Torneo Intermedio 2019) - Padre y Decano - El Sitio del Pueblo\" \/>\n<meta property=\"og:description\" content=\"Ya est\u00e1 habilitado el canje y venta de entradas para el encuentro entre Pe\u00f1arol y Juventud de las Piedras, a jugarse el pr\u00f3ximo domingo a partir de las 18 horas, en el Estadio Campe\u00f3n del Siglo, por la quinta fecha del Torneo Intermedio 2019. Adquir\u00ed la tuya en los locales de Redpagos o a trav\u00e9s [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.padreydecano.com\/cms\/noticias\/venta-de-entradas-vs-juventud-de-las-piedras-torneo-intermedio-2019\/\" \/>\n<meta property=\"og:site_name\" content=\"Padre y Decano - El Sitio del Pueblo\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-15T22:24:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-08-15T22:27:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2019\/07\/ENTRADAS75.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Udelar\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Udelar\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/venta-de-entradas-vs-juventud-de-las-piedras-torneo-intermedio-2019\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/venta-de-entradas-vs-juventud-de-las-piedras-torneo-intermedio-2019\/\"},\"author\":{\"name\":\"Udelar\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/b22191326be6d1c7fa55c2ad137a9a32\"},\"headline\":\"Venta de entradas vs Juventud de Las Piedras (Torneo Intermedio 2019)\",\"datePublished\":\"2019-08-15T22:24:35+00:00\",\"dateModified\":\"2019-08-15T22:27:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/venta-de-entradas-vs-juventud-de-las-piedras-torneo-intermedio-2019\/\"},\"wordCount\":320,\"commentCount\":8,\"publisher\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/venta-de-entradas-vs-juventud-de-las-piedras-torneo-intermedio-2019\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2019\/07\/ENTRADAS75.png\",\"keywords\":[\"Torneo Intermedio 2019\",\"Venta de entradas\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.padreydecano.com\/cms\/noticias\/venta-de-entradas-vs-juventud-de-las-piedras-torneo-intermedio-2019\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/venta-de-entradas-vs-juventud-de-las-piedras-torneo-intermedio-2019\/\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/venta-de-entradas-vs-juventud-de-las-piedras-torneo-intermedio-2019\/\",\"name\":\"Venta de entradas vs Juventud de Las Piedras (Torneo Intermedio 2019) - Padre y Decano - El Sitio del Pueblo\",\"isPartOf\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/venta-de-entradas-vs-juventud-de-las-piedras-torneo-intermedio-2019\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/venta-de-entradas-vs-juventud-de-las-piedras-torneo-intermedio-2019\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2019\/07\/ENTRADAS75.png\",\"datePublished\":\"2019-08-15T22:24:35+00:00\",\"dateModified\":\"2019-08-15T22:27:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/venta-de-entradas-vs-juventud-de-las-piedras-torneo-intermedio-2019\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.padreydecano.com\/cms\/noticias\/venta-de-entradas-vs-juventud-de-las-piedras-torneo-intermedio-2019\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/venta-de-entradas-vs-juventud-de-las-piedras-torneo-intermedio-2019\/#primaryimage\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2019\/07\/ENTRADAS75.png\",\"contentUrl\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2019\/07\/ENTRADAS75.png\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/venta-de-entradas-vs-juventud-de-las-piedras-torneo-intermedio-2019\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.padreydecano.com\/cms\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Venta de entradas vs Juventud de Las Piedras (Torneo Intermedio 2019)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#website\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/\",\"name\":\"Padre y Decano - El Sitio del Pueblo\",\"description\":\"Club Atl\u00e9tico Pe\u00f1arol\",\"publisher\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.padreydecano.com\/cms\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#organization\",\"name\":\"Padre y Decano\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2022\/01\/avatar-square.png\",\"contentUrl\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2022\/01\/avatar-square.png\",\"width\":1500,\"height\":1500,\"caption\":\"Padre y Decano\"},\"image\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/b22191326be6d1c7fa55c2ad137a9a32\",\"name\":\"Udelar\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/611ece663b16897a2cd2f46982281225?s=96&d=https%3A%2F%2Fpadreydecano.com%2Fcms%2Fwp-content%2Fthemes%2Fpyd-theme%2Fimg%2Fdefault-avatar.png&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/611ece663b16897a2cd2f46982281225?s=96&d=https%3A%2F%2Fpadreydecano.com%2Fcms%2Fwp-content%2Fthemes%2Fpyd-theme%2Fimg%2Fdefault-avatar.png&r=g\",\"caption\":\"Udelar\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Venta de entradas vs Juventud de Las Piedras (Torneo Intermedio 2019) - Padre y Decano - El Sitio del Pueblo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.padreydecano.com\/cms\/noticias\/venta-de-entradas-vs-juventud-de-las-piedras-torneo-intermedio-2019\/","og_locale":"es_ES","og_type":"article","og_title":"Venta de entradas vs Juventud de Las Piedras (Torneo Intermedio 2019) - Padre y Decano - El Sitio del Pueblo","og_description":"Ya est\u00e1 habilitado el canje y venta de entradas para el encuentro entre Pe\u00f1arol y Juventud de las Piedras, a jugarse el pr\u00f3ximo domingo a partir de las 18 horas, en el Estadio Campe\u00f3n del Siglo, por la quinta fecha del Torneo Intermedio 2019. Adquir\u00ed la tuya en los locales de Redpagos o a trav\u00e9s [&hellip;]","og_url":"https:\/\/www.padreydecano.com\/cms\/noticias\/venta-de-entradas-vs-juventud-de-las-piedras-torneo-intermedio-2019\/","og_site_name":"Padre y Decano - El Sitio del Pueblo","article_published_time":"2019-08-15T22:24:35+00:00","article_modified_time":"2019-08-15T22:27:28+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2019\/07\/ENTRADAS75.png","type":"image\/png"}],"author":"Udelar","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Udelar","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/venta-de-entradas-vs-juventud-de-las-piedras-torneo-intermedio-2019\/#article","isPartOf":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/venta-de-entradas-vs-juventud-de-las-piedras-torneo-intermedio-2019\/"},"author":{"name":"Udelar","@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/b22191326be6d1c7fa55c2ad137a9a32"},"headline":"Venta de entradas vs Juventud de Las Piedras (Torneo Intermedio 2019)","datePublished":"2019-08-15T22:24:35+00:00","dateModified":"2019-08-15T22:27:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/venta-de-entradas-vs-juventud-de-las-piedras-torneo-intermedio-2019\/"},"wordCount":320,"commentCount":8,"publisher":{"@id":"https:\/\/www.padreydecano.com\/cms\/#organization"},"image":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/venta-de-entradas-vs-juventud-de-las-piedras-torneo-intermedio-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2019\/07\/ENTRADAS75.png","keywords":["Torneo Intermedio 2019","Venta de entradas"],"articleSection":["Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.padreydecano.com\/cms\/noticias\/venta-de-entradas-vs-juventud-de-las-piedras-torneo-intermedio-2019\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/venta-de-entradas-vs-juventud-de-las-piedras-torneo-intermedio-2019\/","url":"https:\/\/www.padreydecano.com\/cms\/noticias\/venta-de-entradas-vs-juventud-de-las-piedras-torneo-intermedio-2019\/","name":"Venta de entradas vs Juventud de Las Piedras (Torneo Intermedio 2019) - Padre y Decano - El Sitio del Pueblo","isPartOf":{"@id":"https:\/\/www.padreydecano.com\/cms\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/venta-de-entradas-vs-juventud-de-las-piedras-torneo-intermedio-2019\/#primaryimage"},"image":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/venta-de-entradas-vs-juventud-de-las-piedras-torneo-intermedio-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2019\/07\/ENTRADAS75.png","datePublished":"2019-08-15T22:24:35+00:00","dateModified":"2019-08-15T22:27:28+00:00","breadcrumb":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/venta-de-entradas-vs-juventud-de-las-piedras-torneo-intermedio-2019\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.padreydecano.com\/cms\/noticias\/venta-de-entradas-vs-juventud-de-las-piedras-torneo-intermedio-2019\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/venta-de-entradas-vs-juventud-de-las-piedras-torneo-intermedio-2019\/#primaryimage","url":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2019\/07\/ENTRADAS75.png","contentUrl":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2019\/07\/ENTRADAS75.png","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/venta-de-entradas-vs-juventud-de-las-piedras-torneo-intermedio-2019\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.padreydecano.com\/cms\/"},{"@type":"ListItem","position":2,"name":"Venta de entradas vs Juventud de Las Piedras (Torneo Intermedio 2019)"}]},{"@type":"WebSite","@id":"https:\/\/www.padreydecano.com\/cms\/#website","url":"https:\/\/www.padreydecano.com\/cms\/","name":"Padre y Decano - El Sitio del Pueblo","description":"Club Atl\u00e9tico Pe\u00f1arol","publisher":{"@id":"https:\/\/www.padreydecano.com\/cms\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.padreydecano.com\/cms\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.padreydecano.com\/cms\/#organization","name":"Padre y Decano","url":"https:\/\/www.padreydecano.com\/cms\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/logo\/image\/","url":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2022\/01\/avatar-square.png","contentUrl":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2022\/01\/avatar-square.png","width":1500,"height":1500,"caption":"Padre y Decano"},"image":{"@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/b22191326be6d1c7fa55c2ad137a9a32","name":"Udelar","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/611ece663b16897a2cd2f46982281225?s=96&d=https%3A%2F%2Fpadreydecano.com%2Fcms%2Fwp-content%2Fthemes%2Fpyd-theme%2Fimg%2Fdefault-avatar.png&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/611ece663b16897a2cd2f46982281225?s=96&d=https%3A%2F%2Fpadreydecano.com%2Fcms%2Fwp-content%2Fthemes%2Fpyd-theme%2Fimg%2Fdefault-avatar.png&r=g","caption":"Udelar"}}]}},"_links":{"self":[{"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/posts\/71540"}],"collection":[{"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/comments?post=71540"}],"version-history":[{"count":0,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/posts\/71540\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/media\/71211"}],"wp:attachment":[{"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/media?parent=71540"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/categories?post=71540"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/tags?post=71540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}