{"id":64429,"date":"2017-09-12T21:19:51","date_gmt":"2017-09-13T00:19:51","guid":{"rendered":"http:\/\/www.padreydecano.com\/cms\/?p=64429"},"modified":"2017-09-12T21:19:51","modified_gmt":"2017-09-13T00:19:51","slug":"valls-queremos-un-evento-que-convoque-a-toda-la-familia","status":"publish","type":"post","link":"https:\/\/www.padreydecano.com\/cms\/otras-disciplinas\/valls-queremos-un-evento-que-convoque-a-toda-la-familia\/","title":{"rendered":"Valls: \u00abQueremos un evento que convoque a toda la familia\u00bb"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/09\/fernando-valls.jpg\" rel=\"shadowbox[sbpost-64429];player=img;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-54711\" src=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/09\/fernando-valls.jpg\" alt=\"\" width=\"260\" height=\"473\" srcset=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/09\/fernando-valls.jpg 528w, https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/09\/fernando-valls-165x300.jpg 165w\" sizes=\"(max-width: 260px) 100vw, 260px\" \/><\/a><strong>Padre y Decano habl\u00f3 mano a mano con Fernando Valls, Presidente de la Comisi\u00f3n de Atletismo del Club Atl\u00e9tico Pe\u00f1arol, de cara a la realizaci\u00f3n de la sexta edici\u00f3n de la 5k.<\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffcc00;\"><strong>\u00bfC\u00f3mo vienen las inscripciones para este a\u00f1o?<\/strong> <\/span><\/p>\n<p style=\"text-align: justify;\">\nPor suerte a\u00f1o a a\u00f1o mejoran y cada vez m\u00e1s el hincha de Pe\u00f1arol toma la 5K como el festejo de cumplea\u00f1os donde puede participar toda la familia. Adem\u00e1s, cuidando cada detalle hemos logrado un evento de gran calidad a nivel de carreras y nos hemos posicionado como una de las mejores del pa\u00eds. Para nosotros el objetivo es que Pe\u00f1arol debe tener el mejor evento en calidad y con ello lograr financiar las escuelas de atletismo para dejar un aporte de identidad al club.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffcc00;\"><strong>\u00bfHay alg\u00fan tipo de cambio con respecto a los a\u00f1os anteriores?<\/strong> <\/span><\/p>\n<p style=\"text-align: justify;\">\nSiempre estamos trabajando en mejoras, en cambios de dise\u00f1o que lleven a\u00f1o tras a\u00f1o a dejar un aporte en identidad y est\u00e9tica al club. Este a\u00f1o la remera ser\u00e1 negra con detalles en vinilo refractario y el concepto comunicacional en esta oportunidad ser\u00e1 <strong>\u201cILUMIN\u00c1\u201d<\/strong> con todo lo que eso significa; no solo visualmente sino como personas. <strong>ILUMIN\u00c1<\/strong> es dejar el alma, dar lo mejor de nosotros, compartir conocimientos, crear, respetar ser solidario, humilde, leal y honesto.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffcc00;\"><strong>Se agotaron las camisetas el primer d\u00eda, \u00bfno esperaban tanta convocatoria del p\u00fablico? <\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">Realmente nunca imaginamos tal \u00e9xito. El dise\u00f1o de la remera y su concepto gust\u00f3 mucho. A\u00f1o tras a\u00f1o como es una edici\u00f3n limitada; sucede esto y provoca m\u00e1s avidez por tener la remera 5k PE\u00d1AROL. Pero el evento se sigue ampliando y este a\u00f1o aumentamos cupos para que puedan participar m\u00e1s pe\u00f1arolenses de esta fiesta en 2 colores.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffcc00;\"><strong>\u00bfTienen pensado hacer una nueva partida?<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">Las remeras son importadas, por lo tanto su pedido y confecci\u00f3n demoran meses, es por eso que todos los a\u00f1os repetimos que son una edici\u00f3n limitada.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffcc00;\"><strong>\u00bfA d\u00f3nde se destina lo recaudado este a\u00f1o?<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">Lo recaudado por la 5K PE\u00d1AROL desde el primer a\u00f1o cumple el motivo solidario por el que fue creada y es el de financiar las escuelas de atletismo del club que funcionan en car\u00e1cter gratuito y en forma ininterrumpida.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffcc00;\"><strong>\u00bfQu\u00e9 se ha mejorado en el atletismo de Pe\u00f1arol con lo recaudado las carreras anteriores?<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">El atletismo en Pe\u00f1arol ha crecido en forma seria y sostenida, logrando actualmente tener a Pe\u00f1arol como el equipo m\u00e1s poderoso del atletismo uruguayo bicampe\u00f3n 2016 y 2017, due\u00f1o de varios r\u00e9cords uruguayos incluso logrando en alguna disciplina ubicarse 4to a nivel sudamericano y adem\u00e1s dando deporte de calidad a m\u00e1s de 100 chicos.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ffcc00;\"><strong>\u00bfHabr\u00e1 alg\u00fan otro espect\u00e1culo de forma paralela para el p\u00fablico que se acerque?<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">S\u00ed, habr\u00e1 espect\u00e1culos musicales para todos los que asistan que iremos anunciando en estos d\u00edas para que no sea solo una carrera sino que sea un evento que convoque a todos los miembros de la familia.<\/p>\n<p><a href=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/09\/5kPe\u00f1arol_015.jpg\" rel=\"shadowbox[sbpost-64429];player=img;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-54494\" src=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/09\/5kPe\u00f1arol_015.jpg\" alt=\"\" width=\"620\" height=\"413\" srcset=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/09\/5kPe\u00f1arol_015.jpg 800w, https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/09\/5kPe\u00f1arol_015-300x200.jpg 300w\" sizes=\"(max-width: 620px) 100vw, 620px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Padre y Decano habl\u00f3 mano a mano con Fernando Valls, Presidente de la Comisi\u00f3n de Atletismo del Club Atl\u00e9tico Pe\u00f1arol, de cara a la realizaci\u00f3n de la sexta edici\u00f3n de la 5k. \u00bfC\u00f3mo vienen las inscripciones para este a\u00f1o? Por suerte a\u00f1o a a\u00f1o mejoran y cada vez m\u00e1s el hincha de Pe\u00f1arol toma la [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":54713,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27],"tags":[37],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Valls: &quot;Queremos un evento que convoque a toda la familia&quot; - Padre y Decano - El Sitio del Pueblo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.padreydecano.com\/cms\/otras-disciplinas\/valls-queremos-un-evento-que-convoque-a-toda-la-familia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Valls: &quot;Queremos un evento que convoque a toda la familia&quot; - Padre y Decano - El Sitio del Pueblo\" \/>\n<meta property=\"og:description\" content=\"Padre y Decano habl\u00f3 mano a mano con Fernando Valls, Presidente de la Comisi\u00f3n de Atletismo del Club Atl\u00e9tico Pe\u00f1arol, de cara a la realizaci\u00f3n de la sexta edici\u00f3n de la 5k. \u00bfC\u00f3mo vienen las inscripciones para este a\u00f1o? Por suerte a\u00f1o a a\u00f1o mejoran y cada vez m\u00e1s el hincha de Pe\u00f1arol toma la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.padreydecano.com\/cms\/otras-disciplinas\/valls-queremos-un-evento-que-convoque-a-toda-la-familia\/\" \/>\n<meta property=\"og:site_name\" content=\"Padre y Decano - El Sitio del Pueblo\" \/>\n<meta property=\"article:published_time\" content=\"2017-09-13T00:19:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/09\/fernando-valls-chica.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"502\" \/>\n\t<meta property=\"og:image:height\" content=\"326\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"fishoapyd\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"fishoapyd\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/otras-disciplinas\/valls-queremos-un-evento-que-convoque-a-toda-la-familia\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/otras-disciplinas\/valls-queremos-un-evento-que-convoque-a-toda-la-familia\/\"},\"author\":{\"name\":\"fishoapyd\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/1376f1ec91158cca7aeef6d2109f929d\"},\"headline\":\"Valls: \u00abQueremos un evento que convoque a toda la familia\u00bb\",\"datePublished\":\"2017-09-13T00:19:51+00:00\",\"dateModified\":\"2017-09-13T00:19:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/otras-disciplinas\/valls-queremos-un-evento-que-convoque-a-toda-la-familia\/\"},\"wordCount\":540,\"commentCount\":8,\"publisher\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/otras-disciplinas\/valls-queremos-un-evento-que-convoque-a-toda-la-familia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/09\/fernando-valls-chica.jpg\",\"keywords\":[\"Atletismo\"],\"articleSection\":[\"Otras disciplinas\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.padreydecano.com\/cms\/otras-disciplinas\/valls-queremos-un-evento-que-convoque-a-toda-la-familia\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/otras-disciplinas\/valls-queremos-un-evento-que-convoque-a-toda-la-familia\/\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/otras-disciplinas\/valls-queremos-un-evento-que-convoque-a-toda-la-familia\/\",\"name\":\"Valls: \\\"Queremos un evento que convoque a toda la familia\\\" - Padre y Decano - El Sitio del Pueblo\",\"isPartOf\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/otras-disciplinas\/valls-queremos-un-evento-que-convoque-a-toda-la-familia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/otras-disciplinas\/valls-queremos-un-evento-que-convoque-a-toda-la-familia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/09\/fernando-valls-chica.jpg\",\"datePublished\":\"2017-09-13T00:19:51+00:00\",\"dateModified\":\"2017-09-13T00:19:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/otras-disciplinas\/valls-queremos-un-evento-que-convoque-a-toda-la-familia\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.padreydecano.com\/cms\/otras-disciplinas\/valls-queremos-un-evento-que-convoque-a-toda-la-familia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/otras-disciplinas\/valls-queremos-un-evento-que-convoque-a-toda-la-familia\/#primaryimage\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/09\/fernando-valls-chica.jpg\",\"contentUrl\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/09\/fernando-valls-chica.jpg\",\"width\":502,\"height\":326},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/otras-disciplinas\/valls-queremos-un-evento-que-convoque-a-toda-la-familia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.padreydecano.com\/cms\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Valls: \u00abQueremos un evento que convoque a toda la familia\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#website\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/\",\"name\":\"Padre y Decano - El Sitio del Pueblo\",\"description\":\"Club Atl\u00e9tico Pe\u00f1arol\",\"publisher\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.padreydecano.com\/cms\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#organization\",\"name\":\"Padre y Decano\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2022\/01\/avatar-square.png\",\"contentUrl\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2022\/01\/avatar-square.png\",\"width\":1500,\"height\":1500,\"caption\":\"Padre y Decano\"},\"image\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/1376f1ec91158cca7aeef6d2109f929d\",\"name\":\"fishoapyd\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2022\/12\/avatar-square-1.png\",\"contentUrl\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2022\/12\/avatar-square-1.png\",\"caption\":\"fishoapyd\"},\"sameAs\":[\"http:\/\/www.padreydecano.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Valls: \"Queremos un evento que convoque a toda la familia\" - Padre y Decano - El Sitio del Pueblo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.padreydecano.com\/cms\/otras-disciplinas\/valls-queremos-un-evento-que-convoque-a-toda-la-familia\/","og_locale":"es_ES","og_type":"article","og_title":"Valls: \"Queremos un evento que convoque a toda la familia\" - Padre y Decano - El Sitio del Pueblo","og_description":"Padre y Decano habl\u00f3 mano a mano con Fernando Valls, Presidente de la Comisi\u00f3n de Atletismo del Club Atl\u00e9tico Pe\u00f1arol, de cara a la realizaci\u00f3n de la sexta edici\u00f3n de la 5k. \u00bfC\u00f3mo vienen las inscripciones para este a\u00f1o? Por suerte a\u00f1o a a\u00f1o mejoran y cada vez m\u00e1s el hincha de Pe\u00f1arol toma la [&hellip;]","og_url":"https:\/\/www.padreydecano.com\/cms\/otras-disciplinas\/valls-queremos-un-evento-que-convoque-a-toda-la-familia\/","og_site_name":"Padre y Decano - El Sitio del Pueblo","article_published_time":"2017-09-13T00:19:51+00:00","og_image":[{"width":502,"height":326,"url":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/09\/fernando-valls-chica.jpg","type":"image\/jpeg"}],"author":"fishoapyd","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"fishoapyd","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.padreydecano.com\/cms\/otras-disciplinas\/valls-queremos-un-evento-que-convoque-a-toda-la-familia\/#article","isPartOf":{"@id":"https:\/\/www.padreydecano.com\/cms\/otras-disciplinas\/valls-queremos-un-evento-que-convoque-a-toda-la-familia\/"},"author":{"name":"fishoapyd","@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/1376f1ec91158cca7aeef6d2109f929d"},"headline":"Valls: \u00abQueremos un evento que convoque a toda la familia\u00bb","datePublished":"2017-09-13T00:19:51+00:00","dateModified":"2017-09-13T00:19:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.padreydecano.com\/cms\/otras-disciplinas\/valls-queremos-un-evento-que-convoque-a-toda-la-familia\/"},"wordCount":540,"commentCount":8,"publisher":{"@id":"https:\/\/www.padreydecano.com\/cms\/#organization"},"image":{"@id":"https:\/\/www.padreydecano.com\/cms\/otras-disciplinas\/valls-queremos-un-evento-que-convoque-a-toda-la-familia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/09\/fernando-valls-chica.jpg","keywords":["Atletismo"],"articleSection":["Otras disciplinas"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.padreydecano.com\/cms\/otras-disciplinas\/valls-queremos-un-evento-que-convoque-a-toda-la-familia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.padreydecano.com\/cms\/otras-disciplinas\/valls-queremos-un-evento-que-convoque-a-toda-la-familia\/","url":"https:\/\/www.padreydecano.com\/cms\/otras-disciplinas\/valls-queremos-un-evento-que-convoque-a-toda-la-familia\/","name":"Valls: \"Queremos un evento que convoque a toda la familia\" - Padre y Decano - El Sitio del Pueblo","isPartOf":{"@id":"https:\/\/www.padreydecano.com\/cms\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.padreydecano.com\/cms\/otras-disciplinas\/valls-queremos-un-evento-que-convoque-a-toda-la-familia\/#primaryimage"},"image":{"@id":"https:\/\/www.padreydecano.com\/cms\/otras-disciplinas\/valls-queremos-un-evento-que-convoque-a-toda-la-familia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/09\/fernando-valls-chica.jpg","datePublished":"2017-09-13T00:19:51+00:00","dateModified":"2017-09-13T00:19:51+00:00","breadcrumb":{"@id":"https:\/\/www.padreydecano.com\/cms\/otras-disciplinas\/valls-queremos-un-evento-que-convoque-a-toda-la-familia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.padreydecano.com\/cms\/otras-disciplinas\/valls-queremos-un-evento-que-convoque-a-toda-la-familia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.padreydecano.com\/cms\/otras-disciplinas\/valls-queremos-un-evento-que-convoque-a-toda-la-familia\/#primaryimage","url":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/09\/fernando-valls-chica.jpg","contentUrl":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/09\/fernando-valls-chica.jpg","width":502,"height":326},{"@type":"BreadcrumbList","@id":"https:\/\/www.padreydecano.com\/cms\/otras-disciplinas\/valls-queremos-un-evento-que-convoque-a-toda-la-familia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.padreydecano.com\/cms\/"},{"@type":"ListItem","position":2,"name":"Valls: \u00abQueremos un evento que convoque a toda la familia\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/www.padreydecano.com\/cms\/#website","url":"https:\/\/www.padreydecano.com\/cms\/","name":"Padre y Decano - El Sitio del Pueblo","description":"Club Atl\u00e9tico Pe\u00f1arol","publisher":{"@id":"https:\/\/www.padreydecano.com\/cms\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.padreydecano.com\/cms\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.padreydecano.com\/cms\/#organization","name":"Padre y Decano","url":"https:\/\/www.padreydecano.com\/cms\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/logo\/image\/","url":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2022\/01\/avatar-square.png","contentUrl":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2022\/01\/avatar-square.png","width":1500,"height":1500,"caption":"Padre y Decano"},"image":{"@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/1376f1ec91158cca7aeef6d2109f929d","name":"fishoapyd","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/image\/","url":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2022\/12\/avatar-square-1.png","contentUrl":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2022\/12\/avatar-square-1.png","caption":"fishoapyd"},"sameAs":["http:\/\/www.padreydecano.com"]}]}},"_links":{"self":[{"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/posts\/64429"}],"collection":[{"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/comments?post=64429"}],"version-history":[{"count":0,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/posts\/64429\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/media\/54713"}],"wp:attachment":[{"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/media?parent=64429"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/categories?post=64429"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/tags?post=64429"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}