{"id":55003,"date":"2015-10-03T22:05:56","date_gmt":"2015-10-04T01:05:56","guid":{"rendered":"http:\/\/www.padreydecano.com\/cms\/?p=55003"},"modified":"2015-10-03T22:05:56","modified_gmt":"2015-10-04T01:05:56","slug":"compacto-danubio-0-penarol-1","status":"publish","type":"post","link":"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-danubio-0-penarol-1\/","title":{"rendered":"Compacto: Danubio 0 Pe\u00f1arol 1"},"content":{"rendered":"<p>Compacto del partido de la <a href=\"\/cms\/partidos\/un-desahogo\/\"><strong>victoria de Pe\u00f1aro<\/strong>l<\/a> en Jardines por 1 a 0 ante Danubio.<\/p>\n<div align=\"center\">\n<table class=\"video\">\n<tbody>\n<tr>\n<td><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/z4XerToXcVY?wmode=transparent\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Compacto del partido de la victoria de Pe\u00f1arol en Jardines por 1 a 0 ante Danubio.<\/p>\n","protected":false},"author":16,"featured_media":55006,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[254],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Compacto: Danubio 0 Pe\u00f1arol 1 - Padre y Decano - El Sitio del Pueblo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-danubio-0-penarol-1\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Compacto: Danubio 0 Pe\u00f1arol 1 - Padre y Decano - El Sitio del Pueblo\" \/>\n<meta property=\"og:description\" content=\"Compacto del partido de la victoria de Pe\u00f1arol en Jardines por 1 a 0 ante Danubio.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-danubio-0-penarol-1\/\" \/>\n<meta property=\"og:site_name\" content=\"Padre y Decano - El Sitio del Pueblo\" \/>\n<meta property=\"article:published_time\" content=\"2015-10-04T01:05:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/10\/DanubioVsPe\u00f1arol-100-Copiar-Copiar.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mariano\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mariano\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-danubio-0-penarol-1\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-danubio-0-penarol-1\/\"},\"author\":{\"name\":\"mariano\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/da0f0e72c91242bc7c270c61c9798d01\"},\"headline\":\"Compacto: Danubio 0 Pe\u00f1arol 1\",\"datePublished\":\"2015-10-04T01:05:56+00:00\",\"dateModified\":\"2015-10-04T01:05:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-danubio-0-penarol-1\/\"},\"wordCount\":19,\"commentCount\":4,\"publisher\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-danubio-0-penarol-1\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/10\/DanubioVsPe\u00f1arol-100-Copiar-Copiar.jpg\",\"keywords\":[\"Compactos Apertura 2015\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-danubio-0-penarol-1\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-danubio-0-penarol-1\/\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-danubio-0-penarol-1\/\",\"name\":\"Compacto: Danubio 0 Pe\u00f1arol 1 - Padre y Decano - El Sitio del Pueblo\",\"isPartOf\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-danubio-0-penarol-1\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-danubio-0-penarol-1\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/10\/DanubioVsPe\u00f1arol-100-Copiar-Copiar.jpg\",\"datePublished\":\"2015-10-04T01:05:56+00:00\",\"dateModified\":\"2015-10-04T01:05:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-danubio-0-penarol-1\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-danubio-0-penarol-1\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-danubio-0-penarol-1\/#primaryimage\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/10\/DanubioVsPe\u00f1arol-100-Copiar-Copiar.jpg\",\"contentUrl\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/10\/DanubioVsPe\u00f1arol-100-Copiar-Copiar.jpg\",\"width\":900,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-danubio-0-penarol-1\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.padreydecano.com\/cms\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Compacto: Danubio 0 Pe\u00f1arol 1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#website\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/\",\"name\":\"Padre y Decano - El Sitio del Pueblo\",\"description\":\"Club Atl\u00e9tico Pe\u00f1arol\",\"publisher\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.padreydecano.com\/cms\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#organization\",\"name\":\"Padre y Decano\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2022\/01\/avatar-square.png\",\"contentUrl\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2022\/01\/avatar-square.png\",\"width\":1500,\"height\":1500,\"caption\":\"Padre y Decano\"},\"image\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/da0f0e72c91242bc7c270c61c9798d01\",\"name\":\"mariano\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/771335714915d00ec253a5e994c2f830?s=96&d=https%3A%2F%2Fpadreydecano.com%2Fcms%2Fwp-content%2Fthemes%2Fpyd-theme%2Fimg%2Fdefault-avatar.png&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/771335714915d00ec253a5e994c2f830?s=96&d=https%3A%2F%2Fpadreydecano.com%2Fcms%2Fwp-content%2Fthemes%2Fpyd-theme%2Fimg%2Fdefault-avatar.png&r=g\",\"caption\":\"mariano\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Compacto: Danubio 0 Pe\u00f1arol 1 - Padre y Decano - El Sitio del Pueblo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-danubio-0-penarol-1\/","og_locale":"es_ES","og_type":"article","og_title":"Compacto: Danubio 0 Pe\u00f1arol 1 - Padre y Decano - El Sitio del Pueblo","og_description":"Compacto del partido de la victoria de Pe\u00f1arol en Jardines por 1 a 0 ante Danubio.","og_url":"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-danubio-0-penarol-1\/","og_site_name":"Padre y Decano - El Sitio del Pueblo","article_published_time":"2015-10-04T01:05:56+00:00","og_image":[{"width":900,"height":600,"url":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/10\/DanubioVsPe\u00f1arol-100-Copiar-Copiar.jpg","type":"image\/jpeg"}],"author":"mariano","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"mariano"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-danubio-0-penarol-1\/#article","isPartOf":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-danubio-0-penarol-1\/"},"author":{"name":"mariano","@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/da0f0e72c91242bc7c270c61c9798d01"},"headline":"Compacto: Danubio 0 Pe\u00f1arol 1","datePublished":"2015-10-04T01:05:56+00:00","dateModified":"2015-10-04T01:05:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-danubio-0-penarol-1\/"},"wordCount":19,"commentCount":4,"publisher":{"@id":"https:\/\/www.padreydecano.com\/cms\/#organization"},"image":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-danubio-0-penarol-1\/#primaryimage"},"thumbnailUrl":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/10\/DanubioVsPe\u00f1arol-100-Copiar-Copiar.jpg","keywords":["Compactos Apertura 2015"],"articleSection":["Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-danubio-0-penarol-1\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-danubio-0-penarol-1\/","url":"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-danubio-0-penarol-1\/","name":"Compacto: Danubio 0 Pe\u00f1arol 1 - Padre y Decano - El Sitio del Pueblo","isPartOf":{"@id":"https:\/\/www.padreydecano.com\/cms\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-danubio-0-penarol-1\/#primaryimage"},"image":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-danubio-0-penarol-1\/#primaryimage"},"thumbnailUrl":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/10\/DanubioVsPe\u00f1arol-100-Copiar-Copiar.jpg","datePublished":"2015-10-04T01:05:56+00:00","dateModified":"2015-10-04T01:05:56+00:00","breadcrumb":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-danubio-0-penarol-1\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-danubio-0-penarol-1\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-danubio-0-penarol-1\/#primaryimage","url":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/10\/DanubioVsPe\u00f1arol-100-Copiar-Copiar.jpg","contentUrl":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/10\/DanubioVsPe\u00f1arol-100-Copiar-Copiar.jpg","width":900,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-danubio-0-penarol-1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.padreydecano.com\/cms\/"},{"@type":"ListItem","position":2,"name":"Compacto: Danubio 0 Pe\u00f1arol 1"}]},{"@type":"WebSite","@id":"https:\/\/www.padreydecano.com\/cms\/#website","url":"https:\/\/www.padreydecano.com\/cms\/","name":"Padre y Decano - El Sitio del Pueblo","description":"Club Atl\u00e9tico Pe\u00f1arol","publisher":{"@id":"https:\/\/www.padreydecano.com\/cms\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.padreydecano.com\/cms\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.padreydecano.com\/cms\/#organization","name":"Padre y Decano","url":"https:\/\/www.padreydecano.com\/cms\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/logo\/image\/","url":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2022\/01\/avatar-square.png","contentUrl":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2022\/01\/avatar-square.png","width":1500,"height":1500,"caption":"Padre y Decano"},"image":{"@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/da0f0e72c91242bc7c270c61c9798d01","name":"mariano","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/771335714915d00ec253a5e994c2f830?s=96&d=https%3A%2F%2Fpadreydecano.com%2Fcms%2Fwp-content%2Fthemes%2Fpyd-theme%2Fimg%2Fdefault-avatar.png&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/771335714915d00ec253a5e994c2f830?s=96&d=https%3A%2F%2Fpadreydecano.com%2Fcms%2Fwp-content%2Fthemes%2Fpyd-theme%2Fimg%2Fdefault-avatar.png&r=g","caption":"mariano"}}]}},"_links":{"self":[{"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/posts\/55003"}],"collection":[{"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/comments?post=55003"}],"version-history":[{"count":0,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/posts\/55003\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/media\/55006"}],"wp:attachment":[{"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/media?parent=55003"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/categories?post=55003"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/tags?post=55003"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}