{"id":54300,"date":"2015-08-18T10:46:17","date_gmt":"2015-08-18T13:46:17","guid":{"rendered":"http:\/\/www.padreydecano.com\/cms\/?p=54300"},"modified":"2015-08-18T10:46:17","modified_gmt":"2015-08-18T13:46:17","slug":"qepd-victor-hugo-berardi","status":"publish","type":"post","link":"https:\/\/www.padreydecano.com\/cms\/noticias\/qepd-victor-hugo-berardi\/","title":{"rendered":"QEPD V\u00edctor Hugo Berardi"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/08\/victor-hugo-berardi.jpg\" rel=\"shadowbox[sbpost-54300];player=img;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-54301\" src=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/08\/victor-hugo-berardi.jpg\" alt=\"victor-hugo-berardi\" width=\"603\" height=\"404\" srcset=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/08\/victor-hugo-berardi.jpg 720w, https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/08\/victor-hugo-berardi-300x201.jpg 300w\" sizes=\"(max-width: 603px) 100vw, 603px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">En las \u00faltimas horas falleci\u00f3 V\u00edctor Hugo Berardi, ex jugador y entrenador de basquetbol, formado en Atenas y de un ex\u00edtoso pasaje por el Club Atl\u00e9tico Pe\u00f1arol.<\/p>\n<p style=\"text-align: justify;\">Berardi fue el entrenador que obtuvo la conquista del Torneo Federal de 1982 derrotando en la final a Bohemios, la Liguilla venciendo en la final a Nacional y el Sudamericano de Clubes, certamen donde derrotamos a Obras\u00a0Sanitarias de Argentina. Adem\u00e1s, este equipo fue Tercero del Mundial de Clubes. Fue una campa\u00f1a excepcional, hist\u00f3rica.<\/p>\n<p style=\"text-align: justify;\">Adem\u00e1s obtuvo\u00a0dos Sudamericanos con la Selecci\u00f3n Uruguaya, en Montevideo 1995 y en Maracaibo 1997, y fue asistente t\u00e9cnico en los Juegos Ol\u00edmpicos de 1984.<\/p>\n<p style=\"text-align: justify;\">Nuestras condolencias para familiares y amigos. Se fue un grande.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En las \u00faltimas horas falleci\u00f3 V\u00edctor Hugo Berardi, ex jugador y entrenador de basquetbol, formado en Atenas y de un ex\u00edtoso pasaje por el Club Atl\u00e9tico Pe\u00f1arol. Berardi fue el entrenador que obtuvo la conquista del Torneo Federal de 1982 derrotando en la final a Bohemios, la Liguilla venciendo en la final a Nacional y [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>QEPD V\u00edctor Hugo Berardi - Padre y Decano - El Sitio del Pueblo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.padreydecano.com\/cms\/noticias\/qepd-victor-hugo-berardi\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"QEPD V\u00edctor Hugo Berardi - Padre y Decano - El Sitio del Pueblo\" \/>\n<meta property=\"og:description\" content=\"En las \u00faltimas horas falleci\u00f3 V\u00edctor Hugo Berardi, ex jugador y entrenador de basquetbol, formado en Atenas y de un ex\u00edtoso pasaje por el Club Atl\u00e9tico Pe\u00f1arol. Berardi fue el entrenador que obtuvo la conquista del Torneo Federal de 1982 derrotando en la final a Bohemios, la Liguilla venciendo en la final a Nacional y [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.padreydecano.com\/cms\/noticias\/qepd-victor-hugo-berardi\/\" \/>\n<meta property=\"og:site_name\" content=\"Padre y Decano - El Sitio del Pueblo\" \/>\n<meta property=\"article:published_time\" content=\"2015-08-18T13:46:17+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/08\/victor-hugo-berardi.jpg\" \/>\n<meta name=\"author\" content=\"Moderador\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Moderador\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/qepd-victor-hugo-berardi\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/qepd-victor-hugo-berardi\/\"},\"author\":{\"name\":\"Moderador\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/d93e9e537230ae052c194251d9a1def2\"},\"headline\":\"QEPD V\u00edctor Hugo Berardi\",\"datePublished\":\"2015-08-18T13:46:17+00:00\",\"dateModified\":\"2015-08-18T13:46:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/qepd-victor-hugo-berardi\/\"},\"wordCount\":129,\"commentCount\":14,\"publisher\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/qepd-victor-hugo-berardi\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/08\/victor-hugo-berardi.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.padreydecano.com\/cms\/noticias\/qepd-victor-hugo-berardi\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/qepd-victor-hugo-berardi\/\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/qepd-victor-hugo-berardi\/\",\"name\":\"QEPD V\u00edctor Hugo Berardi - Padre y Decano - El Sitio del Pueblo\",\"isPartOf\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/qepd-victor-hugo-berardi\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/qepd-victor-hugo-berardi\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/08\/victor-hugo-berardi.jpg\",\"datePublished\":\"2015-08-18T13:46:17+00:00\",\"dateModified\":\"2015-08-18T13:46:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/qepd-victor-hugo-berardi\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.padreydecano.com\/cms\/noticias\/qepd-victor-hugo-berardi\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/qepd-victor-hugo-berardi\/#primaryimage\",\"url\":\"http:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/08\/victor-hugo-berardi.jpg\",\"contentUrl\":\"http:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/08\/victor-hugo-berardi.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/qepd-victor-hugo-berardi\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.padreydecano.com\/cms\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"QEPD V\u00edctor Hugo Berardi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#website\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/\",\"name\":\"Padre y Decano - El Sitio del Pueblo\",\"description\":\"Club Atl\u00e9tico Pe\u00f1arol\",\"publisher\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.padreydecano.com\/cms\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#organization\",\"name\":\"Padre y Decano\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2022\/01\/avatar-square.png\",\"contentUrl\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2022\/01\/avatar-square.png\",\"width\":1500,\"height\":1500,\"caption\":\"Padre y Decano\"},\"image\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/d93e9e537230ae052c194251d9a1def2\",\"name\":\"Moderador\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2587727bf8a53bd3da4ec49f01bea66e?s=96&d=https%3A%2F%2Fpadreydecano.com%2Fcms%2Fwp-content%2Fthemes%2Fpyd-theme%2Fimg%2Fdefault-avatar.png&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2587727bf8a53bd3da4ec49f01bea66e?s=96&d=https%3A%2F%2Fpadreydecano.com%2Fcms%2Fwp-content%2Fthemes%2Fpyd-theme%2Fimg%2Fdefault-avatar.png&r=g\",\"caption\":\"Moderador\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"QEPD V\u00edctor Hugo Berardi - Padre y Decano - El Sitio del Pueblo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.padreydecano.com\/cms\/noticias\/qepd-victor-hugo-berardi\/","og_locale":"es_ES","og_type":"article","og_title":"QEPD V\u00edctor Hugo Berardi - Padre y Decano - El Sitio del Pueblo","og_description":"En las \u00faltimas horas falleci\u00f3 V\u00edctor Hugo Berardi, ex jugador y entrenador de basquetbol, formado en Atenas y de un ex\u00edtoso pasaje por el Club Atl\u00e9tico Pe\u00f1arol. Berardi fue el entrenador que obtuvo la conquista del Torneo Federal de 1982 derrotando en la final a Bohemios, la Liguilla venciendo en la final a Nacional y [&hellip;]","og_url":"https:\/\/www.padreydecano.com\/cms\/noticias\/qepd-victor-hugo-berardi\/","og_site_name":"Padre y Decano - El Sitio del Pueblo","article_published_time":"2015-08-18T13:46:17+00:00","og_image":[{"url":"http:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/08\/victor-hugo-berardi.jpg"}],"author":"Moderador","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Moderador","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/qepd-victor-hugo-berardi\/#article","isPartOf":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/qepd-victor-hugo-berardi\/"},"author":{"name":"Moderador","@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/d93e9e537230ae052c194251d9a1def2"},"headline":"QEPD V\u00edctor Hugo Berardi","datePublished":"2015-08-18T13:46:17+00:00","dateModified":"2015-08-18T13:46:17+00:00","mainEntityOfPage":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/qepd-victor-hugo-berardi\/"},"wordCount":129,"commentCount":14,"publisher":{"@id":"https:\/\/www.padreydecano.com\/cms\/#organization"},"image":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/qepd-victor-hugo-berardi\/#primaryimage"},"thumbnailUrl":"http:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/08\/victor-hugo-berardi.jpg","articleSection":["Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.padreydecano.com\/cms\/noticias\/qepd-victor-hugo-berardi\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/qepd-victor-hugo-berardi\/","url":"https:\/\/www.padreydecano.com\/cms\/noticias\/qepd-victor-hugo-berardi\/","name":"QEPD V\u00edctor Hugo Berardi - Padre y Decano - El Sitio del Pueblo","isPartOf":{"@id":"https:\/\/www.padreydecano.com\/cms\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/qepd-victor-hugo-berardi\/#primaryimage"},"image":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/qepd-victor-hugo-berardi\/#primaryimage"},"thumbnailUrl":"http:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/08\/victor-hugo-berardi.jpg","datePublished":"2015-08-18T13:46:17+00:00","dateModified":"2015-08-18T13:46:17+00:00","breadcrumb":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/qepd-victor-hugo-berardi\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.padreydecano.com\/cms\/noticias\/qepd-victor-hugo-berardi\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/qepd-victor-hugo-berardi\/#primaryimage","url":"http:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/08\/victor-hugo-berardi.jpg","contentUrl":"http:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/08\/victor-hugo-berardi.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/qepd-victor-hugo-berardi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.padreydecano.com\/cms\/"},{"@type":"ListItem","position":2,"name":"QEPD V\u00edctor Hugo Berardi"}]},{"@type":"WebSite","@id":"https:\/\/www.padreydecano.com\/cms\/#website","url":"https:\/\/www.padreydecano.com\/cms\/","name":"Padre y Decano - El Sitio del Pueblo","description":"Club Atl\u00e9tico Pe\u00f1arol","publisher":{"@id":"https:\/\/www.padreydecano.com\/cms\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.padreydecano.com\/cms\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.padreydecano.com\/cms\/#organization","name":"Padre y Decano","url":"https:\/\/www.padreydecano.com\/cms\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/logo\/image\/","url":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2022\/01\/avatar-square.png","contentUrl":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2022\/01\/avatar-square.png","width":1500,"height":1500,"caption":"Padre y Decano"},"image":{"@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/d93e9e537230ae052c194251d9a1def2","name":"Moderador","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/2587727bf8a53bd3da4ec49f01bea66e?s=96&d=https%3A%2F%2Fpadreydecano.com%2Fcms%2Fwp-content%2Fthemes%2Fpyd-theme%2Fimg%2Fdefault-avatar.png&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2587727bf8a53bd3da4ec49f01bea66e?s=96&d=https%3A%2F%2Fpadreydecano.com%2Fcms%2Fwp-content%2Fthemes%2Fpyd-theme%2Fimg%2Fdefault-avatar.png&r=g","caption":"Moderador"}}]}},"_links":{"self":[{"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/posts\/54300"}],"collection":[{"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/comments?post=54300"}],"version-history":[{"count":0,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/posts\/54300\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/media?parent=54300"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/categories?post=54300"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/tags?post=54300"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}