{"id":53330,"date":"2015-06-26T15:48:03","date_gmt":"2015-06-26T18:48:03","guid":{"rendered":"http:\/\/www.padreydecano.com\/cms\/?p=53330"},"modified":"2015-06-30T09:37:10","modified_gmt":"2015-06-30T12:37:10","slug":"pacheco-una-vida-en-penarol","status":"publish","type":"post","link":"https:\/\/www.padreydecano.com\/cms\/noticias\/pacheco-una-vida-en-penarol\/","title":{"rendered":"Pacheco, una vida en Pe\u00f1arol"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/06\/pacheco-goleador-final-2013.jpg\" rel=\"shadowbox[sbpost-53330];player=img;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-53340\" src=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/06\/pacheco-goleador-final-2013.jpg\" alt=\"pacheco-goleador-final-2013\" width=\"608\" height=\"404\" srcset=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/06\/pacheco-goleador-final-2013.jpg 800w, https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/06\/pacheco-goleador-final-2013-300x200.jpg 300w\" sizes=\"(max-width: 608px) 100vw, 608px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Antonio Pacheco no volver\u00e1 a vestir la camiseta de Pe\u00f1arol. La Comisi\u00f3n Directiva de la entidad decana decidi\u00f3 en forma un\u00e1nime que al futbolista con m\u00e1s cl\u00e1sicos ganados en la historia\u00a0no se le renueve contrato en\u00a0la instituci\u00f3n que lo vio nacer.<a href=\"http:\/\/padreydecano.com\/\" target=\"_blank\">\u00a0Padreydecano.com<\/a>\u00a0repasa n\u00fameros y datos del \u00eddolo aurinegro.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2011\/11\/minitony.jpg\" rel=\"shadowbox[sbpost-53330];player=img;\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-8211 alignleft\" src=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2011\/11\/minitony.jpg\" alt=\"minitony\" width=\"207\" height=\"126\" \/><\/a>Pese a la pol\u00e9mica por la forma en que se le comunic\u00f3 a Tony que deb\u00eda irse del club carbonero, lleg\u00f3 el fin de una era. El jugador lleg\u00f3 al club en la d\u00e9cada del 80, hizo todas las divisiones formativas y fue ascendido al plantel principal por Gregorio P\u00e9rez.<\/p>\n<p style=\"text-align: justify;\">Debut\u00f3 el 11 de agosto de 1993 por la Copa Conmebol ante Hurac\u00e1n de Parque Patricios. Fue triunfo 1 a 0 con gol de Gustavo Ferreyra. El \u00abjugador de dibujitos animados\u00bb, ingres\u00f3 a los 41 minutos del segundo tiempo por Andree Gonz\u00e1lez.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/06\/pacheco-quinquenio.jpg\" rel=\"shadowbox[sbpost-53330];player=img;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-53337\" src=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/06\/pacheco-quinquenio-300x183.jpg\" alt=\"pacheco-quinquenio\" width=\"300\" height=\"183\" srcset=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/06\/pacheco-quinquenio-300x183.jpg 300w, https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/06\/pacheco-quinquenio.jpg 914w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>As\u00ed se inici\u00f3 la carrera del futbolista que gan\u00f3 m\u00e1s cl\u00e1sicos desde 1900 a la fecha. Disput\u00f3 algunos amistosos e incluso realiz\u00f3 una gira por Jap\u00f3n. Debut\u00f3 en el Campeonato Uruguayo el 30 de abril de 1994 ante Liverpool por el Torneo Apertura.<\/p>\n<p style=\"text-align: justify;\">Anot\u00f3 su primer gol el 3 de julio en la goleada ante Basa\u00f1ez 5 a 0. Logr\u00f3 el t\u00edtulo del Torneo Clausura y el Uruguayo de ese a\u00f1o. En ausencia de Pablo Bengoechea, visti\u00f3 la camiseta n\u00famero 10 en la final del Apertura ante Liverpool en 1995, convirti\u00f3 un gol y dio la vuelta ol\u00edmpica.<\/p>\n<p style=\"text-align: justify;\">En el Apertura 1996 anot\u00f3 su primer gol cl\u00e1sico en Primera Divisi\u00f3n, donde se registr\u00f3 triunfo 2 a 0. Y por segundo a\u00f1o consecutivo dio la vuelta ol\u00edmpica ante el tradicional rival, haciendo el gol decisivo en la final.<\/p>\n<p style=\"text-align: justify;\">Logr\u00f3 el <a href=\"https:\/\/www.padreydecano.com\/cms\/campanas-historicas\/el-segundo-quinquenio-de-oro\/\" target=\"_blank\">Quinquenio en 1997<\/a>, otra vez venciendo a los tricolores (seis veces en el a\u00f1o), convirtiendo goles cl\u00e1sicos y tambi\u00e9n en las finales ante Defensor Sporting.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/06\/pacheco-defensor-quinquenio-1997.jpg\" rel=\"shadowbox[sbpost-53330];player=img;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-53335\" src=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/06\/pacheco-defensor-quinquenio-1997.jpg\" alt=\"pacheco-defensor-quinquenio-1997\" width=\"608\" height=\"371\" srcset=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/06\/pacheco-defensor-quinquenio-1997.jpg 914w, https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/06\/pacheco-defensor-quinquenio-1997-300x183.jpg 300w\" sizes=\"(max-width: 608px) 100vw, 608px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Luego de no obtener el certamen de 1998, lleg\u00f3 la revancha en 1999.\u00a0De la mano de Julio Ribas, <a href=\"https:\/\/www.padreydecano.com\/cms\/campanas-historicas\/la-campana-de-1999\/\" target=\"_blank\">la m\u00e1quina del 4&#215;4<\/a> obtuvo el Clausura con Tony como goleador. En las finales, otra vez Nacional, vio como el Decano daba la vuelta ol\u00edmpica.<\/p>\n<p style=\"text-align: justify;\">Se fue en el 2000 buscando un mejor porvenir para su familia, pero siempre so\u00f1ando con volver a su casa. Tuvo un breve pasaje por Pe\u00f1arol en 2003 y pese a sus 11 goles, el manya no gan\u00f3 el Apertura.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/06\/pacheco-2008.jpg\" rel=\"shadowbox[sbpost-53330];player=img;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-53338\" src=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/06\/pacheco-2008-300x183.jpg\" alt=\"pacheco-2008\" width=\"300\" height=\"183\" srcset=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/06\/pacheco-2008-300x183.jpg 300w, https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/06\/pacheco-2008.jpg 914w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Luego de eso los aurinegros vivieron una de sus peores crisis deportivas donde los t\u00edtulos no llegaban. En 2007, Pacheco retorn\u00f3 al club que lo vio nacer. El primer campeonato del a\u00f1o fue malo, pero los albos volvieron ver la red del arco perforada por Tony.<\/p>\n<p style=\"text-align: justify;\">En el Clausura lleg\u00f3 Mario Saralegui, y el equipo mejor\u00f3. Pacheco l\u00edder y capit\u00e1n, marc\u00f3 el camino en el cl\u00e1sico con un gol de tiro libre. La final del torneo fue ante River Plate, Pe\u00f1arol ca\u00eda 1 a 3, pero el 8 apareci\u00f3, hizo un gol y el partido termin\u00f3 5 a 3.\u00a0No se pudo ganar el Uruguayo, tampoco en la temporada siguiente, pese a que Tony sigui\u00f3 haciendo goles cl\u00e1sicos y fue el goleador del certamen.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2011\/06\/5144667973_05b1b15334_o.jpg\" rel=\"shadowbox[sbpost-53330];player=img;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-4563\" src=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2011\/06\/5144667973_05b1b15334_o-300x199.jpg\" alt=\"Paternidad Cl\u00e1sica\" width=\"300\" height=\"199\" srcset=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2011\/06\/5144667973_05b1b15334_o-300x199.jpg 300w, https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2011\/06\/5144667973_05b1b15334_o.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Luego del mal Apertura 2009, lleg\u00f3 Diego Aguirre a la conducci\u00f3n t\u00e9cnica del club Decano.\u00a0El Clausura 2010 fue brillante, Pe\u00f1arol lo gan\u00f3 invicto y Pacheco volvi\u00f3 s ser el goleador del Uruguayo.<\/p>\n<p style=\"text-align: justify;\">Las finales eran ante el viejo antagonista, el capit\u00e1n estaba lesionado, pero decidi\u00f3 jugar lastimado, antes de abandonar a su club.\u00a0El 15 de mayo de 2010, cuando el partido estaba complicado, apareci\u00f3 el 8. Cabezazo contra el poste y los carboneros volv\u00edan a ganar un cl\u00e1sico. Tres d\u00edas despu\u00e9s un empate le daba la gloria y la Copa a Pe\u00f1arol.<\/p>\n<p style=\"text-align: justify;\">En 2011 despu\u00e9s de muchos a\u00f1os los aurinegros llegaron a una final de la Copa Libertadores de Am\u00e9rica. Aguirre releg\u00f3 a Pacheco al banco. Pero en la final cuando no apareci\u00f3 el f\u00fatbol, apel\u00f3 al capit\u00e1n, que en pocos minutos fue el mejor de Pe\u00f1arol.<\/p>\n<p style=\"text-align: justify;\">En la segunda final Pacheco no jug\u00f3, y el mirasol perdi\u00f3. Para la segunda parte del a\u00f1o Aguirre decidi\u00f3 no contar con Tony y el jugador debi\u00f3 irse a Wanderers. So\u00f1ando con volver, la Fiera se fue al cuarto partido del torneo y los aurinegros sufrieron en toda la temporada.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2012\/08\/tony-quebrado-conmarca.jpg\" rel=\"shadowbox[sbpost-53330];player=img;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-29227\" src=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2012\/08\/tony-quebrado-conmarca-225x300.jpg\" alt=\"tony-quebrado-conmarca\" width=\"203\" height=\"271\" srcset=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2012\/08\/tony-quebrado-conmarca-225x300.jpg 225w, https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2012\/08\/tony-quebrado-conmarca.jpg 450w\" sizes=\"(max-width: 203px) 100vw, 203px\" \/><\/a>La gente lo pidi\u00f3 y <a href=\"https:\/\/www.padreydecano.com\/cms\/los-aromos\/fotos-reencuentro-del-tony-con-la-gente\/\" target=\"_blank\">Pacheco volvi\u00f3<\/a>, la pretemporada fue un \u00e9xito, y al jugador se lo ve\u00eda como en sus mejores tiempos. El 26 de agosto de 2012, Tony volvi\u00f3 a pisar el verde c\u00e9sped con la casaca aurinegra. El 8 convirti\u00f3 un gol y era todo fiesta, hasta que el paname\u00f1o Eric Davis <a href=\"https:\/\/www.padreydecano.com\/cms\/partidos\/peor-arranque-imposible\/\" target=\"_blank\">fractur\u00f3 al capit\u00e1n<\/a>.<\/p>\n<p style=\"text-align: justify;\">Quienes concurrieron al Estadio Centenario no olvidar\u00e1n esa tarde. Fractura de tibia y peron\u00e9. Muchos dijeron que no volver\u00eda a pisar una cancha de f\u00fatbol, se equivocaron. Los hinchas de Pe\u00f1arol, y el mundo futbolero apoyaron al profesional, que retorn\u00f3 para el Clausura 2013.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2013\/05\/pe\u00f1arol-nacional-clausura-2013-036.jpg\" rel=\"shadowbox[sbpost-53330];player=img;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-38480\" src=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2013\/05\/pe\u00f1arol-nacional-clausura-2013-036-300x199.jpg\" alt=\"Fotos vs Hijos (Clausura 2013)\" width=\"300\" height=\"199\" srcset=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2013\/05\/pe\u00f1arol-nacional-clausura-2013-036-300x199.jpg 300w, https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2013\/05\/pe\u00f1arol-nacional-clausura-2013-036.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>En el primer juego como titular ante Cerro Largo, Pacheco volvi\u00f3 a convertir. Se lleg\u00f3 a la fecha del cl\u00e1sico con el entrenador Jorge Da Silva cuestionado y un equipo sin brillo. A \u00faltimo momento se decidi\u00f3 que Tony fuera titular, demor\u00f3 4 minutos en darle la raz\u00f3n al Polilla, el 8 abri\u00f3 el score y los mirasoles derrotaron a los bolsos por 3 a 0.<\/p>\n<p style=\"text-align: justify;\">El 4 de junio se disputaba la gran final ante Defensor Sporting. En una noche m\u00e1gica, <a href=\"https:\/\/www.padreydecano.com\/cms\/noticias\/pacheco-canto-las-49\/\" target=\"_blank\">Pacheco anot\u00f3 3 goles <\/a>y levant\u00f3 otra Copa Uruguaya. Las \u00faltimas temporadas no fueron de lo mejor para el capit\u00e1n y tampoco para los carboneros. De todas formas el referente fue el segundo m\u00e1ximo anotador del periodo.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/06\/3-goles-pacheco-defensor-2013.jpg\" rel=\"shadowbox[sbpost-53330];player=img;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-53336\" src=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/06\/3-goles-pacheco-defensor-2013.jpg\" alt=\"3-goles-pacheco-defensor-2013\" width=\"608\" height=\"404\" srcset=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/06\/3-goles-pacheco-defensor-2013.jpg 800w, https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/06\/3-goles-pacheco-defensor-2013-300x200.jpg 300w\" sizes=\"(max-width: 608px) 100vw, 608px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Particip\u00f3 en la <a href=\"https:\/\/www.padreydecano.com\/cms\/partidos\/5-de-oro-y-carbon\/\" target=\"_blank\">hist\u00f3rica goleada del 27 de abril de 2014<\/a>, esa tarde cl\u00e1sica los aurinegros golearon 5 a 0 a Nacional. Hace pocos d\u00edas Pacheco obtuvo el <a href=\"https:\/\/www.padreydecano.com\/cms\/partidos\/penarol-campeon-del-torneo-clausura-2015\/\" target=\"_blank\">Clausura 2015<\/a> con Pablo Bengoechea como entrenador. No se lleg\u00f3 al Uruguayo en un partido final con muchas cosas raras.<\/p>\n<p style=\"text-align: justify;\">Pero los dirigentes decidieron que Pacheco no siguiera m\u00e1s en el club que tanto honr\u00f3. Ya no se ver\u00e1 al \u00eddolo de la casaca n\u00famero 8, esa que usaron Juan Eduardo Hohberg, Pedro Virgilio Rocha, Mario Saralegui y tantos otros. Seguir\u00e1n llegando campeonatos, se ganar\u00e1n cl\u00e1sicos pero no ser\u00e1 lo mismo. Se va un grande entre los grandes, hasta siempre Tony.<\/p>\n<p><span style=\"color: #ffcc02;\"><strong>N\u00fameros y datos de la carrera de Antonio Pacheco:<\/strong><\/span><\/p>\n<ul>\n<li>Campeonatos oficiales: 19<\/li>\n<li>Copa Uruguaya: 1993, 94, 95, 96, 97, 99, 2003, 2009\/10, 2012\/13<\/li>\n<li>Torneo Apertura: 1995, 96, 2012<\/li>\n<li>Torneo Clausura: 1994, 19999, 2008, 2010, 2015<\/li>\n<li>Liguilla: 1994, 1997<\/li>\n<li>Jugador con m\u00e1s cl\u00e1sicos disputados en el profesionalismo: 60<\/li>\n<li>M\u00e1ximo ganador cl\u00e1sico en la historia de los cl\u00e1sicos: 28 y 12 goles<\/li>\n<li>Campe\u00f3n Uruguayo como socio honorario.<\/li>\n<li>Le convirti\u00f3 goles a Nacional en Baby f\u00fatbol, formativas y Primera Divisi\u00f3n.<\/li>\n<li>Venci\u00f3 a Nacional por el Uruguayo, Apertura, Clausura, finales del Uruguayo, Liguilla, Libertadores, Mercosur, Supercopa, y torneos amistosos.<\/li>\n<li>Convirti\u00f3 goles cl\u00e1sicos de penal, tiro libre, de cabeza, de derecha y de zurda.<\/li>\n<li>Siempre que anot\u00f3 en una final, Pe\u00f1arol fue campe\u00f3n.<\/li>\n<li>Logr\u00f3 8 goles en finales de car\u00e1cter oficial.<\/li>\n<li>Anot\u00f3 en 6 finales oficiales.<\/li>\n<li>Gan\u00f3 10 finales oficiales con Pe\u00f1arol<\/li>\n<li>Goleador del Torneo Clausura: 1999, 2010<\/li>\n<li>Goleador de la Copa Uruguaya en dos ocasiones consecutivas: 2008\/09, 2009\/10<\/li>\n<li>\u00danico jugador en la historia de Pe\u00f1arol en hacer 3 goles en una final del Campeonato Uruguayo: 4 de junio de 2013 ante Defensor<\/li>\n<li>M\u00e1ximo ganador en finales del Campeonato Uruguayo, (7): 1994, 95, 96, 97, 99, 2010 y 2013<\/li>\n<li>M\u00e1ximo goleador de las finales de la Copa Uruguaya: 6 goles<\/li>\n<li>M\u00e1ximo ganador de finales clasicas por el Campeonato Uruguayo, (4): 1995, 96, 99, 2010<\/li>\n<li>Ganador de la semifinal cl\u00e1sica de 1997<\/li>\n<li>Cuarto m\u00e1ximo goleador en la historia de la Copa Uruguaya: 141 goles<\/li>\n<li>Anot\u00f3 176 goles con la camiseta de Pe\u00f1arol<\/li>\n<li>Logr\u00f3 convertir 217 goles en su carrera<\/li>\n<li>Consigui\u00f3 21 dobletes, 3 tripletes y en una ocasi\u00f3n anot\u00f3 <a href=\"https:\/\/www.padreydecano.com\/cms\/el-baul-de-los-recuerdos\/los-5-goles-de-antonio-pacheco-a-river-plate\/\" target=\"_blank\">5 goles en un partido<\/a><\/li>\n<li>M\u00e1s de 500 partidos con la camiseta de Pe\u00f1arol<\/li>\n<li>Elegido el mejor jugador de los \u00faltimos 20 a\u00f1os por la encuesta del diario El Observador en 2014<\/li>\n<\/ul>\n<p style=\"text-align: right;\">Escrito por: <a href=\"http:\/\/twitter.com\/wilsonmendez86\" target=\"_blank\">Wilson M\u00e9ndez<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Padreydecano.com repasa n\u00fameros, curiosidades y datos del Tony.<\/p>\n","protected":false},"author":13,"featured_media":53337,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pacheco, una vida en Pe\u00f1arol - Padre y Decano - El Sitio del Pueblo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.padreydecano.com\/cms\/noticias\/pacheco-una-vida-en-penarol\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pacheco, una vida en Pe\u00f1arol - Padre y Decano - El Sitio del Pueblo\" \/>\n<meta property=\"og:description\" content=\"Padreydecano.com repasa n\u00fameros, curiosidades y datos del Tony.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.padreydecano.com\/cms\/noticias\/pacheco-una-vida-en-penarol\/\" \/>\n<meta property=\"og:site_name\" content=\"Padre y Decano - El Sitio del Pueblo\" \/>\n<meta property=\"article:published_time\" content=\"2015-06-26T18:48:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-06-30T12:37:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/06\/pacheco-quinquenio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"914\" \/>\n\t<meta property=\"og:image:height\" content=\"558\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Moderador\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Moderador\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/pacheco-una-vida-en-penarol\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/pacheco-una-vida-en-penarol\/\"},\"author\":{\"name\":\"Moderador\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/d93e9e537230ae052c194251d9a1def2\"},\"headline\":\"Pacheco, una vida en Pe\u00f1arol\",\"datePublished\":\"2015-06-26T18:48:03+00:00\",\"dateModified\":\"2015-06-30T12:37:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/pacheco-una-vida-en-penarol\/\"},\"wordCount\":1336,\"commentCount\":109,\"publisher\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/pacheco-una-vida-en-penarol\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/06\/pacheco-quinquenio.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.padreydecano.com\/cms\/noticias\/pacheco-una-vida-en-penarol\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/pacheco-una-vida-en-penarol\/\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/pacheco-una-vida-en-penarol\/\",\"name\":\"Pacheco, una vida en Pe\u00f1arol - Padre y Decano - El Sitio del Pueblo\",\"isPartOf\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/pacheco-una-vida-en-penarol\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/pacheco-una-vida-en-penarol\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/06\/pacheco-quinquenio.jpg\",\"datePublished\":\"2015-06-26T18:48:03+00:00\",\"dateModified\":\"2015-06-30T12:37:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/pacheco-una-vida-en-penarol\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.padreydecano.com\/cms\/noticias\/pacheco-una-vida-en-penarol\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/pacheco-una-vida-en-penarol\/#primaryimage\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/06\/pacheco-quinquenio.jpg\",\"contentUrl\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/06\/pacheco-quinquenio.jpg\",\"width\":914,\"height\":558},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/pacheco-una-vida-en-penarol\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.padreydecano.com\/cms\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pacheco, una vida en Pe\u00f1arol\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#website\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/\",\"name\":\"Padre y Decano - El Sitio del Pueblo\",\"description\":\"Club Atl\u00e9tico Pe\u00f1arol\",\"publisher\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.padreydecano.com\/cms\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#organization\",\"name\":\"Padre y Decano\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2022\/01\/avatar-square.png\",\"contentUrl\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2022\/01\/avatar-square.png\",\"width\":1500,\"height\":1500,\"caption\":\"Padre y Decano\"},\"image\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/d93e9e537230ae052c194251d9a1def2\",\"name\":\"Moderador\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2587727bf8a53bd3da4ec49f01bea66e?s=96&d=https%3A%2F%2Fpadreydecano.com%2Fcms%2Fwp-content%2Fthemes%2Fpyd-theme%2Fimg%2Fdefault-avatar.png&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2587727bf8a53bd3da4ec49f01bea66e?s=96&d=https%3A%2F%2Fpadreydecano.com%2Fcms%2Fwp-content%2Fthemes%2Fpyd-theme%2Fimg%2Fdefault-avatar.png&r=g\",\"caption\":\"Moderador\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pacheco, una vida en Pe\u00f1arol - Padre y Decano - El Sitio del Pueblo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.padreydecano.com\/cms\/noticias\/pacheco-una-vida-en-penarol\/","og_locale":"es_ES","og_type":"article","og_title":"Pacheco, una vida en Pe\u00f1arol - Padre y Decano - El Sitio del Pueblo","og_description":"Padreydecano.com repasa n\u00fameros, curiosidades y datos del Tony.","og_url":"https:\/\/www.padreydecano.com\/cms\/noticias\/pacheco-una-vida-en-penarol\/","og_site_name":"Padre y Decano - El Sitio del Pueblo","article_published_time":"2015-06-26T18:48:03+00:00","article_modified_time":"2015-06-30T12:37:10+00:00","og_image":[{"width":914,"height":558,"url":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/06\/pacheco-quinquenio.jpg","type":"image\/jpeg"}],"author":"Moderador","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Moderador","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/pacheco-una-vida-en-penarol\/#article","isPartOf":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/pacheco-una-vida-en-penarol\/"},"author":{"name":"Moderador","@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/d93e9e537230ae052c194251d9a1def2"},"headline":"Pacheco, una vida en Pe\u00f1arol","datePublished":"2015-06-26T18:48:03+00:00","dateModified":"2015-06-30T12:37:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/pacheco-una-vida-en-penarol\/"},"wordCount":1336,"commentCount":109,"publisher":{"@id":"https:\/\/www.padreydecano.com\/cms\/#organization"},"image":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/pacheco-una-vida-en-penarol\/#primaryimage"},"thumbnailUrl":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/06\/pacheco-quinquenio.jpg","articleSection":["Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.padreydecano.com\/cms\/noticias\/pacheco-una-vida-en-penarol\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/pacheco-una-vida-en-penarol\/","url":"https:\/\/www.padreydecano.com\/cms\/noticias\/pacheco-una-vida-en-penarol\/","name":"Pacheco, una vida en Pe\u00f1arol - Padre y Decano - El Sitio del Pueblo","isPartOf":{"@id":"https:\/\/www.padreydecano.com\/cms\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/pacheco-una-vida-en-penarol\/#primaryimage"},"image":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/pacheco-una-vida-en-penarol\/#primaryimage"},"thumbnailUrl":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/06\/pacheco-quinquenio.jpg","datePublished":"2015-06-26T18:48:03+00:00","dateModified":"2015-06-30T12:37:10+00:00","breadcrumb":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/pacheco-una-vida-en-penarol\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.padreydecano.com\/cms\/noticias\/pacheco-una-vida-en-penarol\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/pacheco-una-vida-en-penarol\/#primaryimage","url":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/06\/pacheco-quinquenio.jpg","contentUrl":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/06\/pacheco-quinquenio.jpg","width":914,"height":558},{"@type":"BreadcrumbList","@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/pacheco-una-vida-en-penarol\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.padreydecano.com\/cms\/"},{"@type":"ListItem","position":2,"name":"Pacheco, una vida en Pe\u00f1arol"}]},{"@type":"WebSite","@id":"https:\/\/www.padreydecano.com\/cms\/#website","url":"https:\/\/www.padreydecano.com\/cms\/","name":"Padre y Decano - El Sitio del Pueblo","description":"Club Atl\u00e9tico Pe\u00f1arol","publisher":{"@id":"https:\/\/www.padreydecano.com\/cms\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.padreydecano.com\/cms\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.padreydecano.com\/cms\/#organization","name":"Padre y Decano","url":"https:\/\/www.padreydecano.com\/cms\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/logo\/image\/","url":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2022\/01\/avatar-square.png","contentUrl":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2022\/01\/avatar-square.png","width":1500,"height":1500,"caption":"Padre y Decano"},"image":{"@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/d93e9e537230ae052c194251d9a1def2","name":"Moderador","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/2587727bf8a53bd3da4ec49f01bea66e?s=96&d=https%3A%2F%2Fpadreydecano.com%2Fcms%2Fwp-content%2Fthemes%2Fpyd-theme%2Fimg%2Fdefault-avatar.png&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2587727bf8a53bd3da4ec49f01bea66e?s=96&d=https%3A%2F%2Fpadreydecano.com%2Fcms%2Fwp-content%2Fthemes%2Fpyd-theme%2Fimg%2Fdefault-avatar.png&r=g","caption":"Moderador"}}]}},"_links":{"self":[{"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/posts\/53330"}],"collection":[{"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/comments?post=53330"}],"version-history":[{"count":0,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/posts\/53330\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/media\/53337"}],"wp:attachment":[{"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/media?parent=53330"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/categories?post=53330"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/tags?post=53330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}