{"id":52974,"date":"2015-06-01T09:49:40","date_gmt":"2015-06-01T12:49:40","guid":{"rendered":"http:\/\/www.padreydecano.com\/cms\/?p=52974"},"modified":"2015-06-01T09:51:40","modified_gmt":"2015-06-01T12:51:40","slug":"compacto-penarol-2-fenix-0","status":"publish","type":"post","link":"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-penarol-2-fenix-0\/","title":{"rendered":"Compacto: Pe\u00f1arol 2 F\u00e9nix 0"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"https:\/\/www.padreydecano.com\/cms\/partidos\/un-pasito-mas-cerca-del-primer-objetivo\/\" target=\"_blank\">Pe\u00f1arol venci\u00f3 2 a 0 a F\u00e9nix <\/a>con goles de Piriz y Aguiar y dio un paso m\u00e1s para el t\u00edtulo. Repas\u00e1 el compacto con los goles, los tiros en el palo, la <a href=\"https:\/\/www.padreydecano.com\/cms\/noticias\/piriz-y-diogo-no-juegan-ante-racing\/\" target=\"_blank\">expulsi\u00f3n de Diogo<\/a> y otras incidencias del partido.<\/p>\n<div align=\"center\">\n<table class=\"video\">\n<tbody>\n<tr>\n<td><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/H7WFjRJpdD0?wmode=transparent\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Pe\u00f1arol venci\u00f3 2 a 0 a F\u00e9nix con goles de Piriz y Aguiar y dio un paso m\u00e1s para el t\u00edtulo. Repas\u00e1 el compacto con los goles, los tiros en el palo, la expulsi\u00f3n de Diogo y otras incidencias del partido.<\/p>\n","protected":false},"author":13,"featured_media":52975,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[241],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Compacto: Pe\u00f1arol 2 F\u00e9nix 0 - Padre y Decano - El Sitio del Pueblo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-penarol-2-fenix-0\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Compacto: Pe\u00f1arol 2 F\u00e9nix 0 - Padre y Decano - El Sitio del Pueblo\" \/>\n<meta property=\"og:description\" content=\"Pe\u00f1arol venci\u00f3 2 a 0 a F\u00e9nix con goles de Piriz y Aguiar y dio un paso m\u00e1s para el t\u00edtulo. Repas\u00e1 el compacto con los goles, los tiros en el palo, la expulsi\u00f3n de Diogo y otras incidencias del partido.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-penarol-2-fenix-0\/\" \/>\n<meta property=\"og:site_name\" content=\"Padre y Decano - El Sitio del Pueblo\" \/>\n<meta property=\"article:published_time\" content=\"2015-06-01T12:49:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-06-01T12:51:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/06\/video-piriz.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"819\" \/>\n\t<meta property=\"og:image:height\" content=\"466\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Moderador\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Moderador\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-penarol-2-fenix-0\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-penarol-2-fenix-0\/\"},\"author\":{\"name\":\"Moderador\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/d93e9e537230ae052c194251d9a1def2\"},\"headline\":\"Compacto: Pe\u00f1arol 2 F\u00e9nix 0\",\"datePublished\":\"2015-06-01T12:49:40+00:00\",\"dateModified\":\"2015-06-01T12:51:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-penarol-2-fenix-0\/\"},\"wordCount\":49,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-penarol-2-fenix-0\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/06\/video-piriz.jpg\",\"keywords\":[\"Compactos Clausura 2015\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-penarol-2-fenix-0\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-penarol-2-fenix-0\/\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-penarol-2-fenix-0\/\",\"name\":\"Compacto: Pe\u00f1arol 2 F\u00e9nix 0 - Padre y Decano - El Sitio del Pueblo\",\"isPartOf\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-penarol-2-fenix-0\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-penarol-2-fenix-0\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/06\/video-piriz.jpg\",\"datePublished\":\"2015-06-01T12:49:40+00:00\",\"dateModified\":\"2015-06-01T12:51:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-penarol-2-fenix-0\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-penarol-2-fenix-0\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-penarol-2-fenix-0\/#primaryimage\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/06\/video-piriz.jpg\",\"contentUrl\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/06\/video-piriz.jpg\",\"width\":819,\"height\":466},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-penarol-2-fenix-0\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.padreydecano.com\/cms\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Compacto: Pe\u00f1arol 2 F\u00e9nix 0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#website\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/\",\"name\":\"Padre y Decano - El Sitio del Pueblo\",\"description\":\"Club Atl\u00e9tico Pe\u00f1arol\",\"publisher\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.padreydecano.com\/cms\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#organization\",\"name\":\"Padre y Decano\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2022\/01\/avatar-square.png\",\"contentUrl\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2022\/01\/avatar-square.png\",\"width\":1500,\"height\":1500,\"caption\":\"Padre y Decano\"},\"image\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/d93e9e537230ae052c194251d9a1def2\",\"name\":\"Moderador\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2587727bf8a53bd3da4ec49f01bea66e?s=96&d=https%3A%2F%2Fpadreydecano.com%2Fcms%2Fwp-content%2Fthemes%2Fpyd-theme%2Fimg%2Fdefault-avatar.png&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2587727bf8a53bd3da4ec49f01bea66e?s=96&d=https%3A%2F%2Fpadreydecano.com%2Fcms%2Fwp-content%2Fthemes%2Fpyd-theme%2Fimg%2Fdefault-avatar.png&r=g\",\"caption\":\"Moderador\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Compacto: Pe\u00f1arol 2 F\u00e9nix 0 - Padre y Decano - El Sitio del Pueblo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-penarol-2-fenix-0\/","og_locale":"es_ES","og_type":"article","og_title":"Compacto: Pe\u00f1arol 2 F\u00e9nix 0 - Padre y Decano - El Sitio del Pueblo","og_description":"Pe\u00f1arol venci\u00f3 2 a 0 a F\u00e9nix con goles de Piriz y Aguiar y dio un paso m\u00e1s para el t\u00edtulo. Repas\u00e1 el compacto con los goles, los tiros en el palo, la expulsi\u00f3n de Diogo y otras incidencias del partido.","og_url":"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-penarol-2-fenix-0\/","og_site_name":"Padre y Decano - El Sitio del Pueblo","article_published_time":"2015-06-01T12:49:40+00:00","article_modified_time":"2015-06-01T12:51:40+00:00","og_image":[{"width":819,"height":466,"url":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/06\/video-piriz.jpg","type":"image\/jpeg"}],"author":"Moderador","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Moderador"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-penarol-2-fenix-0\/#article","isPartOf":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-penarol-2-fenix-0\/"},"author":{"name":"Moderador","@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/d93e9e537230ae052c194251d9a1def2"},"headline":"Compacto: Pe\u00f1arol 2 F\u00e9nix 0","datePublished":"2015-06-01T12:49:40+00:00","dateModified":"2015-06-01T12:51:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-penarol-2-fenix-0\/"},"wordCount":49,"commentCount":0,"publisher":{"@id":"https:\/\/www.padreydecano.com\/cms\/#organization"},"image":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-penarol-2-fenix-0\/#primaryimage"},"thumbnailUrl":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/06\/video-piriz.jpg","keywords":["Compactos Clausura 2015"],"articleSection":["Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-penarol-2-fenix-0\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-penarol-2-fenix-0\/","url":"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-penarol-2-fenix-0\/","name":"Compacto: Pe\u00f1arol 2 F\u00e9nix 0 - Padre y Decano - El Sitio del Pueblo","isPartOf":{"@id":"https:\/\/www.padreydecano.com\/cms\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-penarol-2-fenix-0\/#primaryimage"},"image":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-penarol-2-fenix-0\/#primaryimage"},"thumbnailUrl":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/06\/video-piriz.jpg","datePublished":"2015-06-01T12:49:40+00:00","dateModified":"2015-06-01T12:51:40+00:00","breadcrumb":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-penarol-2-fenix-0\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-penarol-2-fenix-0\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-penarol-2-fenix-0\/#primaryimage","url":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/06\/video-piriz.jpg","contentUrl":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/06\/video-piriz.jpg","width":819,"height":466},{"@type":"BreadcrumbList","@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-penarol-2-fenix-0\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.padreydecano.com\/cms\/"},{"@type":"ListItem","position":2,"name":"Compacto: Pe\u00f1arol 2 F\u00e9nix 0"}]},{"@type":"WebSite","@id":"https:\/\/www.padreydecano.com\/cms\/#website","url":"https:\/\/www.padreydecano.com\/cms\/","name":"Padre y Decano - El Sitio del Pueblo","description":"Club Atl\u00e9tico Pe\u00f1arol","publisher":{"@id":"https:\/\/www.padreydecano.com\/cms\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.padreydecano.com\/cms\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.padreydecano.com\/cms\/#organization","name":"Padre y Decano","url":"https:\/\/www.padreydecano.com\/cms\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/logo\/image\/","url":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2022\/01\/avatar-square.png","contentUrl":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2022\/01\/avatar-square.png","width":1500,"height":1500,"caption":"Padre y Decano"},"image":{"@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/d93e9e537230ae052c194251d9a1def2","name":"Moderador","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/2587727bf8a53bd3da4ec49f01bea66e?s=96&d=https%3A%2F%2Fpadreydecano.com%2Fcms%2Fwp-content%2Fthemes%2Fpyd-theme%2Fimg%2Fdefault-avatar.png&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2587727bf8a53bd3da4ec49f01bea66e?s=96&d=https%3A%2F%2Fpadreydecano.com%2Fcms%2Fwp-content%2Fthemes%2Fpyd-theme%2Fimg%2Fdefault-avatar.png&r=g","caption":"Moderador"}}]}},"_links":{"self":[{"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/posts\/52974"}],"collection":[{"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/comments?post=52974"}],"version-history":[{"count":0,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/posts\/52974\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/media\/52975"}],"wp:attachment":[{"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/media?parent=52974"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/categories?post=52974"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/tags?post=52974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}