{"id":52888,"date":"2015-05-29T14:24:51","date_gmt":"2015-05-29T17:24:51","guid":{"rendered":"http:\/\/www.padreydecano.com\/cms\/?p=52888"},"modified":"2015-05-29T14:24:51","modified_gmt":"2015-05-29T17:24:51","slug":"pena-palermo-una-sorpresa-para-franco","status":"publish","type":"post","link":"https:\/\/www.padreydecano.com\/cms\/noticias\/pena-palermo-una-sorpresa-para-franco\/","title":{"rendered":"Pe\u00f1a Palermo: Una sorpresa para Franco"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/05\/Franco-je.jpg\" rel=\"shadowbox[sbpost-52888];player=img;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-52889 size-full\" src=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/05\/Franco-je-e1432904048259.jpg\" alt=\"Franco je\" width=\"600\" height=\"400\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">As\u00ed lo\u00a0cuenta\u00a0la Pe\u00f1a Palermo en su <a href=\"https:\/\/www.facebook.com\/barrio.palermo.1891?fref=ts\">p\u00e1gina de Facebook<\/a>:<\/p>\n<p style=\"text-align: justify;\"><em>\u00bbA principios de 2014, en el marco de la campa\u00f1a &#8216;Vuelta a Clases&#8217; impulsada por el Club, concurrimos a entregar una donaci\u00f3n de \u00fatiles escolares al centro &#8216;Color Esperanza&#8217;, un Caif al que asisten chicos con discapacidad.<\/em><\/p>\n<p style=\"text-align: justify;\"><em>Al llegar notamos, como pasa en todos lados, que la inmensa mayor\u00eda de los chicos eran hinchas de Pe\u00f1arol. Pero hab\u00eda uno que destacaba por sobre el resto. Vestido de pies a cabeza con ropa de Pe\u00f1arol, se nos acerc\u00f3 Franco, un chico con TGD (trastorno ge<span class=\"text_exposed_show\">neralizado del desarrollo) que utiliza un comunicador para comunicarse mejor. Compartimos una merienda, cant\u00f3 \u00bbdale Pe\u00f1arol\u00bb con el resto de sus amigos y se sac\u00f3 muchas fotos con los integrantes de la Pe\u00f1a, sus nuevos compa\u00f1eros de religi\u00f3n aurinegra.<\/span><\/em><\/p>\n<div class=\"text_exposed_show\">\n<p style=\"text-align: justify;\"><em>Pasado un a\u00f1o, la madre de Franco se comunic\u00f3 con la Pe\u00f1a para hacerle una sorpresa en su cumple y nos cont\u00f3 que todos los fines de semana los pasaba esperando el partido de Pe\u00f1arol.<\/em><\/p>\n<p style=\"text-align: justify;\"><em>As\u00ed que imposibilitados de poder llevar a algun jugador del plantel a festejar con el (el cumple era el mismo d\u00eda del clasico), le grabamos un video de los jugadores felicit\u00e1ndolo por su cumplea\u00f1os, adem\u00e1s de hacerlo socio del Club, regalarle la camiseta oficial y una pelota amarilla y negra.<\/em><\/p>\n<p style=\"text-align: justify;\"><em>La emoci\u00f3n y la alegr\u00eda de Franco al ver sus regalos carboneros fue impagable.<\/em><\/p>\n<p style=\"text-align: justify;\"><em>La Pe\u00f1a Palermo desea que hayas pasado un muy buen cumplea\u00f1os junto a tus amigos y te agradece por tu amor incondicional al Decano del F\u00fatbol Uruguayo y Campe\u00f3n del Siglo XX,.<\/em><\/p>\n<p style=\"text-align: justify;\"><em>Salud!<\/em><\/p>\n<p style=\"text-align: justify;\"><em>Pe\u00f1a Palermo \u00bbJuan Delgado\u00bb &#8211; Club Atl\u00e9tico Pe\u00f1arol\u00bb<\/em><\/p>\n<\/div>\n<div class=\"text_exposed_show\"><\/div>\n<div align=\"center\">\n<table class=\"video\">\n<tbody>\n<tr>\n<td><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/HElRtceGcMA?wmode=transparent\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<p>&nbsp;<\/p>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-52888 gallery-columns-3 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/05\/11297421_10206959771409075_382983327_o.jpg' rel='shadowbox[sbalbum-52888];player=img;'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/05\/11297421_10206959771409075_382983327_o-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/05\/11297421_10206959771409075_382983327_o-150x150.jpg 150w, https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/05\/11297421_10206959771409075_382983327_o-36x36.jpg 36w, https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/05\/11297421_10206959771409075_382983327_o-115x115.jpg 115w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/05\/11297552_10206959770569054_1023646485_o.jpg' rel='shadowbox[sbalbum-52888];player=img;'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/05\/11297552_10206959770569054_1023646485_o-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/05\/11297552_10206959770569054_1023646485_o-150x150.jpg 150w, https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/05\/11297552_10206959770569054_1023646485_o-36x36.jpg 36w, https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/05\/11297552_10206959770569054_1023646485_o-115x115.jpg 115w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/05\/11326861_10206959771049066_2014034664_o.jpg' rel='shadowbox[sbalbum-52888];player=img;'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/05\/11326861_10206959771049066_2014034664_o-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/05\/11326861_10206959771049066_2014034664_o-150x150.jpg 150w, https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/05\/11326861_10206959771049066_2014034664_o-36x36.jpg 36w, https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/05\/11326861_10206959771049066_2014034664_o-115x115.jpg 115w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/05\/11328195_10206959771129068_2130012874_o.jpg' rel='shadowbox[sbalbum-52888];player=img;'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/05\/11328195_10206959771129068_2130012874_o-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/05\/11328195_10206959771129068_2130012874_o-150x150.jpg 150w, https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/05\/11328195_10206959771129068_2130012874_o-36x36.jpg 36w, https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/05\/11328195_10206959771129068_2130012874_o-115x115.jpg 115w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/05\/11337242_10206959771329073_1319354539_o.jpg' rel='shadowbox[sbalbum-52888];player=img;'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/05\/11337242_10206959771329073_1319354539_o-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/05\/11337242_10206959771329073_1319354539_o-150x150.jpg 150w, https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/05\/11337242_10206959771329073_1319354539_o-36x36.jpg 36w, https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/05\/11337242_10206959771329073_1319354539_o-115x115.jpg 115w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/05\/11348868_10206959771369074_1037186666_o.jpg' rel='shadowbox[sbalbum-52888];player=img;'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/05\/11348868_10206959771369074_1037186666_o-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/05\/11348868_10206959771369074_1037186666_o-150x150.jpg 150w, https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/05\/11348868_10206959771369074_1037186666_o-36x36.jpg 36w, https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/05\/11348868_10206959771369074_1037186666_o-115x115.jpg 115w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>As\u00ed lo\u00a0cuenta\u00a0la Pe\u00f1a Palermo en su p\u00e1gina de Facebook: \u00bbA principios de 2014, en el marco de la campa\u00f1a &#8216;Vuelta a Clases&#8217; impulsada por el Club, concurrimos a entregar una donaci\u00f3n de \u00fatiles escolares al centro &#8216;Color Esperanza&#8217;, un Caif al que asisten chicos con discapacidad. Al llegar notamos, como pasa en todos lados, que [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pe\u00f1a Palermo: Una sorpresa para Franco - Padre y Decano - El Sitio del Pueblo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.padreydecano.com\/cms\/noticias\/pena-palermo-una-sorpresa-para-franco\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pe\u00f1a Palermo: Una sorpresa para Franco - Padre y Decano - El Sitio del Pueblo\" \/>\n<meta property=\"og:description\" content=\"As\u00ed lo\u00a0cuenta\u00a0la Pe\u00f1a Palermo en su p\u00e1gina de Facebook: \u00bbA principios de 2014, en el marco de la campa\u00f1a &#8216;Vuelta a Clases&#8217; impulsada por el Club, concurrimos a entregar una donaci\u00f3n de \u00fatiles escolares al centro &#8216;Color Esperanza&#8217;, un Caif al que asisten chicos con discapacidad. Al llegar notamos, como pasa en todos lados, que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.padreydecano.com\/cms\/noticias\/pena-palermo-una-sorpresa-para-franco\/\" \/>\n<meta property=\"og:site_name\" content=\"Padre y Decano - El Sitio del Pueblo\" \/>\n<meta property=\"article:published_time\" content=\"2015-05-29T17:24:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/05\/11297421_10206959771409075_382983327_o-150x150.jpg\" \/>\n<meta name=\"author\" content=\"1891\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"1891\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/pena-palermo-una-sorpresa-para-franco\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/pena-palermo-una-sorpresa-para-franco\/\"},\"author\":{\"name\":\"1891\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/5607c72c38a1537a151b24d1e67535e0\"},\"headline\":\"Pe\u00f1a Palermo: Una sorpresa para Franco\",\"datePublished\":\"2015-05-29T17:24:51+00:00\",\"dateModified\":\"2015-05-29T17:24:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/pena-palermo-una-sorpresa-para-franco\/\"},\"wordCount\":310,\"commentCount\":4,\"publisher\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/pena-palermo-una-sorpresa-para-franco\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/05\/Franco-je-e1432904048259.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.padreydecano.com\/cms\/noticias\/pena-palermo-una-sorpresa-para-franco\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/pena-palermo-una-sorpresa-para-franco\/\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/pena-palermo-una-sorpresa-para-franco\/\",\"name\":\"Pe\u00f1a Palermo: Una sorpresa para Franco - Padre y Decano - El Sitio del Pueblo\",\"isPartOf\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/pena-palermo-una-sorpresa-para-franco\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/pena-palermo-una-sorpresa-para-franco\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/05\/Franco-je-e1432904048259.jpg\",\"datePublished\":\"2015-05-29T17:24:51+00:00\",\"dateModified\":\"2015-05-29T17:24:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/pena-palermo-una-sorpresa-para-franco\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.padreydecano.com\/cms\/noticias\/pena-palermo-una-sorpresa-para-franco\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/pena-palermo-una-sorpresa-para-franco\/#primaryimage\",\"url\":\"http:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/05\/Franco-je-e1432904048259.jpg\",\"contentUrl\":\"http:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/05\/Franco-je-e1432904048259.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/pena-palermo-una-sorpresa-para-franco\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.padreydecano.com\/cms\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pe\u00f1a Palermo: Una sorpresa para Franco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#website\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/\",\"name\":\"Padre y Decano - El Sitio del Pueblo\",\"description\":\"Club Atl\u00e9tico Pe\u00f1arol\",\"publisher\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.padreydecano.com\/cms\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#organization\",\"name\":\"Padre y Decano\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2022\/01\/avatar-square.png\",\"contentUrl\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2022\/01\/avatar-square.png\",\"width\":1500,\"height\":1500,\"caption\":\"Padre y Decano\"},\"image\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/5607c72c38a1537a151b24d1e67535e0\",\"name\":\"1891\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/29d4d1b0d523a21898e8cf9585d259d3?s=96&d=https%3A%2F%2Fpadreydecano.com%2Fcms%2Fwp-content%2Fthemes%2Fpyd-theme%2Fimg%2Fdefault-avatar.png&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/29d4d1b0d523a21898e8cf9585d259d3?s=96&d=https%3A%2F%2Fpadreydecano.com%2Fcms%2Fwp-content%2Fthemes%2Fpyd-theme%2Fimg%2Fdefault-avatar.png&r=g\",\"caption\":\"1891\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pe\u00f1a Palermo: Una sorpresa para Franco - Padre y Decano - El Sitio del Pueblo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.padreydecano.com\/cms\/noticias\/pena-palermo-una-sorpresa-para-franco\/","og_locale":"es_ES","og_type":"article","og_title":"Pe\u00f1a Palermo: Una sorpresa para Franco - Padre y Decano - El Sitio del Pueblo","og_description":"As\u00ed lo\u00a0cuenta\u00a0la Pe\u00f1a Palermo en su p\u00e1gina de Facebook: \u00bbA principios de 2014, en el marco de la campa\u00f1a &#8216;Vuelta a Clases&#8217; impulsada por el Club, concurrimos a entregar una donaci\u00f3n de \u00fatiles escolares al centro &#8216;Color Esperanza&#8217;, un Caif al que asisten chicos con discapacidad. Al llegar notamos, como pasa en todos lados, que [&hellip;]","og_url":"https:\/\/www.padreydecano.com\/cms\/noticias\/pena-palermo-una-sorpresa-para-franco\/","og_site_name":"Padre y Decano - El Sitio del Pueblo","article_published_time":"2015-05-29T17:24:51+00:00","og_image":[{"url":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/05\/11297421_10206959771409075_382983327_o-150x150.jpg"}],"author":"1891","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"1891","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/pena-palermo-una-sorpresa-para-franco\/#article","isPartOf":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/pena-palermo-una-sorpresa-para-franco\/"},"author":{"name":"1891","@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/5607c72c38a1537a151b24d1e67535e0"},"headline":"Pe\u00f1a Palermo: Una sorpresa para Franco","datePublished":"2015-05-29T17:24:51+00:00","dateModified":"2015-05-29T17:24:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/pena-palermo-una-sorpresa-para-franco\/"},"wordCount":310,"commentCount":4,"publisher":{"@id":"https:\/\/www.padreydecano.com\/cms\/#organization"},"image":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/pena-palermo-una-sorpresa-para-franco\/#primaryimage"},"thumbnailUrl":"http:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/05\/Franco-je-e1432904048259.jpg","articleSection":["Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.padreydecano.com\/cms\/noticias\/pena-palermo-una-sorpresa-para-franco\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/pena-palermo-una-sorpresa-para-franco\/","url":"https:\/\/www.padreydecano.com\/cms\/noticias\/pena-palermo-una-sorpresa-para-franco\/","name":"Pe\u00f1a Palermo: Una sorpresa para Franco - Padre y Decano - El Sitio del Pueblo","isPartOf":{"@id":"https:\/\/www.padreydecano.com\/cms\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/pena-palermo-una-sorpresa-para-franco\/#primaryimage"},"image":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/pena-palermo-una-sorpresa-para-franco\/#primaryimage"},"thumbnailUrl":"http:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/05\/Franco-je-e1432904048259.jpg","datePublished":"2015-05-29T17:24:51+00:00","dateModified":"2015-05-29T17:24:51+00:00","breadcrumb":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/pena-palermo-una-sorpresa-para-franco\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.padreydecano.com\/cms\/noticias\/pena-palermo-una-sorpresa-para-franco\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/pena-palermo-una-sorpresa-para-franco\/#primaryimage","url":"http:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/05\/Franco-je-e1432904048259.jpg","contentUrl":"http:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/05\/Franco-je-e1432904048259.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/pena-palermo-una-sorpresa-para-franco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.padreydecano.com\/cms\/"},{"@type":"ListItem","position":2,"name":"Pe\u00f1a Palermo: Una sorpresa para Franco"}]},{"@type":"WebSite","@id":"https:\/\/www.padreydecano.com\/cms\/#website","url":"https:\/\/www.padreydecano.com\/cms\/","name":"Padre y Decano - El Sitio del Pueblo","description":"Club Atl\u00e9tico Pe\u00f1arol","publisher":{"@id":"https:\/\/www.padreydecano.com\/cms\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.padreydecano.com\/cms\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.padreydecano.com\/cms\/#organization","name":"Padre y Decano","url":"https:\/\/www.padreydecano.com\/cms\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/logo\/image\/","url":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2022\/01\/avatar-square.png","contentUrl":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2022\/01\/avatar-square.png","width":1500,"height":1500,"caption":"Padre y Decano"},"image":{"@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/5607c72c38a1537a151b24d1e67535e0","name":"1891","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/29d4d1b0d523a21898e8cf9585d259d3?s=96&d=https%3A%2F%2Fpadreydecano.com%2Fcms%2Fwp-content%2Fthemes%2Fpyd-theme%2Fimg%2Fdefault-avatar.png&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/29d4d1b0d523a21898e8cf9585d259d3?s=96&d=https%3A%2F%2Fpadreydecano.com%2Fcms%2Fwp-content%2Fthemes%2Fpyd-theme%2Fimg%2Fdefault-avatar.png&r=g","caption":"1891"}}]}},"_links":{"self":[{"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/posts\/52888"}],"collection":[{"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/comments?post=52888"}],"version-history":[{"count":0,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/posts\/52888\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/media?parent=52888"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/categories?post=52888"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/tags?post=52888"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}