{"id":52874,"date":"2015-05-28T19:43:09","date_gmt":"2015-05-28T22:43:09","guid":{"rendered":"http:\/\/www.padreydecano.com\/cms\/?p=52874"},"modified":"2015-05-28T19:43:09","modified_gmt":"2015-05-28T22:43:09","slug":"quisiera-ver-al-pajaro-en-primera","status":"publish","type":"post","link":"https:\/\/www.padreydecano.com\/cms\/noticias\/quisiera-ver-al-pajaro-en-primera\/","title":{"rendered":"Quisiera ver al P\u00e1jaro en Primera"},"content":{"rendered":"<p dir=\"ltr\" style=\"text-align: justify;\"><a href=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/05\/Valverde-EntrenamientoPe\u00f1arol28-5-37.jpg\" rel=\"shadowbox[sbpost-52874];player=img;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-52875\" src=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/05\/Valverde-EntrenamientoPe\u00f1arol28-5-37.jpg\" alt=\"Valverde-EntrenamientoPe\u00f1arol28-5 (37)\" width=\"608\" height=\"405\" srcset=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/05\/Valverde-EntrenamientoPe\u00f1arol28-5-37.jpg 900w, https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/05\/Valverde-EntrenamientoPe\u00f1arol28-5-37-300x200.jpg 300w\" sizes=\"(max-width: 608px) 100vw, 608px\" \/><\/a><\/p>\n<p dir=\"ltr\" style=\"text-align: justify;\"><strong>Federico Valverde demuestra su calidad en Los Aromos.<\/strong> Cada d\u00eda que pasa evoluciona un poco m\u00e1s. Lo notan sus compa\u00f1eros, cuerpo t\u00e9cnico y cualquiera que vea los entrenamientos del conjunto Decano; <strong>merece minutos con el plantel principal.<\/strong><\/p>\n<p dir=\"ltr\" style=\"text-align: justify;\"><a href=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/05\/Valverde-EntrenamientoPe\u00f1arol28-5-13.jpg\" rel=\"shadowbox[sbpost-52874];player=img;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-52876\" src=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/05\/Valverde-EntrenamientoPe\u00f1arol28-5-13-300x200.jpg\" alt=\"Valverde-EntrenamientoPe\u00f1arol28-5 (13)\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/05\/Valverde-EntrenamientoPe\u00f1arol28-5-13-300x200.jpg 300w, https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/05\/Valverde-EntrenamientoPe\u00f1arol28-5-13.jpg 900w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Habitualmente lo mejor es llevar a los juveniles de a poco, no cargarlos de presi\u00f3n. Para sobrellevar la responsabilidad del equipo est\u00e1n Antonio Pacheco, Marcelo Zalayeta y Luis Aguiar. Pero hay casos especiales, y \u00e9ste es uno de ellos.<\/p>\n<p dir=\"ltr\" style=\"text-align: justify;\"><strong>Lo del P\u00e1jaro ha sido ascendente desde el primer d\u00eda que pis\u00f3 el Complejo Washington Cataldi<\/strong>. Los que lo conocemos desde las formativas, sabemos de sus <strong>dotes de estratega y jugador completo;<\/strong> panorama, habilidad, pases al pie, excelente pegada y tranquilidad en los momentos m\u00e1s calientes de un partido.<\/p>\n<p dir=\"ltr\" style=\"text-align: justify;\">Pero verlo aplicar esas cualidades en las pr\u00e1cticas es otra cosa. El pibe es desfachatado, tira ca\u00f1os y lujos (siempre y cuando sea necesario), ante Antonio Pacheco o Dami\u00e1n Macaluso. No tiene problemas en ordenar a Marcel Novick y adem\u00e1s sabe escuchar a sus compa\u00f1eros y cuerpo t\u00e9cnico para mejorar.<\/p>\n<p dir=\"ltr\" style=\"text-align: justify;\"><a href=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/05\/Valverde-EntrenamientoPe\u00f1arol28-5-11.jpg\" rel=\"shadowbox[sbpost-52874];player=img;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-52877\" src=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/05\/Valverde-EntrenamientoPe\u00f1arol28-5-11-300x200.jpg\" alt=\"Valverde-EntrenamientoPe\u00f1arol28-5 (11)\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/05\/Valverde-EntrenamientoPe\u00f1arol28-5-11-300x200.jpg 300w, https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/05\/Valverde-EntrenamientoPe\u00f1arol28-5-11.jpg 900w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Pudimos ver a <strong>Valverde qued\u00e1ndose\u00a0a entrenar tiros libres con Pablo Bengoechea como consejero. Un privilegio que solo Pe\u00f1arol puede darle a un chico de su edad. El Profe le mostraba como darle a la pelota, el P\u00e1jaro escuchaba y lo aplicaba en el acto.<\/strong><\/p>\n<p dir=\"ltr\" style=\"text-align: justify;\">El resultado era fatal para el arquero Leandro Gelpi, que ve\u00eda como el esf\u00e9rico ingresaba en el \u00e1ngulo una y otra vez. Este fin de semana, el volante jugar\u00e1 en su divisional (Quinta), pero esperamos con ansiedad verlo en Primera Divisi\u00f3n. Bengoechea sabe que el muchacho le puede dar mucho al conjunto aurinegro.<\/p>\n<p dir=\"ltr\" style=\"text-align: right;\">Escrito por <a href=\"http:\/\/twitter.com\/wilsonmendez86\" target=\"_blank\">Wilson M\u00e9ndez<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Federico Valverde demuestra su calidad en Los Aromos. Cada d\u00eda que pasa evoluciona un poco m\u00e1s. Lo notan sus compa\u00f1eros, cuerpo t\u00e9cnico y cualquiera que vea los entrenamientos del conjunto Decano; merece minutos con el plantel principal. Habitualmente lo mejor es llevar a los juveniles de a poco, no cargarlos de presi\u00f3n. Para sobrellevar la [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Quisiera ver al P\u00e1jaro en Primera - Padre y Decano - El Sitio del Pueblo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.padreydecano.com\/cms\/noticias\/quisiera-ver-al-pajaro-en-primera\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quisiera ver al P\u00e1jaro en Primera - Padre y Decano - El Sitio del Pueblo\" \/>\n<meta property=\"og:description\" content=\"Federico Valverde demuestra su calidad en Los Aromos. Cada d\u00eda que pasa evoluciona un poco m\u00e1s. Lo notan sus compa\u00f1eros, cuerpo t\u00e9cnico y cualquiera que vea los entrenamientos del conjunto Decano; merece minutos con el plantel principal. Habitualmente lo mejor es llevar a los juveniles de a poco, no cargarlos de presi\u00f3n. Para sobrellevar la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.padreydecano.com\/cms\/noticias\/quisiera-ver-al-pajaro-en-primera\/\" \/>\n<meta property=\"og:site_name\" content=\"Padre y Decano - El Sitio del Pueblo\" \/>\n<meta property=\"article:published_time\" content=\"2015-05-28T22:43:09+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/05\/Valverde-EntrenamientoPe\u00f1arol28-5-37.jpg\" \/>\n<meta name=\"author\" content=\"Moderador\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Moderador\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/quisiera-ver-al-pajaro-en-primera\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/quisiera-ver-al-pajaro-en-primera\/\"},\"author\":{\"name\":\"Moderador\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/d93e9e537230ae052c194251d9a1def2\"},\"headline\":\"Quisiera ver al P\u00e1jaro en Primera\",\"datePublished\":\"2015-05-28T22:43:09+00:00\",\"dateModified\":\"2015-05-28T22:43:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/quisiera-ver-al-pajaro-en-primera\/\"},\"wordCount\":306,\"commentCount\":44,\"publisher\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#organization\"},\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.padreydecano.com\/cms\/noticias\/quisiera-ver-al-pajaro-en-primera\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/quisiera-ver-al-pajaro-en-primera\/\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/quisiera-ver-al-pajaro-en-primera\/\",\"name\":\"Quisiera ver al P\u00e1jaro en Primera - Padre y Decano - El Sitio del Pueblo\",\"isPartOf\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#website\"},\"datePublished\":\"2015-05-28T22:43:09+00:00\",\"dateModified\":\"2015-05-28T22:43:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/quisiera-ver-al-pajaro-en-primera\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.padreydecano.com\/cms\/noticias\/quisiera-ver-al-pajaro-en-primera\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/quisiera-ver-al-pajaro-en-primera\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.padreydecano.com\/cms\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quisiera ver al P\u00e1jaro en Primera\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#website\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/\",\"name\":\"Padre y Decano - El Sitio del Pueblo\",\"description\":\"Club Atl\u00e9tico Pe\u00f1arol\",\"publisher\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.padreydecano.com\/cms\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#organization\",\"name\":\"Padre y Decano\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2022\/01\/avatar-square.png\",\"contentUrl\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2022\/01\/avatar-square.png\",\"width\":1500,\"height\":1500,\"caption\":\"Padre y Decano\"},\"image\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/d93e9e537230ae052c194251d9a1def2\",\"name\":\"Moderador\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2587727bf8a53bd3da4ec49f01bea66e?s=96&d=https%3A%2F%2Fpadreydecano.com%2Fcms%2Fwp-content%2Fthemes%2Fpyd-theme%2Fimg%2Fdefault-avatar.png&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2587727bf8a53bd3da4ec49f01bea66e?s=96&d=https%3A%2F%2Fpadreydecano.com%2Fcms%2Fwp-content%2Fthemes%2Fpyd-theme%2Fimg%2Fdefault-avatar.png&r=g\",\"caption\":\"Moderador\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quisiera ver al P\u00e1jaro en Primera - Padre y Decano - El Sitio del Pueblo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.padreydecano.com\/cms\/noticias\/quisiera-ver-al-pajaro-en-primera\/","og_locale":"es_ES","og_type":"article","og_title":"Quisiera ver al P\u00e1jaro en Primera - Padre y Decano - El Sitio del Pueblo","og_description":"Federico Valverde demuestra su calidad en Los Aromos. Cada d\u00eda que pasa evoluciona un poco m\u00e1s. Lo notan sus compa\u00f1eros, cuerpo t\u00e9cnico y cualquiera que vea los entrenamientos del conjunto Decano; merece minutos con el plantel principal. Habitualmente lo mejor es llevar a los juveniles de a poco, no cargarlos de presi\u00f3n. Para sobrellevar la [&hellip;]","og_url":"https:\/\/www.padreydecano.com\/cms\/noticias\/quisiera-ver-al-pajaro-en-primera\/","og_site_name":"Padre y Decano - El Sitio del Pueblo","article_published_time":"2015-05-28T22:43:09+00:00","og_image":[{"url":"http:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/05\/Valverde-EntrenamientoPe\u00f1arol28-5-37.jpg"}],"author":"Moderador","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Moderador","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/quisiera-ver-al-pajaro-en-primera\/#article","isPartOf":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/quisiera-ver-al-pajaro-en-primera\/"},"author":{"name":"Moderador","@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/d93e9e537230ae052c194251d9a1def2"},"headline":"Quisiera ver al P\u00e1jaro en Primera","datePublished":"2015-05-28T22:43:09+00:00","dateModified":"2015-05-28T22:43:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/quisiera-ver-al-pajaro-en-primera\/"},"wordCount":306,"commentCount":44,"publisher":{"@id":"https:\/\/www.padreydecano.com\/cms\/#organization"},"articleSection":["Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.padreydecano.com\/cms\/noticias\/quisiera-ver-al-pajaro-en-primera\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/quisiera-ver-al-pajaro-en-primera\/","url":"https:\/\/www.padreydecano.com\/cms\/noticias\/quisiera-ver-al-pajaro-en-primera\/","name":"Quisiera ver al P\u00e1jaro en Primera - Padre y Decano - El Sitio del Pueblo","isPartOf":{"@id":"https:\/\/www.padreydecano.com\/cms\/#website"},"datePublished":"2015-05-28T22:43:09+00:00","dateModified":"2015-05-28T22:43:09+00:00","breadcrumb":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/quisiera-ver-al-pajaro-en-primera\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.padreydecano.com\/cms\/noticias\/quisiera-ver-al-pajaro-en-primera\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/quisiera-ver-al-pajaro-en-primera\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.padreydecano.com\/cms\/"},{"@type":"ListItem","position":2,"name":"Quisiera ver al P\u00e1jaro en Primera"}]},{"@type":"WebSite","@id":"https:\/\/www.padreydecano.com\/cms\/#website","url":"https:\/\/www.padreydecano.com\/cms\/","name":"Padre y Decano - El Sitio del Pueblo","description":"Club Atl\u00e9tico Pe\u00f1arol","publisher":{"@id":"https:\/\/www.padreydecano.com\/cms\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.padreydecano.com\/cms\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.padreydecano.com\/cms\/#organization","name":"Padre y Decano","url":"https:\/\/www.padreydecano.com\/cms\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/logo\/image\/","url":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2022\/01\/avatar-square.png","contentUrl":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2022\/01\/avatar-square.png","width":1500,"height":1500,"caption":"Padre y Decano"},"image":{"@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/d93e9e537230ae052c194251d9a1def2","name":"Moderador","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/2587727bf8a53bd3da4ec49f01bea66e?s=96&d=https%3A%2F%2Fpadreydecano.com%2Fcms%2Fwp-content%2Fthemes%2Fpyd-theme%2Fimg%2Fdefault-avatar.png&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2587727bf8a53bd3da4ec49f01bea66e?s=96&d=https%3A%2F%2Fpadreydecano.com%2Fcms%2Fwp-content%2Fthemes%2Fpyd-theme%2Fimg%2Fdefault-avatar.png&r=g","caption":"Moderador"}}]}},"_links":{"self":[{"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/posts\/52874"}],"collection":[{"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/comments?post=52874"}],"version-history":[{"count":0,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/posts\/52874\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/media?parent=52874"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/categories?post=52874"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/tags?post=52874"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}