{"id":52116,"date":"2015-04-06T09:35:24","date_gmt":"2015-04-06T12:35:24","guid":{"rendered":"http:\/\/www.padreydecano.com\/cms\/?p=52116"},"modified":"2015-04-06T10:27:56","modified_gmt":"2015-04-06T13:27:56","slug":"compacto-river-plate-1-penarol-2","status":"publish","type":"post","link":"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-river-plate-1-penarol-2\/","title":{"rendered":"Compacto: River Plate 1 Pe\u00f1arol 2"},"content":{"rendered":"<p style=\"text-align: justify;\">Repas\u00e1 el compacto con el <a title=\"Desde arriba\" href=\"https:\/\/www.padreydecano.com\/cms\/partidos\/desde-arriba\/\" target=\"_blank\">triunfazo de Pe\u00f1arol<\/a> 2 a 1 ante River Plate: el golazo de Gabriel Leyes, una nueva anotaci\u00f3n de cabeza de P\u00edriz y el gol de River tras una clara mano que no sanciona el \u00e1rbitro Fuentes.<\/p>\n<div align=\"center\">\n<table class=\"video\">\n<tbody>\n<tr>\n<td><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/vSvEe2UZ5EE?wmode=transparent\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Repas\u00e1 el compacto con el triunfazo de Pe\u00f1arol 2 a 1 ante River Plate: el golazo de Gabriel Leyes, una nueva anotaci\u00f3n de cabeza de P\u00edriz y el gol de River tras una clara mano que no sanciona el \u00e1rbitro Fuentes.<\/p>\n","protected":false},"author":13,"featured_media":52117,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[241],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Compacto: River Plate 1 Pe\u00f1arol 2 - Padre y Decano - El Sitio del Pueblo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-river-plate-1-penarol-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Compacto: River Plate 1 Pe\u00f1arol 2 - Padre y Decano - El Sitio del Pueblo\" \/>\n<meta property=\"og:description\" content=\"Repas\u00e1 el compacto con el triunfazo de Pe\u00f1arol 2 a 1 ante River Plate: el golazo de Gabriel Leyes, una nueva anotaci\u00f3n de cabeza de P\u00edriz y el gol de River tras una clara mano que no sanciona el \u00e1rbitro Fuentes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-river-plate-1-penarol-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Padre y Decano - El Sitio del Pueblo\" \/>\n<meta property=\"article:published_time\" content=\"2015-04-06T12:35:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-04-06T13:27:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/04\/video-pe\u00f1arol-river-clausura-2015.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"780\" \/>\n\t<meta property=\"og:image:height\" content=\"461\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Moderador\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Moderador\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-river-plate-1-penarol-2\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-river-plate-1-penarol-2\/\"},\"author\":{\"name\":\"Moderador\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/d93e9e537230ae052c194251d9a1def2\"},\"headline\":\"Compacto: River Plate 1 Pe\u00f1arol 2\",\"datePublished\":\"2015-04-06T12:35:24+00:00\",\"dateModified\":\"2015-04-06T13:27:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-river-plate-1-penarol-2\/\"},\"wordCount\":47,\"commentCount\":4,\"publisher\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-river-plate-1-penarol-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/04\/video-pe\u00f1arol-river-clausura-2015.jpg\",\"keywords\":[\"Compactos Clausura 2015\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-river-plate-1-penarol-2\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-river-plate-1-penarol-2\/\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-river-plate-1-penarol-2\/\",\"name\":\"Compacto: River Plate 1 Pe\u00f1arol 2 - Padre y Decano - El Sitio del Pueblo\",\"isPartOf\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-river-plate-1-penarol-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-river-plate-1-penarol-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/04\/video-pe\u00f1arol-river-clausura-2015.jpg\",\"datePublished\":\"2015-04-06T12:35:24+00:00\",\"dateModified\":\"2015-04-06T13:27:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-river-plate-1-penarol-2\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-river-plate-1-penarol-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-river-plate-1-penarol-2\/#primaryimage\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/04\/video-pe\u00f1arol-river-clausura-2015.jpg\",\"contentUrl\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/04\/video-pe\u00f1arol-river-clausura-2015.jpg\",\"width\":780,\"height\":461},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-river-plate-1-penarol-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.padreydecano.com\/cms\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Compacto: River Plate 1 Pe\u00f1arol 2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#website\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/\",\"name\":\"Padre y Decano - El Sitio del Pueblo\",\"description\":\"Club Atl\u00e9tico Pe\u00f1arol\",\"publisher\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.padreydecano.com\/cms\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#organization\",\"name\":\"Padre y Decano\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2022\/01\/avatar-square.png\",\"contentUrl\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2022\/01\/avatar-square.png\",\"width\":1500,\"height\":1500,\"caption\":\"Padre y Decano\"},\"image\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/d93e9e537230ae052c194251d9a1def2\",\"name\":\"Moderador\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2587727bf8a53bd3da4ec49f01bea66e?s=96&d=https%3A%2F%2Fpadreydecano.com%2Fcms%2Fwp-content%2Fthemes%2Fpyd-theme%2Fimg%2Fdefault-avatar.png&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2587727bf8a53bd3da4ec49f01bea66e?s=96&d=https%3A%2F%2Fpadreydecano.com%2Fcms%2Fwp-content%2Fthemes%2Fpyd-theme%2Fimg%2Fdefault-avatar.png&r=g\",\"caption\":\"Moderador\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Compacto: River Plate 1 Pe\u00f1arol 2 - Padre y Decano - El Sitio del Pueblo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-river-plate-1-penarol-2\/","og_locale":"es_ES","og_type":"article","og_title":"Compacto: River Plate 1 Pe\u00f1arol 2 - Padre y Decano - El Sitio del Pueblo","og_description":"Repas\u00e1 el compacto con el triunfazo de Pe\u00f1arol 2 a 1 ante River Plate: el golazo de Gabriel Leyes, una nueva anotaci\u00f3n de cabeza de P\u00edriz y el gol de River tras una clara mano que no sanciona el \u00e1rbitro Fuentes.","og_url":"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-river-plate-1-penarol-2\/","og_site_name":"Padre y Decano - El Sitio del Pueblo","article_published_time":"2015-04-06T12:35:24+00:00","article_modified_time":"2015-04-06T13:27:56+00:00","og_image":[{"width":780,"height":461,"url":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/04\/video-pe\u00f1arol-river-clausura-2015.jpg","type":"image\/jpeg"}],"author":"Moderador","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Moderador"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-river-plate-1-penarol-2\/#article","isPartOf":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-river-plate-1-penarol-2\/"},"author":{"name":"Moderador","@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/d93e9e537230ae052c194251d9a1def2"},"headline":"Compacto: River Plate 1 Pe\u00f1arol 2","datePublished":"2015-04-06T12:35:24+00:00","dateModified":"2015-04-06T13:27:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-river-plate-1-penarol-2\/"},"wordCount":47,"commentCount":4,"publisher":{"@id":"https:\/\/www.padreydecano.com\/cms\/#organization"},"image":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-river-plate-1-penarol-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/04\/video-pe\u00f1arol-river-clausura-2015.jpg","keywords":["Compactos Clausura 2015"],"articleSection":["Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-river-plate-1-penarol-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-river-plate-1-penarol-2\/","url":"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-river-plate-1-penarol-2\/","name":"Compacto: River Plate 1 Pe\u00f1arol 2 - Padre y Decano - El Sitio del Pueblo","isPartOf":{"@id":"https:\/\/www.padreydecano.com\/cms\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-river-plate-1-penarol-2\/#primaryimage"},"image":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-river-plate-1-penarol-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/04\/video-pe\u00f1arol-river-clausura-2015.jpg","datePublished":"2015-04-06T12:35:24+00:00","dateModified":"2015-04-06T13:27:56+00:00","breadcrumb":{"@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-river-plate-1-penarol-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-river-plate-1-penarol-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-river-plate-1-penarol-2\/#primaryimage","url":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/04\/video-pe\u00f1arol-river-clausura-2015.jpg","contentUrl":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2015\/04\/video-pe\u00f1arol-river-clausura-2015.jpg","width":780,"height":461},{"@type":"BreadcrumbList","@id":"https:\/\/www.padreydecano.com\/cms\/noticias\/compacto-river-plate-1-penarol-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.padreydecano.com\/cms\/"},{"@type":"ListItem","position":2,"name":"Compacto: River Plate 1 Pe\u00f1arol 2"}]},{"@type":"WebSite","@id":"https:\/\/www.padreydecano.com\/cms\/#website","url":"https:\/\/www.padreydecano.com\/cms\/","name":"Padre y Decano - El Sitio del Pueblo","description":"Club Atl\u00e9tico Pe\u00f1arol","publisher":{"@id":"https:\/\/www.padreydecano.com\/cms\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.padreydecano.com\/cms\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.padreydecano.com\/cms\/#organization","name":"Padre y Decano","url":"https:\/\/www.padreydecano.com\/cms\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/logo\/image\/","url":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2022\/01\/avatar-square.png","contentUrl":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2022\/01\/avatar-square.png","width":1500,"height":1500,"caption":"Padre y Decano"},"image":{"@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/d93e9e537230ae052c194251d9a1def2","name":"Moderador","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/2587727bf8a53bd3da4ec49f01bea66e?s=96&d=https%3A%2F%2Fpadreydecano.com%2Fcms%2Fwp-content%2Fthemes%2Fpyd-theme%2Fimg%2Fdefault-avatar.png&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2587727bf8a53bd3da4ec49f01bea66e?s=96&d=https%3A%2F%2Fpadreydecano.com%2Fcms%2Fwp-content%2Fthemes%2Fpyd-theme%2Fimg%2Fdefault-avatar.png&r=g","caption":"Moderador"}}]}},"_links":{"self":[{"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/posts\/52116"}],"collection":[{"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/comments?post=52116"}],"version-history":[{"count":0,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/posts\/52116\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/media\/52117"}],"wp:attachment":[{"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/media?parent=52116"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/categories?post=52116"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/tags?post=52116"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}