{"id":18452,"date":"2012-03-06T02:35:01","date_gmt":"2012-03-06T04:35:01","guid":{"rendered":"http:\/\/www.padreydecano.com\/cms\/?p=18452"},"modified":"2012-03-07T00:39:56","modified_gmt":"2012-03-07T02:39:56","slug":"sirve-un-unico-resultado","status":"publish","type":"post","link":"https:\/\/www.padreydecano.com\/cms\/los-aromos\/sirve-un-unico-resultado\/","title":{"rendered":"Sirve un \u00fanico resultado"},"content":{"rendered":"<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright  wp-image-18441\" src=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2012\/03\/los-aromos-entrenamiento-marzo-2012-300x225.jpg\" alt=\"\" width=\"210\" height=\"158\" srcset=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2012\/03\/los-aromos-entrenamiento-marzo-2012-300x225.jpg 300w, https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2012\/03\/los-aromos-entrenamiento-marzo-2012.jpg 800w\" sizes=\"(max-width: 210px) 100vw, 210px\" \/>El partido del semestre. As\u00ed se encarar\u00e1 el partido del pr\u00f3ximo martes entre Pe\u00f1arol y Universidad de Chile en el Estadio Centenario. Nuevo cuerpo t\u00e9cnico, nuevas esperanzas, nueva manera de jugar.<\/p>\n<p style=\"text-align: justify;\">El equipo ahora conducido por Jorge \u201cEl Polilla\u201d Da Silva jugar\u00e1 ma\u00f1ana un encuentro totalmente decisivo en lo que al futuro de Pe\u00f1arol se refiere. Esto se da debido a que cualquier resultado diferente a una victoria carbonera nos dejar\u00e1 definitivamente afuera de la Copa Libertadores 2012.<\/p>\n<p style=\"text-align: justify;\">Los jugadores que ha decidido concentrar el Polilla Da Silva son los siguientes: Fabi\u00e1n Carini, Danilo Lerda, Carlos Valdez, Alejandro Gonz\u00e1lez, Dar\u00edo Rodr\u00edguez, Juan \u00c1lvez, Marcelo Silva, Emiliano Alb\u00edn, Nicol\u00e1s Freitas, Joao Pedro, Sebasti\u00e1n Crist\u00f3foro, Marcel Novick, Facundo Guich\u00f3n, Sebasti\u00e1n Rosano, Luis Aguiar, Jorge Zambrana, Maximiliano P\u00e9rez, Marcelo Zalayeta, Rodrigo Mora, Fabi\u00e1n Estoyanoff y Santiago Silva.<\/p>\n<p style=\"text-align: justify;\">Luis Aguiar no llegar\u00e1 para el partido, aunque s\u00ed est\u00e1 concentrado. Carlos Valdez podr\u00e1 ser de la partida, al igual que Marcelo Zalayeta (ya jug\u00f3 en el \u00faltimo partido contra Cerro Largo).<\/p>\n<p style=\"text-align: justify;\">Nuestro director t\u00e9cnico est\u00e1 pensando en qui\u00e9n sustituir\u00e1 a Luis Aguiar. Una de las posibilidades es conformar la zaga con Marcelo Silva y Carlos Valdez, con Dar\u00edo Rodr\u00edguez y Alejandro Gonz\u00e1lez de laterales; pasando a jugar Emiliano Alb\u00edn en zona de volantes. Tambi\u00e9n est\u00e1 la chance de que entre el brasile\u00f1o Joao Pedro en la mitad de la cancha.<\/p>\n<p style=\"text-align: justify;\">Por su parte, Rodrigo Mora ya pr\u00e1cticamente recuperado de su cuadro gripal ser\u00e1 titular, al igual que Marcelo Silva, a quien se lo resguard\u00f3 en el partido del s\u00e1bado para el enfrentamiento del pr\u00f3ximo martes.<\/p>\n<p style=\"text-align: justify;\">Con la mentalidad de ganar o ganar, Pe\u00f1arol saldr\u00e1 a la cancha probablemente con <strong>Fabi\u00e1n Carini en el arco, Alejandro Gonz\u00e1lez por derecha, Carlos Valdez y Marcelo Silva en la zaga y Dar\u00edo Rodr\u00edguez por izquierda. En la mitad de la cancha jugar\u00e1n Nicol\u00e1s Freitas y<strong>\u00a0Sebasti\u00e1n Crist\u00f3foro<\/strong>, por derecha Fabi\u00e1n Estoyanoff, por izquierda Emiliano Alb\u00edn (o Santiago Silva) y arriba Rodrigo Mora junto a Marcelo Zalayeta.<\/strong><\/p>\n<p style=\"text-align: justify;\">Vamos todos a alentar al carbonero, ahora es cuando m\u00e1s hay que asistir al estadio. Entre todos este partido lo sacamos adelante, \u00a1porque somos Pe\u00f1arol y lo vamos a ganar a lo Pe\u00f1arol!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El partido del semestre. As\u00ed se encarar\u00e1 el partido del pr\u00f3ximo martes entre Pe\u00f1arol y Universidad de Chile en el Estadio Centenario. Nuevo cuerpo t\u00e9cnico, nuevas esperanzas, nueva manera de jugar. El equipo ahora conducido por Jorge \u201cEl Polilla\u201d Da Silva jugar\u00e1 ma\u00f1ana un encuentro totalmente decisivo en lo que al futuro de Pe\u00f1arol se [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":18343,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sirve un \u00fanico resultado - Padre y Decano - El Sitio del Pueblo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.padreydecano.com\/cms\/los-aromos\/sirve-un-unico-resultado\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sirve un \u00fanico resultado - Padre y Decano - El Sitio del Pueblo\" \/>\n<meta property=\"og:description\" content=\"El partido del semestre. As\u00ed se encarar\u00e1 el partido del pr\u00f3ximo martes entre Pe\u00f1arol y Universidad de Chile en el Estadio Centenario. Nuevo cuerpo t\u00e9cnico, nuevas esperanzas, nueva manera de jugar. El equipo ahora conducido por Jorge \u201cEl Polilla\u201d Da Silva jugar\u00e1 ma\u00f1ana un encuentro totalmente decisivo en lo que al futuro de Pe\u00f1arol se [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.padreydecano.com\/cms\/los-aromos\/sirve-un-unico-resultado\/\" \/>\n<meta property=\"og:site_name\" content=\"Padre y Decano - El Sitio del Pueblo\" \/>\n<meta property=\"article:published_time\" content=\"2012-03-06T04:35:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2012-03-07T02:39:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2012\/03\/sliderbellavista-640x2501.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Moderador\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Moderador\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/los-aromos\/sirve-un-unico-resultado\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/los-aromos\/sirve-un-unico-resultado\/\"},\"author\":{\"name\":\"Moderador\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/d93e9e537230ae052c194251d9a1def2\"},\"headline\":\"Sirve un \u00fanico resultado\",\"datePublished\":\"2012-03-06T04:35:01+00:00\",\"dateModified\":\"2012-03-07T02:39:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/los-aromos\/sirve-un-unico-resultado\/\"},\"wordCount\":405,\"commentCount\":7,\"publisher\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/los-aromos\/sirve-un-unico-resultado\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2012\/03\/sliderbellavista-640x2501.jpg\",\"articleSection\":[\"Los Aromos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.padreydecano.com\/cms\/los-aromos\/sirve-un-unico-resultado\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/los-aromos\/sirve-un-unico-resultado\/\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/los-aromos\/sirve-un-unico-resultado\/\",\"name\":\"Sirve un \u00fanico resultado - Padre y Decano - El Sitio del Pueblo\",\"isPartOf\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/los-aromos\/sirve-un-unico-resultado\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/los-aromos\/sirve-un-unico-resultado\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2012\/03\/sliderbellavista-640x2501.jpg\",\"datePublished\":\"2012-03-06T04:35:01+00:00\",\"dateModified\":\"2012-03-07T02:39:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/los-aromos\/sirve-un-unico-resultado\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.padreydecano.com\/cms\/los-aromos\/sirve-un-unico-resultado\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/los-aromos\/sirve-un-unico-resultado\/#primaryimage\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2012\/03\/sliderbellavista-640x2501.jpg\",\"contentUrl\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2012\/03\/sliderbellavista-640x2501.jpg\",\"width\":\"640\",\"height\":\"250\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/los-aromos\/sirve-un-unico-resultado\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.padreydecano.com\/cms\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sirve un \u00fanico resultado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#website\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/\",\"name\":\"Padre y Decano - El Sitio del Pueblo\",\"description\":\"Club Atl\u00e9tico Pe\u00f1arol\",\"publisher\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.padreydecano.com\/cms\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#organization\",\"name\":\"Padre y Decano\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2022\/01\/avatar-square.png\",\"contentUrl\":\"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2022\/01\/avatar-square.png\",\"width\":1500,\"height\":1500,\"caption\":\"Padre y Decano\"},\"image\":{\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/d93e9e537230ae052c194251d9a1def2\",\"name\":\"Moderador\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2587727bf8a53bd3da4ec49f01bea66e?s=96&d=https%3A%2F%2Fpadreydecano.com%2Fcms%2Fwp-content%2Fthemes%2Fpyd-theme%2Fimg%2Fdefault-avatar.png&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2587727bf8a53bd3da4ec49f01bea66e?s=96&d=https%3A%2F%2Fpadreydecano.com%2Fcms%2Fwp-content%2Fthemes%2Fpyd-theme%2Fimg%2Fdefault-avatar.png&r=g\",\"caption\":\"Moderador\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sirve un \u00fanico resultado - Padre y Decano - El Sitio del Pueblo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.padreydecano.com\/cms\/los-aromos\/sirve-un-unico-resultado\/","og_locale":"es_ES","og_type":"article","og_title":"Sirve un \u00fanico resultado - Padre y Decano - El Sitio del Pueblo","og_description":"El partido del semestre. As\u00ed se encarar\u00e1 el partido del pr\u00f3ximo martes entre Pe\u00f1arol y Universidad de Chile en el Estadio Centenario. Nuevo cuerpo t\u00e9cnico, nuevas esperanzas, nueva manera de jugar. El equipo ahora conducido por Jorge \u201cEl Polilla\u201d Da Silva jugar\u00e1 ma\u00f1ana un encuentro totalmente decisivo en lo que al futuro de Pe\u00f1arol se [&hellip;]","og_url":"https:\/\/www.padreydecano.com\/cms\/los-aromos\/sirve-un-unico-resultado\/","og_site_name":"Padre y Decano - El Sitio del Pueblo","article_published_time":"2012-03-06T04:35:01+00:00","article_modified_time":"2012-03-07T02:39:56+00:00","og_image":[{"width":640,"height":250,"url":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2012\/03\/sliderbellavista-640x2501.jpg","type":"image\/jpeg"}],"author":"Moderador","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Moderador","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.padreydecano.com\/cms\/los-aromos\/sirve-un-unico-resultado\/#article","isPartOf":{"@id":"https:\/\/www.padreydecano.com\/cms\/los-aromos\/sirve-un-unico-resultado\/"},"author":{"name":"Moderador","@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/d93e9e537230ae052c194251d9a1def2"},"headline":"Sirve un \u00fanico resultado","datePublished":"2012-03-06T04:35:01+00:00","dateModified":"2012-03-07T02:39:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.padreydecano.com\/cms\/los-aromos\/sirve-un-unico-resultado\/"},"wordCount":405,"commentCount":7,"publisher":{"@id":"https:\/\/www.padreydecano.com\/cms\/#organization"},"image":{"@id":"https:\/\/www.padreydecano.com\/cms\/los-aromos\/sirve-un-unico-resultado\/#primaryimage"},"thumbnailUrl":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2012\/03\/sliderbellavista-640x2501.jpg","articleSection":["Los Aromos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.padreydecano.com\/cms\/los-aromos\/sirve-un-unico-resultado\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.padreydecano.com\/cms\/los-aromos\/sirve-un-unico-resultado\/","url":"https:\/\/www.padreydecano.com\/cms\/los-aromos\/sirve-un-unico-resultado\/","name":"Sirve un \u00fanico resultado - Padre y Decano - El Sitio del Pueblo","isPartOf":{"@id":"https:\/\/www.padreydecano.com\/cms\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.padreydecano.com\/cms\/los-aromos\/sirve-un-unico-resultado\/#primaryimage"},"image":{"@id":"https:\/\/www.padreydecano.com\/cms\/los-aromos\/sirve-un-unico-resultado\/#primaryimage"},"thumbnailUrl":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2012\/03\/sliderbellavista-640x2501.jpg","datePublished":"2012-03-06T04:35:01+00:00","dateModified":"2012-03-07T02:39:56+00:00","breadcrumb":{"@id":"https:\/\/www.padreydecano.com\/cms\/los-aromos\/sirve-un-unico-resultado\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.padreydecano.com\/cms\/los-aromos\/sirve-un-unico-resultado\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.padreydecano.com\/cms\/los-aromos\/sirve-un-unico-resultado\/#primaryimage","url":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2012\/03\/sliderbellavista-640x2501.jpg","contentUrl":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2012\/03\/sliderbellavista-640x2501.jpg","width":"640","height":"250"},{"@type":"BreadcrumbList","@id":"https:\/\/www.padreydecano.com\/cms\/los-aromos\/sirve-un-unico-resultado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.padreydecano.com\/cms\/"},{"@type":"ListItem","position":2,"name":"Sirve un \u00fanico resultado"}]},{"@type":"WebSite","@id":"https:\/\/www.padreydecano.com\/cms\/#website","url":"https:\/\/www.padreydecano.com\/cms\/","name":"Padre y Decano - El Sitio del Pueblo","description":"Club Atl\u00e9tico Pe\u00f1arol","publisher":{"@id":"https:\/\/www.padreydecano.com\/cms\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.padreydecano.com\/cms\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.padreydecano.com\/cms\/#organization","name":"Padre y Decano","url":"https:\/\/www.padreydecano.com\/cms\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/logo\/image\/","url":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2022\/01\/avatar-square.png","contentUrl":"https:\/\/www.padreydecano.com\/cms\/wp-content\/uploads\/2022\/01\/avatar-square.png","width":1500,"height":1500,"caption":"Padre y Decano"},"image":{"@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/d93e9e537230ae052c194251d9a1def2","name":"Moderador","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.padreydecano.com\/cms\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/2587727bf8a53bd3da4ec49f01bea66e?s=96&d=https%3A%2F%2Fpadreydecano.com%2Fcms%2Fwp-content%2Fthemes%2Fpyd-theme%2Fimg%2Fdefault-avatar.png&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2587727bf8a53bd3da4ec49f01bea66e?s=96&d=https%3A%2F%2Fpadreydecano.com%2Fcms%2Fwp-content%2Fthemes%2Fpyd-theme%2Fimg%2Fdefault-avatar.png&r=g","caption":"Moderador"}}]}},"_links":{"self":[{"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/posts\/18452"}],"collection":[{"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/comments?post=18452"}],"version-history":[{"count":0,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/posts\/18452\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/media\/18343"}],"wp:attachment":[{"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/media?parent=18452"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/categories?post=18452"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.padreydecano.com\/cms\/wp-json\/wp\/v2\/tags?post=18452"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}